{"id":9843,"date":"2022-07-13T00:00:48","date_gmt":"2022-07-13T00:00:48","guid":{"rendered":"http:\/\/lahora.mx\/?p=9843"},"modified":"2022-07-13T00:00:49","modified_gmt":"2022-07-13T00:00:49","slug":"aprueban-en-comision-del-congreso-reservar-asientos-para-mujeres-en-transporte-publico","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/07\/13\/aprueban-en-comision-del-congreso-reservar-asientos-para-mujeres-en-transporte-publico\/","title":{"rendered":"Aprueban en Comisi\u00f3n del Congreso reservar asientos para mujeres en transporte p\u00fablico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por unanimidad, las y los integrantes de la Comisi\u00f3n de Transportes y Movilidad de la LXI Legislatura, aprobaron una reforma cuyo objetivo es reservar asientos exclusivos para mujeres en las unidades de transporte p\u00fablico, a fin de evitar el acoso sexual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La modificaci\u00f3n se realiz\u00f3 al art\u00edculo 15 de la Ley de Transporte del Estado de Puebla, con la adici\u00f3n de la fracci\u00f3n VIII, en la cual se se\u00f1ala que la reservaci\u00f3n de asientos se har\u00e1 conforme a las disposiciones administrativas vigentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, la presidenta de la Comisi\u00f3n de Transportes y Movilidad, Isabel Merlo Talavera expres\u00f3 que en el plan de trabajo se plantearon acciones tendientes a evitar el acoso sexual al interior de las unidades en el transporte p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diputada Isabel Merlo, promovente de la iniciativa, mencion\u00f3 que, adem\u00e1s de los marcos normativos para castigar el acoso sexual, es necesario implementar acciones para prevenirlo, como en este caso al reservar asientos en el transporte p\u00fablico.<br>En su momento, la diputada Guadalupe Leal Rodr\u00edguez se\u00f1al\u00f3 que, con esta modificaci\u00f3n, las mujeres y ni\u00f1as podr\u00e1n sentirse m\u00e1s seguras, adem\u00e1s, consider\u00f3 que generar\u00e1 mayor empat\u00eda social para ceder el asiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la Comisi\u00f3n de Transportes y Movilidad tambi\u00e9n asistieron las diputadas Erika Patricia Valencia \u00c1vila y Nora Merino Escamilla, as\u00ed como el diputado Jaime Natale Uranga.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por unanimidad, las y los integrantes de la Comisi\u00f3n de Transportes y Movilidad de la LXI Legislatura, aprobaron una reforma cuyo objetivo es reservar asientos exclusivos para mujeres en las unidades de transporte p\u00fablico, a fin de evitar el acoso sexual. La modificaci\u00f3n se realiz\u00f3 al art\u00edculo 15 de la Ley de Transporte del Estado [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9844,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[223],"class_list":["post-9843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/9843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=9843"}],"version-history":[{"count":2,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/9843\/revisions"}],"predecessor-version":[{"id":10542,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/9843\/revisions\/10542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/9844"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=9843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=9843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=9843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}