{"id":9392,"date":"2022-06-06T01:09:00","date_gmt":"2022-06-06T01:09:00","guid":{"rendered":"http:\/\/lahora.mx\/?p=9392"},"modified":"2022-07-06T01:12:29","modified_gmt":"2022-07-06T01:12:29","slug":"avalan-en-comisiones-unidas-del-congreso-exhorto-para-implementar-acciones-que-fortalezcan-la-salud-mental-y-emocional-en-planteles-educativos","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/06\/06\/avalan-en-comisiones-unidas-del-congreso-exhorto-para-implementar-acciones-que-fortalezcan-la-salud-mental-y-emocional-en-planteles-educativos\/","title":{"rendered":"Avalan en Comisiones Unidas del Congreso, exhorto para implementar acciones que fortalezcan la salud mental y emocional, en planteles educativos"},"content":{"rendered":"\n<p>En Comisiones Unidas de Salud y Educaci\u00f3n de la LXI Legislatura del Congreso del Estado, que presidi\u00f3 la diputada Azucena Rosas Tapia, se aprob\u00f3 el Dictamen de Acuerdo para solicitar a la Secretar\u00eda de Salud y a la Secretar\u00eda de Educaci\u00f3n del Estado de Puebla, para que de manera coordinada dise\u00f1en e implementen un programa permanente que incluya actividades, encuentros, capacitaciones y pl\u00e1ticas entre alumnos, docentes y directivos de todos los niveles escolares, con el fin de atender y fortalecer la salud mental y emocional en los planteles educativos de la entidad.<\/p>\n\n\n\n<p>El exhorto de la diputada Karla Victoria Mart\u00ednez Gallegos, hace hincapi\u00e9 en el tema de la salud mental, no solo por las ni\u00f1as, ni\u00f1os y adolescentes, sino por la poblaci\u00f3n en general.<\/p>\n\n\n\n<p>\u201cYa que la salud mental tiene mucha importancia en nuestra forma de pensar, razonar, sentir y de actuar, lo que puede impactar en las relacionamos con otras personas y en la toma de decisiones\u201d, se\u00f1ala el Punto de Acuerdo de la legisladora.<\/p>\n\n\n\n<p>A la sesi\u00f3n de Comisiones Unidas, asistieron las y los diputados del \u00f3rgano colegiado, Azucena Rosas Tapia, Xel Arianna Hern\u00e1ndez Garc\u00eda, Jos\u00e9 Antonio L\u00f3pez Ruiz, Norma Sirley Reyes Cabrera, Laura Ivonne Zapata Mart\u00ednez, \u00c9rika Patricia Valencia \u00c1vila, Mariano Hern\u00e1ndez Reyes e Iv\u00e1n Herrera Villag\u00f3mez<\/p>\n\n\n\n<p>Asimismo, se cont\u00f3 con la presencia del diputado Eduardo Alc\u00e1ntara Montiel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Comisiones Unidas de Salud y Educaci\u00f3n de la LXI Legislatura del Congreso del Estado, que presidi\u00f3 la diputada Azucena Rosas Tapia, se aprob\u00f3 el Dictamen de Acuerdo para solicitar a la Secretar\u00eda de Salud y a la Secretar\u00eda de Educaci\u00f3n del Estado de Puebla, para que de manera coordinada dise\u00f1en e implementen un programa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[223],"class_list":["post-9392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/9392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=9392"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/9392\/revisions"}],"predecessor-version":[{"id":9395,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/9392\/revisions\/9395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/9394"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=9392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=9392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=9392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}