{"id":87441,"date":"2026-07-15T04:30:10","date_gmt":"2026-07-15T04:30:10","guid":{"rendered":"https:\/\/lahora.mx\/?p=87441"},"modified":"2026-07-15T04:30:11","modified_gmt":"2026-07-15T04:30:11","slug":"desde-un-coche-sin-placas-operaba-el-tirador-de-la-atlixcayotl-disparaba-por-diversion","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2026\/07\/15\/desde-un-coche-sin-placas-operaba-el-tirador-de-la-atlixcayotl-disparaba-por-diversion\/","title":{"rendered":"Desde un coche sin placas operaba el tirador de la Atlixc\u00e1yotl; disparaba por diversi\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Desde un veh\u00edculo GMC Denali blanco sin placas de circulaci\u00f3n y eligiendo a sus v\u00edctimas al azar la Fiscal\u00eda de Puebla sostuvo que operaba Rafael Zabalza, empresario espa\u00f1ol de la industria farmac\u00e9utica a quien el organismo investiga por los ataques atribuidos al denominado tirador de la Atlixc\u00e1yotl.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En rueda de prensa la fiscal general del estado, Idamis Pastor Betancourt, inform\u00f3 que Rafael Zabalza de 60 a\u00f1os estar\u00eda relacionado con los 11 ataques registrados desde abril en la V\u00eda Atlixc\u00e1yotl, por los que la dependencia integr\u00f3 10 carpetas de investigaci\u00f3n por delitos de tentativa de homicidio, da\u00f1os en propiedad ajena y ataques peligrosos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este martes en el operativo que cumpliment\u00f3 la orden de aprehensi\u00f3n contra el presunto tirador de la Atlixc\u00e1yotl se registr\u00f3 un intercambio de disparos que dej\u00f3 a una persona lesionada y da\u00f1os en nueve veh\u00edculos, por lo que adem\u00e1s iniciar\u00e1n contra \u00e9l una investigaci\u00f3n por tentativa de homicidio y da\u00f1os en propiedad ajena, se\u00f1al\u00f3 Jos\u00e9 Luis Hern\u00e1ndez, fiscal de Investigaci\u00f3n Metropolitana.<br>El secretario de Seguridad P\u00fablica estatal, vicealmirante Francisco S\u00e1nchez Gonz\u00e1lez, explic\u00f3 que la detenci\u00f3n de Rafael Zabalza se logr\u00f3 tras analizar c\u00e1maras de videovigilancia conectadas al C5, con las que identificaron un veh\u00edculo que aparec\u00eda recurrente en donde ocurrieron las agresiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque la falta de placas retras\u00f3 la investigaci\u00f3n, mediante la reconstrucci\u00f3n de los hechos, an\u00e1lisis de peritajes en tercera dimensi\u00f3n y trabajos de inteligencia establecieron que se utiliz\u00f3 ese veh\u00edculo durante los ataques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La investigaci\u00f3n arroj\u00f3 que el presunto responsable eligi\u00f3 al azar a sus v\u00edctimas y que no segu\u00eda un horario o patr\u00f3n espec\u00edfico para las agresiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detenci\u00f3n del tirador de la Atlixc\u00e1yotl deriv\u00f3 en 2 cateos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de las diligencias y tras su captura las autoridades realizaron dos cateos: uno en un domicilio del fraccionamiento Santa Fe y otro en un inmueble ubicado en la calle 31 Poniente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En dichos operativos aseguraron tres armas cortas semiautom\u00e1ticas, un rifle, una escopeta, cartuchos \u00fatiles, dinero en efectivo y un veh\u00edculo GMC blanco sin placas de circulaci\u00f3n, el cual presuntamente era utilizado para cometer los ataques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Informaron que las armas aseguradas s\u00ed se estaban registradas de manera legal, situaci\u00f3n que confirm\u00f3 por la Secretar\u00eda de la Defensa Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Descartan relaci\u00f3n con ataques en el Perif\u00e9rico Ecol\u00f3gico<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la rueda de prensa sobre la detenci\u00f3n del presunto tirador de la Atlixc\u00e1yotl revelaron que hasta el momento Rafael Zabalza no estar\u00eda relacionado con los ataques registrados hace un par de a\u00f1os ni con la agresi\u00f3n armada contra un menor que ocurri\u00f3 a principios de 2026 en el Perif\u00e9rico Ecol\u00f3gico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien se\u00f1alaron que esa zona se encuentra fuera del \u00e1rea donde presuntamente operaba el detenido, precisaron que las investigaciones continuar\u00e1n para esclarecer otros hechos violentos ocurridos en distintos puntos y momentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La detenci\u00f3n de Rafael Zabalza tom\u00f3 m\u00e1s tiempo debido a que, al inicio de los ataques, varias v\u00edctimas no presentaron denuncias, aseguraron.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde un veh\u00edculo GMC Denali blanco sin placas de circulaci\u00f3n y eligiendo a sus v\u00edctimas al azar la Fiscal\u00eda de Puebla sostuvo que operaba Rafael Zabalza, empresario espa\u00f1ol de la industria farmac\u00e9utica a quien el organismo investiga por los ataques atribuidos al denominado tirador de la Atlixc\u00e1yotl. En rueda de prensa la fiscal general del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":87447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[195,223],"class_list":["post-87441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-principal","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/87441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=87441"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/87441\/revisions"}],"predecessor-version":[{"id":87448,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/87441\/revisions\/87448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/87447"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=87441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=87441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=87441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}