{"id":85906,"date":"2026-06-24T15:01:23","date_gmt":"2026-06-24T15:01:23","guid":{"rendered":"https:\/\/lahora.mx\/?p=85906"},"modified":"2026-06-24T15:01:26","modified_gmt":"2026-06-24T15:01:26","slug":"volcadura-de-camion-de-carga-provoca-afectaciones-viales-frente-a-la-central-de-abasto-de-puebla","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2026\/06\/24\/volcadura-de-camion-de-carga-provoca-afectaciones-viales-frente-a-la-central-de-abasto-de-puebla\/","title":{"rendered":"Volcadura de cami\u00f3n de carga provoca afectaciones viales frente a la Central de Abasto de Puebla"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La ma\u00f1ana de este mi\u00e9rcoles se registr\u00f3 la volcadura de un veh\u00edculo de carga sobre la carretera V\u00eda Corta a Santa Ana, a la altura de la Central de Abasto de Puebla, lo que gener\u00f3 complicaciones en la circulaci\u00f3n para quienes transitan por la zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El percance ocurri\u00f3 en inmediaciones de la Central de Abasto, ubicada en el municipio de Puebla, donde la unidad termin\u00f3 volcada sobre uno de los carriles, provocando reducci\u00f3n en el flujo vehicular y largas filas de automovilistas.<br>Tras el incidente, autoridades y cuerpos de emergencia acudieron al lugar para realizar labores de atenci\u00f3n y coordinar las maniobras necesarias para retirar la unidad siniestrada y restablecer la circulaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a las afectaciones viales, se recomend\u00f3 a los conductores extremar precauciones, reducir la velocidad y considerar v\u00edas alternas para evitar retrasos en sus traslados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta el momento no se ha informado oficialmente sobre personas lesionadas ni las causas que originaron el accidente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ma\u00f1ana de este mi\u00e9rcoles se registr\u00f3 la volcadura de un veh\u00edculo de carga sobre la carretera V\u00eda Corta a Santa Ana, a la altura de la Central de Abasto de Puebla, lo que gener\u00f3 complicaciones en la circulaci\u00f3n para quienes transitan por la zona. El percance ocurri\u00f3 en inmediaciones de la Central de Abasto, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":85907,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[226],"tags":[],"class_list":["post-85906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/85906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=85906"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/85906\/revisions"}],"predecessor-version":[{"id":85908,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/85906\/revisions\/85908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/85907"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=85906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=85906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=85906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}