{"id":8579,"date":"2022-06-22T00:56:30","date_gmt":"2022-06-22T00:56:30","guid":{"rendered":"http:\/\/lahora.mx\/?p=8579"},"modified":"2022-06-22T00:56:30","modified_gmt":"2022-06-22T00:56:30","slug":"ahora-es-turno-de-las-personas-fisicas-para-las-utilidades-para-quienes-aplica","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/06\/22\/ahora-es-turno-de-las-personas-fisicas-para-las-utilidades-para-quienes-aplica\/","title":{"rendered":"Ahora es turno de las personas f\u00edsicas, para las utilidades \u00bfpara qui\u00e9nes aplica?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tal como en el caso de las empresas, tambi\u00e9n hay personas f\u00edsicas que est\u00e1n obligadas a pagar reparto de utilidades entre sus trabajadores. Esto es as\u00ed porque hay contribuyentes que tienen actividades empresariales y personal subordinado, aunque no sean una persona moral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi bien la Ley Federal del Trabajo no los menciona textualmente, tampoco los excluye. Podemos decir que las personas f\u00edsicas s\u00ed deben pagar PTU y son aquellas que est\u00e1n inscritas en el r\u00e9gimen de actividades empresariales o servicios profesionales, y en el r\u00e9gimen simplificado de confianza\u201d, se\u00f1ala Rodolfo Trampe, socio de la firma Von Wobeser y Sierra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 29 de junio es la fecha l\u00edmite para que las personas f\u00edsicas obligadas a cumplir con el pago de la Participaci\u00f3n de los Trabajadores en las Utilidades (PTU) lo entreguen a sus trabajadores. Sin embargo, el r\u00e9gimen en el que se encuentran estos contribuyentes no es lo que determina si son sujetos de repartir utilidades, el factor m\u00e1s importante es si cuentan con personal subordinado, subraya Rodolfo Trampe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ver\u00f3nica Zepeda, docente de la Escuela Bancaria y Comercial (EBC), explica que hay personas f\u00edsicas que entran en el esquema del PTU porque \u201cse encuentran en un r\u00e9gimen equivalente a las actividades que realiza una persona moral\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es decir, hay personas f\u00edsicas que al igual que las morales (empresas) prestan servicios, distribuyen o fabrican productos con trabajadores subordinados, eso es lo que las convierte en sujetos obligados de cubrir el reparto de utilidades, puntualiza Ver\u00f3nica Zepeda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto para las personas morales como para las f\u00edsicas, el plazo para cubrir el monto de PTU es el mismo: 60 d\u00edas a partir de la fecha en la que se paga el impuesto anual. Pero las personas f\u00edsicas tienen de plazo hasta junio, porque su fecha l\u00edmite para presentar la declaraci\u00f3n anual es el 30 de abril, un mes despu\u00e9s del plazo l\u00edmite que tienen las empresas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que las empresas, la especialista opina que las personas f\u00edsicas que tienen un nuevo negocio est\u00e1n exentas de repartir utilidades en su primer a\u00f1o de funcionamiento, o bien las que se encuentran desarrollando un nuevo producto son exentas por dos a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esas similitudes, Rodolfo Trampe apunta que la reforma de subcontrataci\u00f3n y los topes que ese establecieron en la Ley Federal del Trabajo para el pago del PTU tambi\u00e9n aplican para las personas f\u00edsicas. Es decir, estos contribuyentes pueden otorgar a un trabajador como m\u00e1ximo un pago equivalente a tres meses de salario o el promedio del monto pagado en los \u00faltimos tres a\u00f1os, lo que resulte m\u00e1s ben\u00e9fico para el colaborador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las sanciones tambi\u00e9n aplican<br>\u201cA todos nos pueden sorprender e incluso hay personas que no saben que est\u00e1n obligadas al pago de este derecho. Recordemos que el desconocimiento de la ley no te exime de las obligaciones\u201d, subraya Ver\u00f3nica Zepeda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, la Ley Federal del Trabajo establece que el incumplimiento del pago del PTU puede equivaler a una sanci\u00f3n que va de los 24,055 a los 481,100 pesos, una de las m\u00e1s altas en la legislaci\u00f3n laboral. Desde la perspectiva de Rodolfo Trampe, esta misma multa que se puede imponer a las empresas por no otorgar reparto de utilidades se podr\u00eda aplicar a las personas f\u00edsicas. \u201cPor el simple hecho de ser patr\u00f3n, sea moral o f\u00edsica, est\u00e1 sujeto a la misma regulaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los especialistas indican que quienes trabajan de manera subordinada para una persona f\u00edsica que incumpli\u00f3 con el pago del reparto de utilidades pueden acceder a los mismos medios de defensa que los empleados de una empresa, como acudir a la Procuradur\u00eda Federal de la Defensa del Trabajo (Profedet), el \u00e1rea de inspecci\u00f3n de la Secretar\u00eda del Trabajo y Previsi\u00f3n Social (STPS) o un tribunal laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Generalmente los trabajadores que laboran para una persona f\u00edsica pueden estar empleados en peque\u00f1os negocios, pero una de las maneras de corroborar si se trabaja para un patr\u00f3n obligado a repartir utilidades, sugiere el especialista, es a trav\u00e9s de los recibos de n\u00f3mina. \u201cEn lugar de que aparezca el nombre de una empresa, aparecer\u00e1 el nombre de una persona f\u00edsica, sin ninguna denominaci\u00f3n o raz\u00f3n social\u201d. Pero es importante tomar en cuenta que esta obligaci\u00f3n est\u00e1 ligada con el sector formal, puntualiza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tal como en el caso de las empresas, tambi\u00e9n hay personas f\u00edsicas que est\u00e1n obligadas a pagar reparto de utilidades entre sus trabajadores. Esto es as\u00ed porque hay contribuyentes que tienen actividades empresariales y personal subordinado, aunque no sean una persona moral. \u201cSi bien la Ley Federal del Trabajo no los menciona textualmente, tampoco los [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[176],"tags":[],"class_list":["post-8579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/8579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=8579"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/8579\/revisions"}],"predecessor-version":[{"id":8581,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/8579\/revisions\/8581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/8580"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=8579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=8579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=8579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}