{"id":83742,"date":"2026-05-26T17:53:48","date_gmt":"2026-05-26T17:53:48","guid":{"rendered":"https:\/\/lahora.mx\/?p=83742"},"modified":"2026-05-26T17:53:48","modified_gmt":"2026-05-26T17:53:48","slug":"muere-profesor-de-la-cnte-en-planton-de-la-cdmx","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2026\/05\/26\/muere-profesor-de-la-cnte-en-planton-de-la-cdmx\/","title":{"rendered":"Muere profesor de la CNTE en plant\u00f3n de la CDMX"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un profesor de la Coordinadora Nacional de los Trabajadores de la Educaci\u00f3n (CNTE) falleci\u00f3 esta madrugada, por un paro cardiaco, en el plant\u00f3n que mantiene la Secci\u00f3n 22 en la Ciudad de M\u00e9xico, reportaron fuentes m\u00e9dicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuentes del movimiento magisterial confirmaron a Grupo REFORMA que el docente pertenece al sector periferia de la regi\u00f3n de Valles Centrales de Oaxaca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLamentablemente hace unos momentos falleci\u00f3 un compa\u00f1ero maestro, del sector de la periferia aqu\u00ed en el campamento de la CDMX\u00bb, difundieron los docentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agregaron que durante los primeros minutos de este martes est\u00e1n intentando contactar con sus familiares para informarles, por lo que omitieron proporcionar su nombre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el primer d\u00eda de plant\u00f3n sobre la calle 5 de Mayo, los profesores se enfrentaron a un cerco policiaco que los recibi\u00f3 con polvo de extintor para frenar su arribo a la plancha del Z\u00f3calo capitalino, donde el Gobierno instala el Fan Fest rumbo al Mundial de la FIFA 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, instalaron un campamento sobre la v\u00eda, que cuenta con personal m\u00e9dico para emergencias, ubicado al centro del plant\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un profesor de la Coordinadora Nacional de los Trabajadores de la Educaci\u00f3n (CNTE) falleci\u00f3 esta madrugada, por un paro cardiaco, en el plant\u00f3n que mantiene la Secci\u00f3n 22 en la Ciudad de M\u00e9xico, reportaron fuentes m\u00e9dicas. Fuentes del movimiento magisterial confirmaron a Grupo REFORMA que el docente pertenece al sector periferia de la regi\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":83743,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[176,226],"tags":[],"class_list":["post-83742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","category-policia"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/83742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=83742"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/83742\/revisions"}],"predecessor-version":[{"id":83744,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/83742\/revisions\/83744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/83743"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=83742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=83742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=83742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}