{"id":82774,"date":"2026-05-13T16:03:25","date_gmt":"2026-05-13T16:03:25","guid":{"rendered":"https:\/\/lahora.mx\/?p=82774"},"modified":"2026-05-13T16:03:27","modified_gmt":"2026-05-13T16:03:27","slug":"sep-confirma-suspension-de-clases-del-14-al-18-de-mayo-en-puebla","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2026\/05\/13\/sep-confirma-suspension-de-clases-del-14-al-18-de-mayo-en-puebla\/","title":{"rendered":"SEP confirma suspensi\u00f3n de clases del 14 al 18 de mayo en Puebla"},"content":{"rendered":"\n<p>Las y los estudiantes de Puebla tendr\u00e1n un nuevo megapuente escolar durante mayo, luego de que el Gobierno estatal determin\u00f3 declarar como d\u00eda inh\u00e1bil el pr\u00f3ximo jueves 14 de mayo para reconocer la labor del magisterio poblano.<\/p>\n\n\n\n<p>A trav\u00e9s de un comunicado oficial, la administraci\u00f3n encabezada por Alejandro Armenta inform\u00f3 que la suspensi\u00f3n de actividades aplicar\u00e1 para instituciones de educaci\u00f3n b\u00e1sica, media superior y superior, tanto p\u00fablicas como privadas incorporadas al sistema estatal.<\/p>\n\n\n\n<p>Suscr\u00edbete a nuestro canal<br>La medida se suma al descanso oficial del viernes 15 de mayo, fecha en la que se conmemora el D\u00eda de la Maestra y el Maestro, por lo que alumnas y alumnos retomar\u00e1n actividades acad\u00e9micas hasta el lunes 18 de mayo de 2026.<br>El Gobierno estatal se\u00f1al\u00f3 que este ajuste busca reconocer el trabajo de las y los docentes en Puebla, adem\u00e1s de fortalecer el valor social de la ense\u00f1anza en las aulas. Con ello, miles de familias poblanas podr\u00e1n disfrutar de un fin de semana largo en plena recta final del ciclo escolar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las y los estudiantes de Puebla tendr\u00e1n un nuevo megapuente escolar durante mayo, luego de que el Gobierno estatal determin\u00f3 declarar como d\u00eda inh\u00e1bil el pr\u00f3ximo jueves 14 de mayo para reconocer la labor del magisterio poblano. A trav\u00e9s de un comunicado oficial, la administraci\u00f3n encabezada por Alejandro Armenta inform\u00f3 que la suspensi\u00f3n de actividades [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":82775,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[195,223],"class_list":["post-82774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-principal","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/82774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=82774"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/82774\/revisions"}],"predecessor-version":[{"id":82776,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/82774\/revisions\/82776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/82775"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=82774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=82774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=82774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}