{"id":76581,"date":"2026-02-10T01:44:07","date_gmt":"2026-02-10T01:44:07","guid":{"rendered":"https:\/\/lahora.mx\/?p=76581"},"modified":"2026-02-10T01:44:09","modified_gmt":"2026-02-10T01:44:09","slug":"ladrones-dan-cristalazo-a-instalaciones-del-chopo-en-puebla","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2026\/02\/10\/ladrones-dan-cristalazo-a-instalaciones-del-chopo-en-puebla\/","title":{"rendered":"Ladrones dan cristalazo a instalaciones del Chopo en Puebla"},"content":{"rendered":"\n<p>Los laboratorios Chopo que se ubican en el Barrio de Xanenetla sobre el bulevar 5 de Mayo, recibieron un cristalazo durante la madrugada de este lunes nueve de febrero, los responsables huyeron del lugar.<\/p>\n\n\n\n<p>Por tal motivo, elementos de la polic\u00eda Municipal y Estatal acudieron a dicho establecimiento, a la altura del n\u00famero 610, despu\u00e9s de reporte registrado por parte de trabajadores quienes se dieron cuenta de lo sucedido.<br>Cuando los empleados llegaron al lugar para iniciar con su jornada, descubrieron da\u00f1os en la puerta principal y el faltante de equipo operativo en el \u00e1rea de recepci\u00f3n.<\/p>\n\n\n\n<p>Conforme a los reportes policiales, el asalto se habr\u00eda registrado cerca de las cuatro de la ma\u00f1ana de este lunes nueve de febrero. Los responsables rompieron el vidrio de la puerta principal para ingresar al inmueble.<\/p>\n\n\n\n<p>Ya al interior del lugar, los maleantes se dirigieron a las cajas registradoras, logrando desprenderlas y sustraerlas.<\/p>\n\n\n\n<p>Los ladrones cortaron los cables del sistema de videovigilancia, por lo que el \u00e1rea de monitoreo central de los laboratorios confirm\u00f3 que se perdi\u00f3 la se\u00f1al de las c\u00e1maras de seguridad, lo que limit\u00f3 la obtenci\u00f3n de caracter\u00edsticas f\u00edsicas de los involucrados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los laboratorios Chopo que se ubican en el Barrio de Xanenetla sobre el bulevar 5 de Mayo, recibieron un cristalazo durante la madrugada de este lunes nueve de febrero, los responsables huyeron del lugar. Por tal motivo, elementos de la polic\u00eda Municipal y Estatal acudieron a dicho establecimiento, a la altura del n\u00famero 610, despu\u00e9s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":76582,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[226],"tags":[],"class_list":["post-76581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/76581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=76581"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/76581\/revisions"}],"predecessor-version":[{"id":76583,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/76581\/revisions\/76583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/76582"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=76581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=76581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=76581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}