{"id":76327,"date":"2026-02-05T16:11:42","date_gmt":"2026-02-05T16:11:42","guid":{"rendered":"https:\/\/lahora.mx\/?p=76327"},"modified":"2026-02-05T16:11:42","modified_gmt":"2026-02-05T16:11:42","slug":"confirman-44-casos-de-sarampion-en-puebla-descartan-uso-obligatorio-de-cubrebocas","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2026\/02\/05\/confirman-44-casos-de-sarampion-en-puebla-descartan-uso-obligatorio-de-cubrebocas\/","title":{"rendered":"Confirman 44 casos de sarampi\u00f3n en Puebla; descartan uso obligatorio de cubrebocas"},"content":{"rendered":"\n<p>En las \u00faltimas 24 horas se confirmaron cuatro nuevos casos de sarampi\u00f3n en Puebla, por lo que al corte del 5 de febrero la entidad acumula 44 contagios confirmados y 159 casos probables, inform\u00f3 la Secretar\u00eda de Salud estatal.<\/p>\n\n\n\n<p>El titular de la dependencia, Joaqu\u00edn Espidio, explic\u00f3 que del total de reportes tambi\u00e9n se han descartado cerca de 60 casos, luego de que las muestras analizadas en laboratorio resultaran negativas. Se\u00f1al\u00f3 que las cifras se actualizan conforme los casos sospechosos son registrados en la plataforma y posteriormente confirmados o descartados mediante estudios cl\u00ednicos.<br>El funcionario indic\u00f3 que se mantiene un seguimiento permanente, principalmente en el sector educativo, por lo que se llevan a cabo reuniones de coordinaci\u00f3n con la Secretar\u00eda de Educaci\u00f3n P\u00fablica para reforzar la vigilancia y la estrategia de atenci\u00f3n ante cualquier nuevo caso que pudiera surgir.<\/p>\n\n\n\n<p>Respecto al uso del cubrebocas, Espidio descart\u00f3 que, por el momento, se considere regresar a su uso obligatorio en escuelas u otros espacios, a diferencia de lo ocurrido en otras entidades como Guadalajara. Afirm\u00f3 que actualmente no se contempla esta medida y que la prioridad es continuar con la vigilancia epidemiol\u00f3gica y la detecci\u00f3n oportuna de casos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En las \u00faltimas 24 horas se confirmaron cuatro nuevos casos de sarampi\u00f3n en Puebla, por lo que al corte del 5 de febrero la entidad acumula 44 contagios confirmados y 159 casos probables, inform\u00f3 la Secretar\u00eda de Salud estatal. El titular de la dependencia, Joaqu\u00edn Espidio, explic\u00f3 que del total de reportes tambi\u00e9n se han [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":76328,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[252],"tags":[],"class_list":["post-76327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/76327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=76327"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/76327\/revisions"}],"predecessor-version":[{"id":76329,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/76327\/revisions\/76329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/76328"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=76327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=76327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=76327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}