{"id":76198,"date":"2026-02-03T00:30:29","date_gmt":"2026-02-03T00:30:29","guid":{"rendered":"https:\/\/lahora.mx\/?p=76198"},"modified":"2026-02-03T00:30:30","modified_gmt":"2026-02-03T00:30:30","slug":"sanborns-del-centro-historico-de-puebla-refuerza-seguridad","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2026\/02\/03\/sanborns-del-centro-historico-de-puebla-refuerza-seguridad\/","title":{"rendered":"Sanborns del Centro Hist\u00f3rico de Puebla refuerza seguridad"},"content":{"rendered":"\n<p>Debido a los contantes robos que se registraran en las sucursales de Sanborns en la ciudad de Puebla, por lo menos la sucursal del Centro Hist\u00f3rico de Puebla ya tom\u00f3 medidas para evitar los mismos.<\/p>\n\n\n\n<p>De manera constante el Sanborns del Centro y la que se encuentra sobre el bulevar 5 de Mayo, son visitados de manera constante por los amantes de lo ajeno, llev\u00e1ndose diferentes art\u00edculos que representan a la empresa perdidas por miles de pesos.<br>Es as\u00ed que Sanborns del Centro de Puebla y tras los actos vand\u00e1licos sufridos, sus vitrinas ahora lucen un enrejado blanco.<\/p>\n\n\n\n<p>Esta medida busca prevenir nuevos incidentes y proteger la mercanc\u00eda en exhibici\u00f3n.<\/p>\n\n\n\n<p>Por lo menos hasta en tres ocasiones a lo largo del 2025, ladrones dieron el cl\u00e1sico cristalazo a dicha empresa que se ubica en la avenida 2 Oriente.<\/p>\n\n\n\n<p>La primera se registr\u00f3 el pasado 23 de mayo del 2025, donde fueron hurtado en su mayor\u00eda perfumes, sin embargo, no se inform\u00f3 el monto de lo robado; la segunda sucedi\u00f3 el 16 de junio del mismo a\u00f1o, donde los rateros nuevamente se llevaron perfumes y ahora tambi\u00e9n relojes.<\/p>\n\n\n\n<p>El tercer y \u00faltimo robo a dicha sucursal fue en el cierre del 2025, el tres de diciembre, las alarmas de la empresa se activaron, pero no se inform\u00f3 lo robado por parte de las autoridades municipales, ni de la empresa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debido a los contantes robos que se registraran en las sucursales de Sanborns en la ciudad de Puebla, por lo menos la sucursal del Centro Hist\u00f3rico de Puebla ya tom\u00f3 medidas para evitar los mismos. De manera constante el Sanborns del Centro y la que se encuentra sobre el bulevar 5 de Mayo, son visitados [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":76199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[226],"tags":[],"class_list":["post-76198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/76198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=76198"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/76198\/revisions"}],"predecessor-version":[{"id":76200,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/76198\/revisions\/76200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/76199"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=76198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=76198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=76198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}