{"id":76145,"date":"2026-02-02T17:27:58","date_gmt":"2026-02-02T17:27:58","guid":{"rendered":"https:\/\/lahora.mx\/?p=76145"},"modified":"2026-02-02T17:27:59","modified_gmt":"2026-02-02T17:27:59","slug":"profeco-contempla-multa-de-5-mdp-a-ticketmaster-por-reventa-de-boletos-de-bts","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2026\/02\/02\/profeco-contempla-multa-de-5-mdp-a-ticketmaster-por-reventa-de-boletos-de-bts\/","title":{"rendered":"Profeco contempla multa de 5 mdp a Ticketmaster por reventa de boletos de BTS"},"content":{"rendered":"\n<p>Los avances de la Procuradur\u00eda Federal del Consumidor (Profeco) marcaron el eje principal de la Ma\u00f1anera del Pueblo encabezada este lunes por la presidenta Claudia Sheinbaum Pardo, realizada de manera excepcional en la Cineteca Nacional Chapultepec.<\/p>\n\n\n\n<p>El titular de Profeco, Iv\u00e1n Escalante, inform\u00f3 que ya se inici\u00f3 un procedimiento por infracci\u00f3n a la ley contra Ticketmaster, derivado del caso BTS y las pr\u00e1cticas detectadas en la venta y reventa de boletos para conciertos. La notificaci\u00f3n fue emitida el 28 de enero de 2026 y contempla una multa superior a los cinco millones de pesos. La empresa tendr\u00e1 diez d\u00edas h\u00e1biles, hasta el 12 de febrero, para presentar pruebas y su defensa.<br>Como parte de las acciones, Profeco tambi\u00e9n notific\u00f3 de manera electr\u00f3nica a plataformas internacionales de reventa como Viagogo, StubHub y Helloticket, con sedes en Estados Unidos, Suiza y Espa\u00f1a. A estas empresas se les exhort\u00f3 a ajustarse a la legislaci\u00f3n mexicana y frenar pr\u00e1cticas consideradas desleales contra los consumidores. En caso de no atender el llamado, se advirti\u00f3 que podr\u00edan enfrentarse a procedimientos legales, sanciones administrativas e incluso restricciones para operar en M\u00e9xico.<\/p>\n\n\n\n<p>Escalante adelant\u00f3 que, en paralelo, se elaboran nuevos lineamientos para regular la publicidad, informaci\u00f3n y comercializaci\u00f3n de boletos para conciertos, festivales y espect\u00e1culos. Estas reglas se desarrollan en coordinaci\u00f3n con la Agencia de Transformaci\u00f3n Digital y Telecomunicaciones y se prev\u00e9 que sean publicadas en el Diario Oficial de la Federaci\u00f3n en las pr\u00f3ximas semanas.<\/p>\n\n\n\n<p>La conferencia matutina se llev\u00f3 a cabo fuera de Palacio Nacional debido a la agenda presidencial, ya que tras concluir el encuentro con medios, la mandataria tiene programada la inauguraci\u00f3n del tramo Santa Fe\u2013Observatorio del Tren Interurbano M\u00e9xico\u2013Toluca, prevista para las 10:00 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los avances de la Procuradur\u00eda Federal del Consumidor (Profeco) marcaron el eje principal de la Ma\u00f1anera del Pueblo encabezada este lunes por la presidenta Claudia Sheinbaum Pardo, realizada de manera excepcional en la Cineteca Nacional Chapultepec. El titular de Profeco, Iv\u00e1n Escalante, inform\u00f3 que ya se inici\u00f3 un procedimiento por infracci\u00f3n a la ley contra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":76146,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[176],"tags":[223],"class_list":["post-76145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/76145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=76145"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/76145\/revisions"}],"predecessor-version":[{"id":76147,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/76145\/revisions\/76147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/76146"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=76145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=76145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=76145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}