{"id":75925,"date":"2026-01-30T15:36:00","date_gmt":"2026-01-30T15:36:00","guid":{"rendered":"https:\/\/lahora.mx\/?p=75925"},"modified":"2026-01-30T17:24:35","modified_gmt":"2026-01-30T17:24:35","slug":"gracias-a-gestiones-mejoramos-la-calle-12-de-la-loma-xicotencatl-alfonso-sanchez","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2026\/01\/30\/gracias-a-gestiones-mejoramos-la-calle-12-de-la-loma-xicotencatl-alfonso-sanchez\/","title":{"rendered":"Gracias a Gestiones Mejoramos La Calle 12 De La Loma Xicot\u00e9ncatl: Alfonso S\u00e1nchez"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Secretar\u00eda de Infraestructura lleva a cabo la rehabilitaci\u00f3n de pavimentoEl presidente municipal de Tlaxcala, Alfonso S\u00e1nchez Garc\u00eda, supervis\u00f3 la rehabilitaci\u00f3n del pavimento asf\u00e1ltico en la Calle 12 de la colonia La Loma Xicoht\u00e9ncatl, trabajos realizados por la Secretar\u00eda de Infraestructura del Gobierno del Estado como parte de las acciones permanentes para mejorar la infraestructura vial y responder a las necesidades de las familias de la capital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la supervisi\u00f3n, el edil capitalino reconoci\u00f3 y agradeci\u00f3 la disposici\u00f3n de la Gobernadora Lorena Cu\u00e9llar Cisneros, cuyo respaldo permiti\u00f3 atender una demanda reiterada de los habitantes de la zona, quienes por a\u00f1os hab\u00edan esperado la reparaci\u00f3n de esta vialidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHoy estamos aqu\u00ed dando respuesta. Gracias al respaldo de nuestra Gobernadora podemos ampliar los beneficios y mejorar calles que por muchos a\u00f1os fueron abandonadas y que ahora recuperan su dignidad para la gente\u201d, subray\u00f3 el alcalde Alfonso S\u00e1nchez Garc\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los trabajos t\u00e9cnicos incluyen el retiro de tramos da\u00f1ados de la carpeta asf\u00e1ltica, limpieza y preparaci\u00f3n de la base, aplicaci\u00f3n de riego de adherencia y colocaci\u00f3n de nueva mezcla asf\u00e1ltica, todo realizado con maquinaria especializada y bajo criterios t\u00e9cnicos que garantizan mayor durabilidad y calidad en la obra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta intervenci\u00f3n se mejora la movilidad vehicular y peatonal, adem\u00e1s se previenen accidentes, se reducen tiempos de traslado y se dignifica el entorno urbano, lo que contribuye a una mejor calidad de vida para quienes habitan y transitan por esta zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Infraestructura lleva a cabo la rehabilitaci\u00f3n de pavimentoEl presidente municipal de Tlaxcala, Alfonso S\u00e1nchez Garc\u00eda, supervis\u00f3 la rehabilitaci\u00f3n del pavimento asf\u00e1ltico en la Calle 12 de la colonia La Loma Xicoht\u00e9ncatl, trabajos realizados por la Secretar\u00eda de Infraestructura del Gobierno del Estado como parte de las acciones permanentes para mejorar la infraestructura [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":75926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[176],"tags":[],"class_list":["post-75925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/75925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=75925"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/75925\/revisions"}],"predecessor-version":[{"id":75927,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/75925\/revisions\/75927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/75926"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=75925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=75925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=75925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}