{"id":73637,"date":"2025-12-26T00:29:08","date_gmt":"2025-12-26T00:29:08","guid":{"rendered":"https:\/\/lahora.mx\/?p=73637"},"modified":"2025-12-26T00:29:09","modified_gmt":"2025-12-26T00:29:09","slug":"cae-en-chiapas-yoel-alter-integrante-de-secta-religiosa-lev-tahor","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/12\/26\/cae-en-chiapas-yoel-alter-integrante-de-secta-religiosa-lev-tahor\/","title":{"rendered":"Cae en Chiapas Yoel Alter, integrante de secta religiosa Lev Tahor}"},"content":{"rendered":"\n<p>Un juez de control dict\u00f3&nbsp;<strong>prisi\u00f3n preventiva<\/strong>&nbsp;oficiosa a&nbsp;<strong>Yoel Alter<\/strong>, presunto integrante de la secta ultraortodoxa \u201c<strong>Lev Tahor<\/strong>\u201d, que seg\u00fan autoridades federales sustraer<a href=\"https:\/\/www.eluniversal.com.mx\/nacion\/asignacion-de-asientos-de-avion-contiguos-a-menores-sin-costo-extra-esto-es-lo-que-propone-morena\/\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;<strong>menores de edad<\/strong><\/a>&nbsp;de su lugar de origen, con el fin de realizar&nbsp;<strong>matrimonios forzados&nbsp;<\/strong>con adultos del mismo grupo religioso.<\/p>\n\n\n\n<p>Derivado de trabajos de inteligencia, el sujeto fue detenido en el estado de&nbsp;<a href=\"https:\/\/www.eluniversal.com.mx\/nacion\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Chiapas&nbsp;<\/strong><\/a>donde elementos de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSCP) y de la Agencia de Investigaci\u00f3n Criminal de la FGR le cumplimentaron una&nbsp;<strong>orden de aprehensi\u00f3n<\/strong>&nbsp;por su probable participaci\u00f3n en el delito de&nbsp;<strong>delincuencia organizada<\/strong>&nbsp;con el fin de cometer<a href=\"https:\/\/www.eluniversal.com.mx\/estados\/capturan-a-jaime-toral-influencer-veracruzano-por-trata-de-personas-lo-acusan-de-esclavitud\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>trata de personas<\/strong><\/a>(hip\u00f3tesis de matrimonios forzados).<\/p>\n\n\n\n<p>En audiencia inicial, el juez calific\u00f3 de legal la detenci\u00f3n y dict\u00f3<strong>&nbsp;prisi\u00f3n preventiva<\/strong>&nbsp;a Yoel Altera, sin embargo, su defensa solicit\u00f3 la duplicidad del plazo constitucional, para definir su situaci\u00f3n jur\u00eddica.<\/p>\n\n\n\n<p>De acuerdo con las investigaciones de la Fiscal\u00eda General de la Rep\u00fablica, Yoel Alter forma parte de la secta\u201d Lev Tahor\u201d, fundada en Jerusal\u00e9n en 1988 y que es se\u00f1alada de<strong>&nbsp;abuso infantil<\/strong>, pedofilia, secuestros y negligencia de menores, lo que ha obligado a sus integrantes a cambiar de ubicaci\u00f3n constantemente para evitar las intervenciones de la&nbsp;<strong>justicia<\/strong>.<\/p>\n\n\n\n<p>Las autoridades identificaron que opera principalmente en Israel, Nueva York, Guatemala y en M\u00e9xico, donde se han realizado diversas detenciones de sus l\u00edderes y el rescate de personas menores de edad.<\/p>\n\n\n\n<p>Como resultado de trabajos de inteligencia, fue posible ubicar su zona de operaci\u00f3n en el estado de Chiapas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un juez de control dict\u00f3&nbsp;prisi\u00f3n preventiva&nbsp;oficiosa a&nbsp;Yoel Alter, presunto integrante de la secta ultraortodoxa \u201cLev Tahor\u201d, que seg\u00fan autoridades federales sustraer&nbsp;menores de edad&nbsp;de su lugar de origen, con el fin de realizar&nbsp;matrimonios forzados&nbsp;con adultos del mismo grupo religioso. Derivado de trabajos de inteligencia, el sujeto fue detenido en el estado de&nbsp;Chiapas&nbsp;donde elementos de la Secretar\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":73638,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[176],"tags":[225,282],"class_list":["post-73637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-policia","tag-seguridad"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/73637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=73637"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/73637\/revisions"}],"predecessor-version":[{"id":73639,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/73637\/revisions\/73639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/73638"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=73637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=73637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=73637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}