{"id":73609,"date":"2025-12-25T01:07:56","date_gmt":"2025-12-25T01:07:56","guid":{"rendered":"https:\/\/lahora.mx\/?p=73609"},"modified":"2025-12-25T01:07:56","modified_gmt":"2025-12-25T01:07:56","slug":"el-departamento-de-justicia-de-ee-uu-recibe-un-millon-de-nuevos-documentos-sobre-el-caso-jeffrey-epstein","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/12\/25\/el-departamento-de-justicia-de-ee-uu-recibe-un-millon-de-nuevos-documentos-sobre-el-caso-jeffrey-epstein\/","title":{"rendered":"El Departamento de Justicia de EE.UU. recibe un mill\u00f3n de nuevos documentos sobre el caso Jeffrey Epstein"},"content":{"rendered":"\n<p>El Departamento de Justicia de Estados Unidos (DOJ) inform\u00f3 que recibi\u00f3 del FBI y de la Fiscal\u00eda del Distrito Sur de Nueva York cerca de un mill\u00f3n de nuevos documentos presuntamente vinculados con el caso del empresario y pederasta Jeffrey Epstein , los cuales deber\u00e1n ser revisados \u200b\u200bantes de su publicaci\u00f3n.<\/p>\n\n\n\n<p>En un comunicado difundido en redes sociales, la dependencia se\u00f1al\u00f3 que cuenta con equipos de abogados dedicados a analizar el material ya realizar las tachaduras legalmente requeridas para proteger la identidad de las v\u00edctimas . \u00abTenemos abogados trabajando incansablemente para revisar y realizar las tachaduras necesarias para proteger a las v\u00edctimas, y publicaremos los documentos lo antes posible. Debido al gran volumen de material, este proceso podr\u00eda demorar algunas semanas m\u00e1s\u00bb, precis\u00f3 el mensaje oficial.<br>La revisi\u00f3n responde a una ley aprobada por el Congreso en noviembre pasado , que obliga a la administraci\u00f3n del presidente Donald Trump a desclasificar y divulgar todos los archivos relacionados con el caso Epstein , quien se suicid\u00f3 en prisi\u00f3n en 2019 .<\/p>\n\n\n\n<p>Aunque el Departamento de Justicia public\u00f3 parte de los archivos el 19 de diciembre , entre ellas fotograf\u00edas del expresidente Bill Clinton con Epstein, aclar\u00f3 que no hab\u00eda sido posible divulgar la totalidad de la informaci\u00f3n debido al volumen de documentos. La decisi\u00f3n provoc\u00f3 cr\u00edticas de la oposici\u00f3n dem\u00f3crata y de las v\u00edctimas del caso , quienes reclamaron mayor transparencia.<\/p>\n\n\n\n<p>En una nueva tanda de archivos difundida el lunes, aparecen menciones reiteradas al presidente Trump , quien habr\u00eda viajado en varias ocasiones en el avi\u00f3n privado del magnate financiero. Sin embargo, hasta el momento no existen indicios de su participaci\u00f3n en delitos sexuales .<\/p>\n\n\n\n<p>De acuerdo con la fiscal general Pam Bondi , el FBI y la fiscal\u00eda neoyorquina detectaron m\u00e1s de un mill\u00f3n de documentos adicionales posiblemente relacionados con el caso, los cuales ser\u00e1n sometidos a un proceso de revisi\u00f3n exhaustiva.<\/p>\n\n\n\n<p>El Departamento de Justicia reiter\u00f3 su compromiso de cumplir con la legislaci\u00f3n federal y con la orden presidencial de divulgar los archivos. Inicialmente, Trump no apoy\u00f3 la publicaci\u00f3n de la informaci\u00f3n vinculada a Epstein \u2014con quien mantuvo amistad hasta 2004\u2014, pero termin\u00f3 firmando la ley tras constatar el amplio respaldo del Congreso a favor de la transparencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento de Justicia de Estados Unidos (DOJ) inform\u00f3 que recibi\u00f3 del FBI y de la Fiscal\u00eda del Distrito Sur de Nueva York cerca de un mill\u00f3n de nuevos documentos presuntamente vinculados con el caso del empresario y pederasta Jeffrey Epstein , los cuales deber\u00e1n ser revisados \u200b\u200bantes de su publicaci\u00f3n. En un comunicado difundido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":73610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[183],"tags":[],"class_list":["post-73609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/73609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=73609"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/73609\/revisions"}],"predecessor-version":[{"id":73611,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/73609\/revisions\/73611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/73610"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=73609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=73609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=73609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}