{"id":73571,"date":"2025-12-24T01:30:37","date_gmt":"2025-12-24T01:30:37","guid":{"rendered":"https:\/\/lahora.mx\/?p=73571"},"modified":"2025-12-24T01:30:38","modified_gmt":"2025-12-24T01:30:38","slug":"gobierno-de-puebla-fortalece-turismo-economia-y-tejido-social-con-olimpiada-conade-2025","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/12\/24\/gobierno-de-puebla-fortalece-turismo-economia-y-tejido-social-con-olimpiada-conade-2025\/","title":{"rendered":"Gobierno de Puebla fortalece turismo, econom\u00eda y tejido social con Olimpiada CONADE 2025"},"content":{"rendered":"\n<p><strong>Por su capacidad organizativa, hospitalidad y resultados, el Estado de Puebla asumir\u00e1 la sede principal de la Olimpiada Nacional CONADE 2026, resalt\u00f3 el gobernador Alejandro Armenta, al considerar que es la actividad deportiva m\u00e1s importante del pa\u00eds.<\/strong><\/p>\n\n\n\n<p>Reafirm\u00f3 que la Olimpiada Nacional CONADE 2026 es un proyecto de transformaci\u00f3n social, al considerar al deporte, el arte y la cultura como las herramientas m\u00e1s eficaces para prevenir la inseguridad y formar mejores ciudadanos, puntualiz\u00f3.<br><br>La decisi\u00f3n fue avalada por la presidenta Claudia Sheinbaum y la Comisi\u00f3n Nacional de Cultura F\u00edsica y Deporte (CONADE), a trav\u00e9s de su director general, Rommel Pacheco y marca el regreso pleno del estado al escenario deportivo nacional.<\/p>\n\n\n\n<p>Alejandro Armenta record\u00f3 que durante el primer a\u00f1o de su administraci\u00f3n, se super\u00f3 un veto que por a\u00f1os impidi\u00f3 realizar eventos nacionales debido a una deuda hist\u00f3rica de 27 millones de pesos, que finalmente fue saldada. Ser sede nacional implica mejorar procedimientos, log\u00edstica y atenci\u00f3n a visitantes, lo que generar\u00e1 derrama econ\u00f3mica, impulso tur\u00edstico y fortalecimiento del sector servicios, expres\u00f3 el gobernador Armenta.<\/p>\n\n\n\n<p>La secretaria de Deporte y Juventud, Gaby La Bonita S\u00e1nchez, precis\u00f3 que el evento se realizar\u00e1 con 16 disciplinas y que Puebla cuenta con infraestructura, hoteles y capital humano para cumplir con los est\u00e1ndares nacionales, como ya ocurri\u00f3 durante los Juegos Nacionales Escolares, por lo que la preparaci\u00f3n de los talentos deportivos inicia de inmediato para garantizar los mejores resultados en 2026.<\/p>\n\n\n\n<p>El deporte en Puebla se aplica como pol\u00edtica de Estado y se articula con educaci\u00f3n, cultura y seguridad, mediante proyectos como la Universidad del Deporte, la Universidad de Ciencias Policiales y la pr\u00f3xima Universidad de las Bellas Artes, acciones que reconstruyen el tejido social y la consolidan como tierra de campeones.<\/p>\n\n\n\n<p>Durante la rueda de prensa, el gobernador Alejandro Armenta entreg\u00f3 un reconocimiento a la bailarina poblana Michel Fuentes Santander, licenciada en Danza Cl\u00e1sica y certificada por la Escuela Nacional Fernando Alonso de Cuba, quien a sus 17 a\u00f1os se convertir\u00e1 en la primera bailarina de Puebla y la cuarta mexicana en competir en un certamen internacional como lo es el Prix de Lausanne 2026, donde representar\u00e1 tanto al estado como a M\u00e9xico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por su capacidad organizativa, hospitalidad y resultados, el Estado de Puebla asumir\u00e1 la sede principal de la Olimpiada Nacional CONADE 2026, resalt\u00f3 el gobernador Alejandro Armenta, al considerar que es la actividad deportiva m\u00e1s importante del pa\u00eds. Reafirm\u00f3 que la Olimpiada Nacional CONADE 2026 es un proyecto de transformaci\u00f3n social, al considerar al deporte, el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":73572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[239,195],"class_list":["post-73571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-gobierno","tag-principal"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/73571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=73571"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/73571\/revisions"}],"predecessor-version":[{"id":73573,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/73571\/revisions\/73573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/73572"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=73571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=73571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=73571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}