{"id":73436,"date":"2025-12-20T00:34:25","date_gmt":"2025-12-20T00:34:25","guid":{"rendered":"https:\/\/lahora.mx\/?p=73436"},"modified":"2025-12-20T00:34:25","modified_gmt":"2025-12-20T00:34:25","slug":"trump-cancela-el-programa-de-visas-de-diversidad-y-deja-fuera-a-mexico-brasil-y-venezuela-para-2026","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/12\/20\/trump-cancela-el-programa-de-visas-de-diversidad-y-deja-fuera-a-mexico-brasil-y-venezuela-para-2026\/","title":{"rendered":"Trump cancela el Programa de Visas de Diversidad y deja fuera a M\u00e9xico, Brasil y Venezuela para 2026"},"content":{"rendered":"\n<p>El gobierno de Estados Unidos anunci\u00f3 la suspensi\u00f3n temporal del Programa de Visas de Diversidad , conocido como \u201cLoter\u00eda de Visas\u201d , luego del tiroteo ocurrido el pasado 13 de diciembre en la Universidad de Brown , presuntamente perpetrado por un ciudadano portugu\u00e9s que ingres\u00f3 al pa\u00eds a trav\u00e9s de este mecanismo migratorio.<\/p>\n\n\n\n<p>La medida, ordenada por el presidente Donald Trump , tendr\u00e1 un impacto directo sobre m\u00e1s de 50 mil solicitantes en todo el mundo , quienes perder\u00e1n la posibilidad de acceder legalmente a una residencia permanente o Green Card durante el a\u00f1o 2026.<br>El Programa de Visas de Diversidad permiti\u00f3 que ciudadanos de pa\u00edses con bajo \u00edndice migratorio hacia Estados Unidos pudieran solicitar la residencia de forma aleatoria. Cada a\u00f1o, se otorgaban hasta 55 mil residencias permanentes , que garantizaban el derecho a vivir y trabajar indefinidamente en el pa\u00eds.<\/p>\n\n\n\n<p>Para participar, los aspirantes deb\u00edan provenir de una naci\u00f3n con menos de 50 mil migrantes admitidos en los \u00faltimos cinco a\u00f1os, adem\u00e1s de contar con un diploma de secundaria o experiencia laboral comprobable de al menos dos a\u00f1os en ese mismo per\u00edodo. No obstante, ser seleccionado no aseguraba la obtenci\u00f3n de la residencia, sino \u00fanicamente la posibilidad de solicitarla.<\/p>\n\n\n\n<p>El gobierno estadunidense precis\u00f3 que M\u00e9xico no ser\u00e1 elegible para participar en el programa de 2026, al ser considerado un pa\u00eds de \u201calta admisi\u00f3n migratoria\u201d , es decir, con m\u00e1s de 50 mil personas ingresadas bajo visas familiares o de empleo durante los \u00faltimos cinco a\u00f1os.<\/p>\n\n\n\n<p>Junto con M\u00e9xico, otros pa\u00edses latinoamericanos como Brasil, Colombia, Cuba, Rep\u00fablica Dominicana, El Salvador, Honduras y Venezuela tambi\u00e9n quedan excluidos del programa, adem\u00e1s de naciones como India, Pakist\u00e1n, Jamaica y Corea del Sur .<\/p>\n\n\n\n<p>Por otro lado, se confirma que la mayor\u00eda de los pa\u00edses africanos , incluidos Argelia, Egipto, Kenia y Sud\u00e1frica , continuar\u00e1n siendo elegibles, al igual que diversas naciones de Europa y Ocean\u00eda . En Asia, pa\u00edses como Jap\u00f3n, Jordania, Singapur, Tailandia y Emiratos \u00c1rabes Unidos a\u00fan podr\u00e1n participar, aunque las restricciones en el programa afectar\u00e1n severamente la movilidad internacional.<\/p>\n\n\n\n<p>La suspensi\u00f3n de la Loter\u00eda de Visas forma parte de una estrategia m\u00e1s amplia impulsada por la administraci\u00f3n de Trump para revisar los mecanismos de ingreso migratorio , bajo el argumento de reforzar la seguridad nacional tras los recientes incidentes violentos registrados en territorio estadunidense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de Estados Unidos anunci\u00f3 la suspensi\u00f3n temporal del Programa de Visas de Diversidad , conocido como \u201cLoter\u00eda de Visas\u201d , luego del tiroteo ocurrido el pasado 13 de diciembre en la Universidad de Brown , presuntamente perpetrado por un ciudadano portugu\u00e9s que ingres\u00f3 al pa\u00eds a trav\u00e9s de este mecanismo migratorio. La medida, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":73437,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[183],"tags":[],"class_list":["post-73436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/73436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=73436"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/73436\/revisions"}],"predecessor-version":[{"id":73438,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/73436\/revisions\/73438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/73437"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=73436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=73436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=73436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}