{"id":72802,"date":"2025-12-10T00:04:24","date_gmt":"2025-12-10T00:04:24","guid":{"rendered":"https:\/\/lahora.mx\/?p=72802"},"modified":"2025-12-10T00:04:24","modified_gmt":"2025-12-10T00:04:24","slug":"tiroteo-escolar-en-universidad-de-kentucky-deja-a-1-muerto-y-varios-heridos","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/12\/10\/tiroteo-escolar-en-universidad-de-kentucky-deja-a-1-muerto-y-varios-heridos\/","title":{"rendered":"Tiroteo escolar en Universidad de Kentucky deja a 1 muerto y varios heridos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Autoridades en Estados Unidos han dado a conocer que, tras un intenso tiroteo escolar que se dio en la Universidad Estatal de Kentucky, una persona falleci\u00f3 y varias se encuentran heridas. Este ataque se dio en el medio de una ola de violencia que azota las escuelas estadounidenses, siendo el 209 ataque del 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por medio de un comunicado, el Departamento de Polic\u00eda de la localidad de Frankfort, donde se dio este atentado, inform\u00f3 que lograron detener a la presunta persona responsable de esta situaci\u00f3n, aunque evitaron dar detalles como su nombre, al igual que el de las victimas que se cobr\u00f3 durante el violento tiroteo.<br>El ataque fue inicialmente reportado la tarde del 9 de diciembre, cuando autoridades de Kentucky respondieron a una llamada de emergencia en las cuales les indicaron que hab\u00eda un \u201cagresor activo\u201d en este campus universitario, por lo cual la escuela fue puesta en confinamiento y se envi\u00f3 a un escuadro SWAT.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien se desconocen los motivos detr\u00e1s de este atentado, en redes sociales han circulado presuntos testimonios de personas que dicen que este fue un ataque con motivos raciales, principalmente porque esta es una instituci\u00f3n donde gran parte del alumnado es afrodescendiente y de ascendencia migrante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades en Estados Unidos han dado a conocer que, tras un intenso tiroteo escolar que se dio en la Universidad Estatal de Kentucky, una persona falleci\u00f3 y varias se encuentran heridas. Este ataque se dio en el medio de una ola de violencia que azota las escuelas estadounidenses, siendo el 209 ataque del 2025. Por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":72803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[183],"tags":[],"class_list":["post-72802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/72802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=72802"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/72802\/revisions"}],"predecessor-version":[{"id":72804,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/72802\/revisions\/72804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/72803"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=72802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=72802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=72802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}