{"id":70032,"date":"2025-10-23T18:22:05","date_gmt":"2025-10-23T18:22:05","guid":{"rendered":"https:\/\/lahora.mx\/?p=70032"},"modified":"2025-10-23T18:22:06","modified_gmt":"2025-10-23T18:22:06","slug":"sheinbaum-visita-hoy-puebla-para-supervisar-labores-de-limpieza-y-entrega-de-apoyos","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/10\/23\/sheinbaum-visita-hoy-puebla-para-supervisar-labores-de-limpieza-y-entrega-de-apoyos\/","title":{"rendered":"Sheinbaum visita hoy Puebla para supervisar labores de limpieza y entrega de apoyos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La presidenta Claudia Sheinbaum inform\u00f3 en su conferencia de prensa de esta ma\u00f1ana que este jueves, realizar\u00e1 visitas a El \u00c1lamo en Poza Rica y a la ciudad de Puebla para supervisar personalmente las labores de limpieza y recuperaci\u00f3n en las localidades afectadas por la reciente contingencia clim\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su recorrido, Sheinbaum tambi\u00e9n verificar\u00e1 la entrega de apoyos a la poblaci\u00f3n a trav\u00e9s de la Secretar\u00eda de Bienestar, en los estados de Veracruz, Puebla, Quer\u00e9taro y San Luis Potos\u00ed. Asimismo, se inform\u00f3 que en Hidalgo la entrega de apoyos iniciar\u00e1 el domingo.<br><br>La mandataria destac\u00f3 la importancia de que las autoridades garanticen la atenci\u00f3n inmediata a las familias afectadas y de coordinar las acciones de recuperaci\u00f3n para minimizar el impacto de los fen\u00f3menos clim\u00e1ticos en las comunidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta Claudia Sheinbaum inform\u00f3 en su conferencia de prensa de esta ma\u00f1ana que este jueves, realizar\u00e1 visitas a El \u00c1lamo en Poza Rica y a la ciudad de Puebla para supervisar personalmente las labores de limpieza y recuperaci\u00f3n en las localidades afectadas por la reciente contingencia clim\u00e1tica. Durante su recorrido, Sheinbaum tambi\u00e9n verificar\u00e1 la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":70033,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[176],"tags":[],"class_list":["post-70032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/70032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=70032"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/70032\/revisions"}],"predecessor-version":[{"id":70034,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/70032\/revisions\/70034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/70033"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=70032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=70032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=70032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}