{"id":70029,"date":"2025-10-23T18:12:18","date_gmt":"2025-10-23T18:12:18","guid":{"rendered":"https:\/\/lahora.mx\/?p=70029"},"modified":"2025-10-23T18:15:05","modified_gmt":"2025-10-23T18:15:05","slug":"inicia-en-puebla-la-temporada-de-vacunacion-invernal-contra-influenza-covid-19-y-neumococo","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/10\/23\/inicia-en-puebla-la-temporada-de-vacunacion-invernal-contra-influenza-covid-19-y-neumococo\/","title":{"rendered":"Inicia en Puebla la temporada de vacunaci\u00f3n invernal contra Influenza, COVID-19 y Neumococo"},"content":{"rendered":"\n<p>Del 13 al 17 de marzo, la Secretar\u00eda de Salud de Puebla llevar\u00e1 a cabo la temporada de vacunaci\u00f3n invernal, en la que se aplicar\u00e1n dosis para prevenir Influenza, COVID-19 y Neumococo, inform\u00f3 el titular de la dependencia, Carlos Olivier, en conferencia de prensa con el gobernador Alejandro Armenta.<br><br>El funcionario destac\u00f3 que, con el inicio de la temporada invernal, los gobiernos estatal y federal hacen un llamado a la poblaci\u00f3n a proteger su salud mediante la vacunaci\u00f3n oportuna, considerada la medida m\u00e1s efectiva para prevenir y controlar enfermedades respiratorias graves.<\/p>\n\n\n\n<p>Durante esta jornada, se aplicar\u00e1n los biol\u00f3gicos correspondientes a grupos de poblaci\u00f3n considerados de riesgo, entre ellos:<\/p>\n\n\n\n<p>Ni\u00f1as y ni\u00f1os de seis a 59 meses de edad.<br>Personas adultas mayores de 60 a\u00f1os.<br>Mujeres embarazadas.<br>Personal de salud.<br>Personas de 5 a 59 a\u00f1os con enfermedades cr\u00f3nicas como diabetes, obesidad, afecciones card\u00edacas, pulmonares o inmunol\u00f3gicas.<br>Las vacunas disponibles incluyen la anticovid-19 (versi\u00f3n Moderna), as\u00ed como las dosis contra Influenza estacional y Neumococo.<\/p>\n\n\n\n<p>La Secretar\u00eda de Salud exhort\u00f3 a la poblaci\u00f3n a acudir a su unidad m\u00e9dica m\u00e1s cercana para recibir la vacuna correspondiente, y record\u00f3 que la inmunizaci\u00f3n es fundamental para reducir hospitalizaciones y complicaciones durante el invierno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 13 al 17 de marzo, la Secretar\u00eda de Salud de Puebla llevar\u00e1 a cabo la temporada de vacunaci\u00f3n invernal, en la que se aplicar\u00e1n dosis para prevenir Influenza, COVID-19 y Neumococo, inform\u00f3 el titular de la dependencia, Carlos Olivier, en conferencia de prensa con el gobernador Alejandro Armenta. El funcionario destac\u00f3 que, con el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":70031,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[252],"tags":[],"class_list":["post-70029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/70029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=70029"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/70029\/revisions"}],"predecessor-version":[{"id":70030,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/70029\/revisions\/70030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/70031"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=70029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=70029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=70029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}