{"id":69011,"date":"2025-09-24T14:59:07","date_gmt":"2025-09-24T14:59:07","guid":{"rendered":"https:\/\/lahora.mx\/?p=69011"},"modified":"2025-10-01T15:01:17","modified_gmt":"2025-10-01T15:01:17","slug":"presentan-en-el-congreso-propuesta-legislativa-para-garantizar-interrupcion-segura-del-embarazo","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/09\/24\/presentan-en-el-congreso-propuesta-legislativa-para-garantizar-interrupcion-segura-del-embarazo\/","title":{"rendered":"Presentan en el Congreso propuesta legislativa para garantizar interrupci\u00f3n segura del embarazo"},"content":{"rendered":"\n<p>En sesi\u00f3n p\u00fablica ordinaria del Congreso del Estado, la diputada Nayeli Salvatori Bojalil present\u00f3 una iniciativa para reformar, adicionar y derogar diversas disposiciones de la Ley Estatal de Salud, con el objetivo de garantizar la interrupci\u00f3n segura del embarazo, al especificar el trato y los protocolos generales que deben implementarse.<\/p>\n\n\n\n<p>La propuesta legislativa pretende priorizar los procedimientos menos invasivos o de menor afectaci\u00f3n para la persona, estableciendo tres d\u00edas naturales como tiempo m\u00e1ximo de espera para su atenci\u00f3n, por el tipo de servicio requerido.<\/p>\n\n\n\n<p>Tambi\u00e9n propone que, en caso de violencia, no se exija la presentaci\u00f3n de denuncia o querella para brindar dicho servicio.<\/p>\n\n\n\n<p>La propuesta legislativa fue turnada a la Comisi\u00f3n de Salud, para su estudio y resoluci\u00f3n correspondiente.<\/p>\n\n\n\n<p>Por otra parte, la diputada Guadalupe Yamak Taja present\u00f3 una iniciativa para adicionar el art\u00edculo 60 Bis a la Ley Estatal de Salud, con el prop\u00f3sito de que las dependencias y entidades de la administraci\u00f3n p\u00fablica estatal y municipal, as\u00ed como los poderes Legislativo y Judicial, que cuenten con una plantilla laboral integrada por treinta o m\u00e1s mujeres, establezcan y mantengan espacios de atenci\u00f3n materna o, en su caso, realicen convenios con instancias infantiles cercanas, debidamente acreditadas, para que presten los servicios en condiciones de calidad y seguridad.<\/p>\n\n\n\n<p>La iniciativa fue dirigida a la Comisi\u00f3n de Salud, para su an\u00e1lisis procedente.<\/p>\n\n\n\n<p>Asimismo, la diputada Norma Estela Pimentel M\u00e9ndez present\u00f3 una iniciativa para reformar y adicionar la Ley Org\u00e1nica de la Administraci\u00f3n P\u00fablica del Estado de Puebla, con el prop\u00f3sito de que el uso del lenguaje incluyente deje de ser un ideal y se convierta en una obligaci\u00f3n jur\u00eddica. Se pretende vigilar el cumplimiento de lo establecido en la Ley para la Igualdad entre Mujeres y Hombres del Estado de Puebla y, en su caso, emitir las medidas correctivas dirigidas a las dependencias y entidades de la administraci\u00f3n p\u00fablica estatal y a los municipios.<\/p>\n\n\n\n<p>La propuesta legislativa fue enviada a la Comisi\u00f3n de Gobernaci\u00f3n y Puntos Constitucionales.<\/p>\n\n\n\n<p>De igual forma, la diputada Norma Estela Pimentel M\u00e9ndez present\u00f3 una iniciativa para reformar diversas disposiciones de la Ley Org\u00e1nica de la Fiscal\u00eda General del Estado de Puebla, con el objetivo de sustituir el lenguaje sexista en el ordenamiento legal por t\u00e9rminos neutros e incluyentes, a fin de contar con un marco normativo con perspectiva de g\u00e9nero y cumplir con las obligaciones nacionales e internacionales en materia de igualdad y no discriminaci\u00f3n.<\/p>\n\n\n\n<p>La iniciativa fue turnada a la Comisi\u00f3n de Procuraci\u00f3n y Administraci\u00f3n de Justicia, para su estudio procedente.<\/p>\n\n\n\n<p>Tambi\u00e9n, la diputada Norma Estela Pimentel M\u00e9ndez present\u00f3 una iniciativa para reformar y adicionar diversas disposiciones de la Ley para la Igualdad entre Mujeres y Hombres del Estado de Puebla, con el objetivo de fortalecer las atribuciones de la Secretar\u00eda de las Mujeres del Estado de Puebla, como un \u00f3rgano rector de la pol\u00edtica de igualdad; as\u00ed como establecer lineamientos para el uso correcto del lenguaje incluyente, revisar el cumplimiento de las disposiciones de la ley de la materia y, en su caso, emitir las medidas correctivas de car\u00e1cter preventivo, dirigidas a las dependencias, entidades y municipios.<br>La propuesta fue dirigida a la Comisi\u00f3n de Igualdad de G\u00e9nero.<\/p>\n\n\n\n<p>En su momento, el diputado Julio Miguel Huerta G\u00f3mez present\u00f3 una iniciativa para reformar la Ley Estatal de Salud, con el objetivo de establecer que para la toma de \u00f3rganos y tejidos se requiere el consentimiento expreso y por escrito del disponente originario, libre de coacci\u00f3n f\u00edsica o moral, otorgado ante notario p\u00fablico, o ante la autoridad p\u00fablica estatal que expida las licencias para conducir veh\u00edculos motorizados, o en documento expedido ante dos testigos id\u00f3neos y con las dem\u00e1s formalidades que al efecto se\u00f1alen las disposiciones aplicables.<\/p>\n\n\n\n<p>La iniciativa fue enviada a la Comisi\u00f3n de Salud, para su an\u00e1lisis y resoluci\u00f3n correspondiente.<\/p>\n\n\n\n<p>Durante la sesi\u00f3n p\u00fablica ordinaria, la Mesa Directiva dio cuenta de las siguientes propuestas legislativas:<\/p>\n\n\n\n<p>-Iniciativa de la diputada Mar\u00eda Soledad Amieva Zamora para reformar la Ley Estatal de Salud, con el fin de establecer que cuando se trate de la atenci\u00f3n de personas con discapacidad y adultas mayores, \u00e9stas tendr\u00e1n derecho a recibir informaci\u00f3n con o sin la presencia o autorizaci\u00f3n de un familiar, de quienes ejerzan la patria potestad, tutela o representaci\u00f3n legal.<\/p>\n\n\n\n<p>La iniciativa fue dirigida a la Comisi\u00f3n de Salud.<\/p>\n\n\n\n<p>-Punto de acuerdo de la diputada Nayeli Salvatori Bojalil por el que exhorta al titular del Poder Ejecutivo Estatal para que, a trav\u00e9s de las secretar\u00edas de las Mujeres, Seguridad P\u00fablica, Infraestructura, Desarrollo Econ\u00f3mico y Trabajo, y la de Educaci\u00f3n P\u00fablica, dise\u00f1en e implementen la estrategia denominada \u00abRed Violeta Puebla: Espacios Seguros y Rutas Camina Segura para Mujeres y Ni\u00f1as\u00bb, entre otras acciones.<\/p>\n\n\n\n<p>La propuesta legislativa fue enviada a la Comisi\u00f3n de Igualdad, para su estudio y resoluci\u00f3n procedente.<\/p>\n\n\n\n<p>-Punto de acuerdo del diputado Andr\u00e9s Iv\u00e1n Villegas Mendoza por el que exhorta a las Secretar\u00edas de Educaci\u00f3n P\u00fablica, de Arte y Cultura, de las Mujeres, as\u00ed como a los Ayuntamientos y Concejos Municipales del Estado de Puebla para que, en el \u00e1mbito de sus respectivas atribuciones, revisen la denominaci\u00f3n de Planteles Educativos, Instituciones Culturales, Espacios P\u00fablicos, Mercados, Panteones, Calles y Jardines y cualquier Espacio P\u00fablico que se encuentre bajo su competencia y que llevan el nombre de Josefa Ortiz De Dom\u00ednguez y consideren actualizarlo por el de Josefa Ortiz T\u00e9llez-Gir\u00f3n, en reconocimiento de su identidad plena y como acto de justicia simb\u00f3lica y de igualdad de g\u00e9nero.<\/p>\n\n\n\n<p>El exhorto fue enviado a la Comisi\u00f3n de Educaci\u00f3n, para su estudio procedente.<\/p>\n\n\n\n<p>-Punto de acuerdo del diputado Jaime Alejandro Aurioles Barroeta, para exhortar a la Secretar\u00eda de Educaci\u00f3n P\u00fablica del Gobierno del Estado y a los Ayuntamientos y Concejos Municipales de la Entidad, a implementar programas para las madres y padres de familia, con la finalidad de dar a conocer los beneficios y ventajas de implementar la crianza positiva en las ni\u00f1as, ni\u00f1os y adolescentes poblanos y, en consecuencia, se les eduque sin violencia, procurando el inter\u00e9s superior de la ni\u00f1ez, y fomentando su desarrollo, bienestar y crecimiento, de manera saludable y armoniosa.<\/p>\n\n\n\n<p>La propuesta legislativa fue dirigida a la Comisi\u00f3n de Educaci\u00f3n para su an\u00e1lisis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En sesi\u00f3n p\u00fablica ordinaria del Congreso del Estado, la diputada Nayeli Salvatori Bojalil present\u00f3 una iniciativa para reformar, adicionar y derogar diversas disposiciones de la Ley Estatal de Salud, con el objetivo de garantizar la interrupci\u00f3n segura del embarazo, al especificar el trato y los protocolos generales que deben implementarse. La propuesta legislativa pretende priorizar [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":69012,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[227,223],"class_list":["post-69011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-congreso","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/69011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=69011"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/69011\/revisions"}],"predecessor-version":[{"id":69013,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/69011\/revisions\/69013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/69012"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=69011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=69011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=69011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}