{"id":68508,"date":"2025-09-22T16:58:58","date_gmt":"2025-09-22T16:58:58","guid":{"rendered":"https:\/\/lahora.mx\/?p=68508"},"modified":"2025-09-22T16:58:59","modified_gmt":"2025-09-22T16:58:59","slug":"mas-de-4-mil-calles-pavimentadas-en-puebla-capital-al-cierre-de-2025-armenta","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/09\/22\/mas-de-4-mil-calles-pavimentadas-en-puebla-capital-al-cierre-de-2025-armenta\/","title":{"rendered":"M\u00e1s de 4 mil calles pavimentadas en Puebla capital, al cierre de 2025: Armenta"},"content":{"rendered":"\n<p>Al concluir el presente a\u00f1o, la ciudad de Puebla contar\u00e1 con m\u00e1s de 4 mil calles pavimentadas y rehabilitadas, as\u00ed lo anunci\u00f3 el gobernador del estado, Alejandro Armenta, al refrendar su compromiso con la dignificaci\u00f3n de la infraestructura urbana y en que se atienda una de las demandas ciudadanas m\u00e1s solicitadas durante sus giras de trabajo.<\/p>\n\n\n\n<p>El titular del ejecutivo estatal reiter\u00f3 que le indigna ver las calles destrozadas y observar baches por todos lados; por ello, destac\u00f3 que las obras se ejecutan en su gobierno con una tercera parte del presupuesto que se destinaba antes.<br><br>El gobernador Alejandro Armenta destac\u00f3 que ya est\u00e1n concluidos al 100 por ciento, los trabajos en la Carretera de San Francisco Totimehuacan hacia la desviaci\u00f3n a San Baltazar Tetela, que en t\u00e9rminos de kil\u00f3metros equivale a mil 200 calles de 50 metros. \u00abEstamos ejecutando obra directa con la maquinaria que compramos con los impuestos de ustedes. Ya no hay milpa, es decir, mil para el pol\u00edtico y mil para la autoridad\u00bb, apunt\u00f3 el mandatario.<\/p>\n\n\n\n<p>Gracias a los m\u00f3dulos de maquinaria adquiridos este a\u00f1o por el Gobierno del Estado, las obras de pavimentaci\u00f3n se realizan con una reducci\u00f3n del 30 por ciento en costos. A este ahorro se suma el apoyo en insumos por parte de Petr\u00f3leos Mexicanos (Pemex), lo que representa otro 30 por ciento de disminuci\u00f3n en gastos. De esta manera, se intervienen 10 vialidades m\u00e1s en la capital de Puebla, ya que la optimizaci\u00f3n de recursos ha permitido obras en menor tiempo y con mayor eficacia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al concluir el presente a\u00f1o, la ciudad de Puebla contar\u00e1 con m\u00e1s de 4 mil calles pavimentadas y rehabilitadas, as\u00ed lo anunci\u00f3 el gobernador del estado, Alejandro Armenta, al refrendar su compromiso con la dignificaci\u00f3n de la infraestructura urbana y en que se atienda una de las demandas ciudadanas m\u00e1s solicitadas durante sus giras de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":68509,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[239,195,223],"class_list":["post-68508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-gobierno","tag-principal","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/68508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=68508"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/68508\/revisions"}],"predecessor-version":[{"id":68510,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/68508\/revisions\/68510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/68509"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=68508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=68508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=68508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}