{"id":66051,"date":"2025-08-01T02:44:06","date_gmt":"2025-08-01T02:44:06","guid":{"rendered":"https:\/\/lahora.mx\/?p=66051"},"modified":"2025-08-01T02:44:06","modified_gmt":"2025-08-01T02:44:06","slug":"puebla-alista-rehabilitacion-de-barrios-historicos-con-apoyo-del-inah","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/08\/01\/puebla-alista-rehabilitacion-de-barrios-historicos-con-apoyo-del-inah\/","title":{"rendered":"Puebla alista rehabilitaci\u00f3n de barrios hist\u00f3ricos con apoyo del INAH"},"content":{"rendered":"\n<p>La ciudad de Puebla se prepara para un ambicioso proyecto de rehabilitaci\u00f3n urbana que buscar\u00e1 devolver el brillo y el valor cultural a sus barrios m\u00e1s antiguos. De acuerdo con autoridades estatales, la Secretar\u00eda de Infraestructura ya se encuentra desarrollando el proyecto ejecutivo que dar\u00e1 forma a las acciones que se implementar\u00e1n en estas zonas con fuerte carga hist\u00f3rica.<br><br>Los barrios que ser\u00e1n intervenidos son Analco, El Carmen, El Alto, La Luz, San Francisco, San Antonio, Xanenetla y Xonaca, considerados los fundacionales de la capital poblana. Estos espacios no solo representan el origen de la ciudad, sino que tambi\u00e9n resguardan parte importante de su identidad arquitect\u00f3nica y social.<\/p>\n\n\n\n<p>Antes de este paso t\u00e9cnico, ya se hab\u00eda completado un plan conceptual elaborado de manera conjunta por el Instituto Nacional de Antropolog\u00eda e Historia (INAH), la Secretar\u00eda de Desarrollo Econ\u00f3mico y la Gerencia del Centro Hist\u00f3rico del Ayuntamiento de Puebla. La intenci\u00f3n ahora es traducir esa visi\u00f3n en acciones concretas y viables, siempre respetando las normas de conservaci\u00f3n del patrimonio que establece el INAH.<\/p>\n\n\n\n<p>Carlos M\u00e1rquez P\u00e9rez, subsecretario de Turismo estatal, explic\u00f3 que se trata de una intervenci\u00f3n integral, enfocada no solo en el embellecimiento urbano, sino tambi\u00e9n en garantizar que las obras respeten la historia y vocaci\u00f3n original de cada barrio. \u201cLa idea es que se rehabiliten respetando lo que eran originalmente, cumpliendo con las exigencias del INAH y d\u00e1ndoles vida como espacios atractivos para el turismo nacional e internacional\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Actualmente, la mayor\u00eda de estos barrios presentan desgaste urbano, deterioro en infraestructura y un uso desigual del espacio p\u00fablico. Sin embargo, muchos de ellos conservan elementos \u00fanicos que podr\u00edan convertirse en polos de atracci\u00f3n si se les da el mantenimiento adecuado.<\/p>\n\n\n\n<p>Desde la Secretar\u00eda de Turismo de Puebla, se ha impulsado su promoci\u00f3n como parte del Centro Hist\u00f3rico, con el objetivo de posicionarlos como puntos de inter\u00e9s m\u00e1s all\u00e1 del circuito tradicional de turistas. La iniciativa se suma a otros esfuerzos por fortalecer el patrimonio cultural y detonar el turismo de identidad, que pone en valor las ra\u00edces locales.<\/p>\n\n\n\n<p>Se espera que una vez concluido el proyecto ejecutivo, se definan etapas de intervenci\u00f3n, presupuesto y tiempos de ejecuci\u00f3n, aunque a\u00fan no hay una fecha concreta para el inicio de las obras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ciudad de Puebla se prepara para un ambicioso proyecto de rehabilitaci\u00f3n urbana que buscar\u00e1 devolver el brillo y el valor cultural a sus barrios m\u00e1s antiguos. De acuerdo con autoridades estatales, la Secretar\u00eda de Infraestructura ya se encuentra desarrollando el proyecto ejecutivo que dar\u00e1 forma a las acciones que se implementar\u00e1n en estas zonas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":66052,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3,175],"tags":[223],"class_list":["post-66051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/66051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=66051"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/66051\/revisions"}],"predecessor-version":[{"id":66053,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/66051\/revisions\/66053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/66052"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=66051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=66051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=66051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}