{"id":65467,"date":"2025-07-20T21:59:00","date_gmt":"2025-07-20T21:59:00","guid":{"rendered":"https:\/\/lahora.mx\/?p=65467"},"modified":"2025-07-23T00:04:42","modified_gmt":"2025-07-23T00:04:42","slug":"alertan-sobre-presunto-medicamento-falso","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/07\/20\/alertan-sobre-presunto-medicamento-falso\/","title":{"rendered":"Alertan sobre presunto medicamento falso"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A trav\u00e9s de un comunicado la Comisi\u00f3n Federal para la Protecci\u00f3n contra Riesgos Sanitarios (Cofepris) emiti\u00f3 una advertencia sore la posible falsificaci\u00f3n de Agrifen RLX, medicamento que contiene paracetamol y fenilefrina.<br><br>Este aviso va dirigido tanto al personal de salud como al p\u00fablico en general; Laboratorios PISA, titular del registro sanitario, fue quien detect\u00f3 la irregularidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El lote N15D027, con fecha de caducidad marcada como diciembre de 2025, no coincide con el registro original, cuya vigencia terminaba en 2017.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consumir este medicamento representar\u00eda un riesgo para la salud, se desconoce su origen y c\u00f3mo fue fabricado y almacenado, lo que tambi\u00e9n impide garantizar su calidad y eficacia, podr\u00eda contener sustancias peligrosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">COFEPRIS recomienda evitar su compra y consumo, tambi\u00e9n pide reportar cualquier sospecha sobre productos similares en farmacias o puntos de venta, la falsificaci\u00f3n de medicamentos puede tener consecuencias graves para quien los usa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas son algunas recomendaciones para reconocer que el medicamento es genuino:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Revisar la caja del medicamento, que no tengo apariencia extra\u00f1a o faltas de ortograf\u00eda en el empaque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Si ves a la venta AGRIFEN RLX de 500 mg \/ 10 mg con el lote N15D027, sin importar la fecha de caducidad, no lo compres. Si sabes d\u00f3nde lo venden, puedes hacer una denuncia sanitaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Si tienes dudas sobre si el medicamento es original, lo mejor es contactar al laboratorio due\u00f1o del registro para confirmar su autenticidad. Puedes buscar esta informaci\u00f3n en la p\u00e1gina oficial de COFEPRIS.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No comprar medicinas en la calle o con vendedores informales, los productos pueden ser falsos, robados o peligrosos.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ante alg\u00fan malestar o reacci\u00f3n, rep\u00f3rtalo en l\u00ednea o escribe al correo: farmacovigilancia@cofepris.gob.mx esto ayuda a prevenir m\u00e1s casos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de un comunicado la Comisi\u00f3n Federal para la Protecci\u00f3n contra Riesgos Sanitarios (Cofepris) emiti\u00f3 una advertencia sore la posible falsificaci\u00f3n de Agrifen RLX, medicamento que contiene paracetamol y fenilefrina. Este aviso va dirigido tanto al personal de salud como al p\u00fablico en general; Laboratorios PISA, titular del registro sanitario, fue quien detect\u00f3 la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":65468,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[252],"tags":[223],"class_list":["post-65467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/65467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=65467"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/65467\/revisions"}],"predecessor-version":[{"id":65469,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/65467\/revisions\/65469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/65468"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=65467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=65467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=65467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}