{"id":62904,"date":"2025-05-28T02:06:06","date_gmt":"2025-05-28T02:06:06","guid":{"rendered":"https:\/\/lahora.mx\/?p=62904"},"modified":"2025-05-28T02:06:06","modified_gmt":"2025-05-28T02:06:06","slug":"el-amanecer-cosmico-retratado-webb-toma-la-foto-mas-antigua-del-universo","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/05\/28\/el-amanecer-cosmico-retratado-webb-toma-la-foto-mas-antigua-del-universo\/","title":{"rendered":"El amanecer c\u00f3smico retratado: Webb toma la foto m\u00e1s antigua del universo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El telescopio espacial James Webb (JWST) ha captado la imagen m\u00e1s profunda registrada sobre un solo objetivo del universo, revelando detalles sin precedentes de galaxias que se formaron durante el llamado \u00abamanecer c\u00f3smico\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lo anunciaron el Centro Nacional de Investigaci\u00f3n Cient\u00edfica (CNRS) de Francia y la Agencia Espacial Europea (ESA).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias al fen\u00f3meno conocido como lente gravitacional, los astr\u00f3nomos lograron observar las primeras galaxias y estrellas que emergieron cuando el universo ten\u00eda menos de mil millones de a\u00f1os. Este descubrimiento representa un avance crucial para comprender c\u00f3mo comenz\u00f3 a organizarse el cosmos tras el Big Bang.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 muestra la imagen m\u00e1s profunda del James Webb?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La imagen, que requiri\u00f3 m\u00e1s de 120 horas de observaci\u00f3n continua, se centra en un \u00fanico objetivo: el c\u00famulo de galaxias Abell S1063, situado a 4.500 millones de a\u00f1os luz de la Tierra. Esta haza\u00f1a marca el periodo de observaci\u00f3n m\u00e1s largo realizado por el JWST sobre un solo punto del universo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ESA destac\u00f3 que se trata de la imagen m\u00e1s profunda obtenida por el telescopio, revelando estructuras c\u00f3smicas extremadamente lejanas y antiguas.<br><br>\u00bfQu\u00e9 es la lente gravitacional?<br>El c\u00famulo Abell S1063 act\u00faa como una lente c\u00f3smica. Su enorme masa curva la luz de objetos a\u00fan m\u00e1s lejanos situados detr\u00e1s de \u00e9l, amplific\u00e1ndola y permitiendo su observaci\u00f3n desde la Tierra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este fen\u00f3meno, conocido como lente gravitacional, es clave para detectar galaxias demasiado distantes o d\u00e9biles para ser vistas de otro modo.<br>Los cient\u00edficos se enfocaron en los \u00abarcos deformados\u00bb de luz que rodean a Abell S1063, se\u00f1ales visuales de estas galaxias primitivas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPor qu\u00e9 es importante el \u00abamanecer c\u00f3smico\u00bb?<br>Explorar el llamado \u00abamanecer c\u00f3smico\u00bb permite a los astr\u00f3nomos comprender c\u00f3mo surgieron las primeras estructuras del universo. Este periodo marca el nacimiento de las primeras estrellas, galaxias y c\u00famulos gal\u00e1cticos que dar\u00edan forma al cosmos actual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las observaciones del JWST proporcionan datos esenciales para refinar los modelos cosmol\u00f3gicos y podr\u00edan arrojar pistas sobre la formaci\u00f3n de elementos, materia oscura y otros misterios del universo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El telescopio espacial James Webb (JWST) ha captado la imagen m\u00e1s profunda registrada sobre un solo objetivo del universo, revelando detalles sin precedentes de galaxias que se formaron durante el llamado \u00abamanecer c\u00f3smico\u00bb. As\u00ed lo anunciaron el Centro Nacional de Investigaci\u00f3n Cient\u00edfica (CNRS) de Francia y la Agencia Espacial Europea (ESA). Gracias al fen\u00f3meno conocido [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":62906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-62904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geek"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/62904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=62904"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/62904\/revisions"}],"predecessor-version":[{"id":62907,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/62904\/revisions\/62907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/62906"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=62904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=62904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=62904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}