{"id":6288,"date":"2022-04-30T01:50:46","date_gmt":"2022-04-30T01:50:46","guid":{"rendered":"http:\/\/lahora.mx\/?p=6288"},"modified":"2022-04-30T01:50:47","modified_gmt":"2022-04-30T01:50:47","slug":"amlo-y-joe-biden-hablaron-sobre-la-migracion","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/04\/30\/amlo-y-joe-biden-hablaron-sobre-la-migracion\/","title":{"rendered":"AMLO y Joe Biden hablaron sobre la migraci\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente estadounidense,\u00a0<strong>Joe Biden<\/strong>, y su hom\u00f3logo mexicano,<strong>\u00a0Andr\u00e9s Manuel L\u00f3pez Obrador<\/strong>, mantuvieron este viernes una conversaci\u00f3n \u00abconstructiva\u00bb centrada principalmente en migraci\u00f3n, asegur\u00f3 la portavoz de la\u00a0<strong>Casa Blanca<\/strong>, Jen Psaki.\u00a0<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reuni\u00f3n virtual entre Biden y L\u00f3pez Obrador dur\u00f3 52 minutos y \u00abla mayor parte de la conversaci\u00f3n fue sobre migraci\u00f3n\u00bb, sobre c\u00f3mo coordinar una estrategia para \u00abreducir la migraci\u00f3n a la frontera\u00bb com\u00fan, recalc\u00f3 Psaki en su rueda de prensa diaria, poco despu\u00e9s de que terminara la llamada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEl tono de la llamada fue muy constructivo\u00bb, a\u00f1adi\u00f3 la portavoz.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abQueremos seguir actuando como aliados y precisamente porque nosotros queremos que se suspenda el titulo 42\u00bb, a\u00f1adi\u00f3 Psaki.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La portavoz de la Casa Blanca mencion\u00f3 que \u00abesta no era una llamada en la que el presidente Biden estaba amenazando al presidente mexicano de ninguna manera\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su lado, el presidente L\u00f3pez Obrador inform\u00f3 que la conversaci\u00f3n fue \u201ccordial\u201d con Joe Biden.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTratamos temas de inter\u00e9s en la relaci\u00f3n bilateral y acordamos que el secretario Marcelo Ebrard visitar\u00e1 Washington el lunes para avanzar en temas de cooperaci\u00f3n para el desarrollo y sobre la Cumbre de las Am\u00e9ricas\u201d, refiri\u00f3 en redes sociales.<br>Previamente, el presidente de Estados Unidos hab\u00eda informado que en la conversaci\u00f3n telef\u00f3nica con L\u00f3pez Obrador discutir\u00eda sus puntos de vista para la Novena Cumbre de las Am\u00e9ricas y las iniciativas prioritarias de Am\u00e9rica del Norte para la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente estadounidense,\u00a0Joe Biden, y su hom\u00f3logo mexicano,\u00a0Andr\u00e9s Manuel L\u00f3pez Obrador, mantuvieron este viernes una conversaci\u00f3n \u00abconstructiva\u00bb centrada principalmente en migraci\u00f3n, asegur\u00f3 la portavoz de la\u00a0Casa Blanca, Jen Psaki.\u00a0 La reuni\u00f3n virtual entre Biden y L\u00f3pez Obrador dur\u00f3 52 minutos y \u00abla mayor parte de la conversaci\u00f3n fue sobre migraci\u00f3n\u00bb, sobre c\u00f3mo coordinar una estrategia [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6289,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[176],"tags":[],"class_list":["post-6288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/6288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=6288"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/6288\/revisions"}],"predecessor-version":[{"id":6290,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/6288\/revisions\/6290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/6289"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=6288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=6288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=6288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}