{"id":60615,"date":"2025-04-03T16:53:59","date_gmt":"2025-04-03T16:53:59","guid":{"rendered":"https:\/\/lahora.mx\/?p=60615"},"modified":"2025-04-03T16:54:00","modified_gmt":"2025-04-03T16:54:00","slug":"volkswagen-dispuesta-a-entrar-al-t-mec-para-librar-aranceles-de-eu","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/04\/03\/volkswagen-dispuesta-a-entrar-al-t-mec-para-librar-aranceles-de-eu\/","title":{"rendered":"Volkswagen, dispuesta a entrar al T-MEC para librar aranceles de EU"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>La empresa alemana\u00a0<strong>Volkswagen<\/strong>\u00a0buscar\u00e1\u00a0librar aranceles de\u00a0<strong>Estados Unidos<\/strong>integr\u00e1ndose al\u00a0<strong>T-MEC<\/strong>, as\u00ed lo revel\u00f3 la\u00a0<strong>presidenta Claudia Sheinbaum<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En conferencia de prensa hoy, la\u00a0<strong>presidenta<\/strong>\u00a0inform\u00f3 que ya tuvo una\u00a0<strong>reuni\u00f3n con los CEO<\/strong>\u00a0de\u00a0<strong>Volkswagen<\/strong>, BMW y Mercedes Benz para tener\u00a0<strong>alternativas<\/strong>\u00a0y no sufrir el impacto de los\u00a0aranceles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLo primero que tendr\u00edan que hacer las\u00a0<strong>empresas alemanas<\/strong>\u00a0y\u00a0<strong>est\u00e1n dispuestas<\/strong>\u00a0a hacerlo y la\u00a0<strong>Secretar\u00eda de Econom\u00eda<\/strong>\u00a0va a entrar con un proceso de di\u00e1logo, es que entren todas a\u00a0<strong>exportar a trav\u00e9s del T-MEC<\/strong>\u201d, explic\u00f3 la mandataria federal.<br><br>De acuerdo con&nbsp;<strong>Claudia Sheinbaum<\/strong>, se les propuso que sus&nbsp;<strong>exportaciones<\/strong>&nbsp;est\u00e9n&nbsp;<strong>integradas al T-MEC<\/strong>&nbsp;para que tengan&nbsp;<strong>mayor contenido de origen<\/strong>&nbsp;y todas estuvieron de acuerdo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, coment\u00f3 que a\u00fan\u00a0<strong>siguen en mesas de negociaci\u00f3n<\/strong> con\u00a0<strong>Estados Unidos<\/strong>, pues solo los\u00a0<strong>autom\u00f3viles de marcas americanas<\/strong>\u00a0est\u00e1n\u00a0exentos de aranceles, pero es algo que ya buscan dialogar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLo que est\u00e1 publicado ahora que todav\u00eda estamos&nbsp;<strong>dialogando<\/strong>, es que la parte que no tendr\u00eda&nbsp;<strong>arancel<\/strong>&nbsp;es lo que&nbsp;<strong>se fabrica en Estados Unidos<\/strong>&nbsp;y de autopartes, por lo pronto todas no tienen aranceles\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, Claudia Sheinbaum resalt\u00f3 que en caso de\u00a0<strong>no tener buenos resultados<\/strong>\u00a0en las\u00a0<strong>negociaciones<\/strong>,\u00a0<strong>M\u00e9xico seguir\u00eda siendo competitivo<\/strong>\u00a0por su cercan\u00eda con Estados Unidos.<br><br>Actualmente\u00a0<strong>Volkswagen<\/strong>\u00a0cuenta con su planta armadora en el estado de\u00a0<strong>Puebla<\/strong>, en la cual\u00a0<strong>el 80 por ciento de su producci\u00f3n<\/strong>\u00a0es enviada a\u00a0<strong>Estados Unidos<\/strong>.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa alemana\u00a0Volkswagen\u00a0buscar\u00e1\u00a0librar aranceles de\u00a0Estados Unidosintegr\u00e1ndose al\u00a0T-MEC, as\u00ed lo revel\u00f3 la\u00a0presidenta Claudia Sheinbaum. En conferencia de prensa hoy, la\u00a0presidenta\u00a0inform\u00f3 que ya tuvo una\u00a0reuni\u00f3n con los CEO\u00a0de\u00a0Volkswagen, BMW y Mercedes Benz para tener\u00a0alternativas\u00a0y no sufrir el impacto de los\u00a0aranceles. \u00abLo primero que tendr\u00edan que hacer las\u00a0empresas alemanas\u00a0y\u00a0est\u00e1n dispuestas\u00a0a hacerlo y la\u00a0Secretar\u00eda de Econom\u00eda\u00a0va a entrar con [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":60616,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[176],"tags":[195,223],"class_list":["post-60615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-principal","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/60615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=60615"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/60615\/revisions"}],"predecessor-version":[{"id":60617,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/60615\/revisions\/60617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/60616"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=60615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=60615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=60615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}