{"id":60105,"date":"2025-03-21T23:07:24","date_gmt":"2025-03-21T23:07:24","guid":{"rendered":"https:\/\/lahora.mx\/?p=60105"},"modified":"2025-03-21T23:07:24","modified_gmt":"2025-03-21T23:07:24","slug":"hallan-armas-tras-cateo-de-inmueble-del-excandidato-a-la-alcaldia-de-chignahuapan","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/03\/21\/hallan-armas-tras-cateo-de-inmueble-del-excandidato-a-la-alcaldia-de-chignahuapan\/","title":{"rendered":"Hallan armas tras cateo de inmueble del excandidato a la alcald\u00eda de Chignahuapan"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>Fiscal\u00eda General del Estado cate\u00f3 en Chignahuapan<\/strong>, un inmueble, presuntamente,&nbsp;<strong>propiedad de Juan N, alias \u201cEl Moco\u201d, excandidato a la alcald\u00eda de este municipio,&nbsp;<\/strong>considerado por las autoridades estatales como&nbsp;<strong>generador de violencia en la regi\u00f3n<\/strong>. En la propiedad fueron&nbsp;<strong>halladas armas de fuego, propaganda pol\u00edtica, listas nominales y vales para la supuesta compra de votos&nbsp;<\/strong>a favor de Yasm\u00edn Medina, quien, de acuerdo con fuentes policiacas, ser\u00eda la esposa del abogado defensor de Juan N.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior, luego de que agentes ministeriales dieran cumplimiento al mandato judicial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A decir de las fuentes consultadas, una vez que las autoridades tuvieron conocimiento acerca de que en el predio denominado\u00a0<strong>\u201cEl Tepetate\u201d, ubicado en la comunidad de \u201cEl Cabellal\u201d, se realizaban presuntas actividades il\u00edcitas,<\/strong>\u00a0se recabaron datos de prueba mediante labores de inteligencia y de campo, solicit\u00e1ndose la orden de cateo correspondiente para inspeccionar el lugar.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el desahogo de la diligencia los agentes aseguraron los siguientes indicios: mil 80 cupones o vales para la compra del voto;&nbsp;<strong>3 mil volantes; 500 p\u00f3sters de 30 x 40 cent\u00edmetros; 24 vinilonas de 1.40 por 1.45 metros;<\/strong>&nbsp;y listas nominales de seis secciones electorales del municipio de Chignahuapan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de una&nbsp;<strong>escopeta calibre 16 mil\u00edmetros con un cartucho \u00fatil, y una escopeta calibre 22 mil\u00edmetros.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con los informantes, la propaganda corresponde a Yasm\u00edn Medina, candidata del partido Movimiento Ciudadano a la presidencial municipal de Chignahuapan, y quien adem\u00e1s,<strong>&nbsp;es se\u00f1alada de tener una relaci\u00f3n cercana con Juan N, alias \u201cEl Moco\u201d,&nbsp;<\/strong>presunto l\u00edder huachicolero de la zona y que incluso, en junio de 2020 fue detenido para despu\u00e9s, conseguir su libertad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A decir de los informantes,\u00a0<strong>dicha candidata ser\u00eda esposa del abogado de Juan N.<\/strong><br><br>En este sentido, e<strong>l defensor particular de Juan, asegur\u00f3 a El Sol de Puebla que la propiedad cateada no es de su cliente,&nbsp;<\/strong>y la propaganda no corresponde a la que fue registrada ante las autoridades electorales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los indicios quedaron a disposici\u00f3n del Agente del Ministerio P\u00fablico a fin de continuar con las investigaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La&nbsp;Fiscal\u00eda General del Estado cate\u00f3 en Chignahuapan, un inmueble, presuntamente,&nbsp;propiedad de Juan N, alias \u201cEl Moco\u201d, excandidato a la alcald\u00eda de este municipio,&nbsp;considerado por las autoridades estatales como&nbsp;generador de violencia en la regi\u00f3n. En la propiedad fueron&nbsp;halladas armas de fuego, propaganda pol\u00edtica, listas nominales y vales para la supuesta compra de votos&nbsp;a favor de Yasm\u00edn [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":60106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[195,223],"class_list":["post-60105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-principal","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/60105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=60105"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/60105\/revisions"}],"predecessor-version":[{"id":60107,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/60105\/revisions\/60107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/60106"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=60105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=60105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=60105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}