{"id":59377,"date":"2025-03-05T22:46:43","date_gmt":"2025-03-05T22:46:43","guid":{"rendered":"https:\/\/lahora.mx\/?p=59377"},"modified":"2025-03-05T22:46:43","modified_gmt":"2025-03-05T22:46:43","slug":"sujetos-disparan-contra-casa-en-texmelucan","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/03\/05\/sujetos-disparan-contra-casa-en-texmelucan\/","title":{"rendered":"Sujetos disparan contra casa en Texmelucan"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Sujetos armados<\/strong>\u00a0a bordo de una motocicleta realizaron\u00a0<strong>detonaciones\u00a0<\/strong>de arma de fuego contra un\u00a0<strong>domicilio<\/strong>\u00a0en la colonia\u00a0<strong>Solidaridad<\/strong>, en el municipio de\u00a0San Mart\u00edn Texmelucan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La noche del martes, vecinos denunciaron el ataque a trav\u00e9s de redes sociales y se\u00f1alaron que, pese a<strong>&nbsp;solicitar&nbsp;<\/strong>el<strong>&nbsp;apoyo&nbsp;<\/strong>de la<strong>&nbsp;Polic\u00eda Municipal<\/strong>, los elementos<strong>&nbsp;nunca llegaron<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con testimonios ciudadanos, los&nbsp;<strong>agresores dispararon contra una vivienda<\/strong>&nbsp;en la colonia Solidaridad y escaparon sin que fueran detenidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante este hecho, vecinos de la zona exigieron\u00a0<strong>mayor seguridad<\/strong>\u00a0y una respuesta m\u00e1s efectiva por parte de las autoridades municipales.<br>Asimismo, expresaron su preocupaci\u00f3n por el&nbsp;<strong>aumento&nbsp;<\/strong>de<strong>hechos delictivos&nbsp;<\/strong>en la regi\u00f3n, lo que ha llevado a muchos ciudadanos a realizar denuncias a trav\u00e9s de redes sociales ante la falta de acci\u00f3n de las autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los habitantes de Texmelucan cuestionaron la gesti\u00f3n del alcalde<strong>Juan Manuel Alonso<\/strong>, y lo acusaron de&nbsp;<strong>no garantizar<\/strong>&nbsp;la&nbsp;<strong>seguridad<\/strong>en el municipio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este incidente se suma a una serie de hechos delictivos recientes que han generado inquietud entre los texmeluquenses, quienes exigen estrategias m\u00e1s contundentes para combatir la delincuencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sujetos armados\u00a0a bordo de una motocicleta realizaron\u00a0detonaciones\u00a0de arma de fuego contra un\u00a0domicilio\u00a0en la colonia\u00a0Solidaridad, en el municipio de\u00a0San Mart\u00edn Texmelucan. La noche del martes, vecinos denunciaron el ataque a trav\u00e9s de redes sociales y se\u00f1alaron que, pese a&nbsp;solicitar&nbsp;el&nbsp;apoyo&nbsp;de la&nbsp;Polic\u00eda Municipal, los elementos&nbsp;nunca llegaron. De acuerdo con testimonios ciudadanos, los&nbsp;agresores dispararon contra una vivienda&nbsp;en la colonia [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":59378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175,226],"tags":[223],"class_list":["post-59377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","category-policia","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/59377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=59377"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/59377\/revisions"}],"predecessor-version":[{"id":59379,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/59377\/revisions\/59379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/59378"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=59377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=59377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=59377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}