{"id":58893,"date":"2025-02-20T18:28:33","date_gmt":"2025-02-20T18:28:33","guid":{"rendered":"https:\/\/lahora.mx\/?p=58893"},"modified":"2025-02-20T18:28:33","modified_gmt":"2025-02-20T18:28:33","slug":"la-presidenta-claudia-sheinbaum-manda-reformas-contra-trafico-de-armas-e-intervencion-extranjera","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2025\/02\/20\/la-presidenta-claudia-sheinbaum-manda-reformas-contra-trafico-de-armas-e-intervencion-extranjera\/","title":{"rendered":"La presidenta Claudia Sheinbaum manda reformas contra tr\u00e1fico de armas e intervenci\u00f3n extranjera"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>Para proteger la&nbsp;<strong>soberan\u00eda nacional<\/strong>&nbsp;y evitar la injerencia de&nbsp;<strong>Estados Unidos&nbsp;<\/strong>en territorio mexicano<strong>,&nbsp;<\/strong>la actual administraci\u00f3n federal enviar\u00e1 reformas a la&nbsp;<strong>Constituci\u00f3n Pol\u00edtica&nbsp;<\/strong>del pa\u00eds para modificar los art\u00edculos 40 y 19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta de\u00a0<strong>M\u00e9xico<\/strong>,\u00a0Claudia Sheinbaum Pardo, present\u00f3 hoy una\u00a0<strong>reforma constitucional<\/strong>\u00a0que enviar\u00e1 al\u00a0<strong>Congreso de la Uni\u00f3n<\/strong>\u00a0para modificar el art\u00edculo 40, relacionado con la soberan\u00eda nacional, y el 19, que tiene que ver con delitos de prisi\u00f3n preventiva oficiosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sheinbaum<\/strong>\u00a0reafirm\u00f3 que\u00a0<strong>M\u00e9xico<\/strong>\u00a0y\u00a0Estados Unidos\u00a0buscan disminuir el consumo y tr\u00e1fico de drogas ilegales, disminuir los \u00edndices de violencia y combatir grupos de\u00a0<strong>delincuencia organizada,<\/strong>\u00a0pero debe ser en colaboraci\u00f3n, coordinaci\u00f3n y\u00a0<strong>respetando la soberan\u00eda mexicana<\/strong>.<br>\u201cCon<strong>\u00a0M\u00e9xico<\/strong>\u00a0es colaboraci\u00f3n y coordinaci\u00f3n, no injerencismo y menos invasi\u00f3n\u201d reiter\u00f3 la dirigente luego que hoy se oficializ\u00f3 en la\u00a0<strong>Uni\u00f3n Americana<\/strong>\u00a0el considerar como grupos terroristas a carteles del narcotr\u00e1fico que operan en M\u00e9xico y surten\u00a0<strong>la demanda de drogas a consumidores estadunidenses<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Modificaciones constitucionales en los art\u00edculos 40 y 19<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con&nbsp;<strong>Sheinbaum<\/strong>, las modificaciones se deben a medidas del gobierno mexicano para salvaguardar la soberan\u00eda nacional y evitar invasi\u00f3n extranjera al pa\u00eds, que podr\u00eda suceder ahora bajo la idea de concebir como&nbsp;<strong>terrorismo a ciertos carteles del pa\u00eds<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Articulo 40<\/strong><br>El pueblo mexicano no aceptar\u00e1 intervenciones, intromisiones o cualquier otro acto del extranjero que viole la soberan\u00eda del Estado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No se permitir\u00e1n golpes de estado, injerencia en elecciones o violaci\u00f3n del territorio mexicano ya sea por mar, tierra o espacio a\u00e9reo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tampoco se consentir\u00e1 intervenci\u00f3n en investigaci\u00f3n o persecuci\u00f3n sin autorizaci\u00f3n de\u00a0<strong>M\u00e9xico<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Articulo 19&nbsp;<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ofrece prisi\u00f3n oficiosa y pena m\u00e1xima para cualquier nacional o extranjero involucrado en la fabricaci\u00f3n, traslado o tr\u00e1fico de armas<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estados Unidos declara como terroristas a Carteles mexicanos<\/strong><br>El gobierno de\u00a0<strong>Estados unidos<\/strong>\u00a0design\u00f3 oficialmente hoy a\u00a0seis carteles mexicanos como terroristas, entre ellos el de\u00a0<strong>Sinaloa<\/strong>\u00a0y el\u00a0<strong>Jalisco Nueva Generaci\u00f3n<\/strong>\u00a0(<strong>CJNG<\/strong>), adem\u00e1s de la banda venezolana del\u00a0<strong>Tren de Aragua<\/strong>\u00a0y la pandilla\u00a0<strong>Mara Salvatrucha<\/strong>(<strong>MS-13<\/strong>)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior porque los&nbsp;<strong>c\u00e1rteles mexicanos<\/strong>, de acuerdo con la actual administraci\u00f3n estadunidense, ponen en riesgo la seguridad nacional, la pol\u00edtica exterior y&nbsp;<strong>los intereses econ\u00f3micos de aquel pa\u00eds<\/strong>.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para proteger la&nbsp;soberan\u00eda nacional&nbsp;y evitar la injerencia de&nbsp;Estados Unidos&nbsp;en territorio mexicano,&nbsp;la actual administraci\u00f3n federal enviar\u00e1 reformas a la&nbsp;Constituci\u00f3n Pol\u00edtica&nbsp;del pa\u00eds para modificar los art\u00edculos 40 y 19. La presidenta de\u00a0M\u00e9xico,\u00a0Claudia Sheinbaum Pardo, present\u00f3 hoy una\u00a0reforma constitucional\u00a0que enviar\u00e1 al\u00a0Congreso de la Uni\u00f3n\u00a0para modificar el art\u00edculo 40, relacionado con la soberan\u00eda nacional, y el 19, que tiene [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":58894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[176],"tags":[],"class_list":["post-58893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/58893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=58893"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/58893\/revisions"}],"predecessor-version":[{"id":58895,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/58893\/revisions\/58895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/58894"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=58893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=58893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=58893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}