{"id":56892,"date":"2024-12-12T14:41:39","date_gmt":"2024-12-12T14:41:39","guid":{"rendered":"https:\/\/lahora.mx\/?p=56892"},"modified":"2024-12-31T14:43:04","modified_gmt":"2024-12-31T14:43:04","slug":"rinden-informe-consejos-de-docencia-e-investigacion-y-estudios-de-posgrado","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/12\/12\/rinden-informe-consejos-de-docencia-e-investigacion-y-estudios-de-posgrado\/","title":{"rendered":"Rinden informe Consejos de Docencia e Investigaci\u00f3n y Estudios de Posgrado"},"content":{"rendered":"\n<p>En apego a lo que marca la legislaci\u00f3n universitaria, los consejos de Docencia e Investigaci\u00f3n y Estudios de Posgrado rindieron sus informes de actividades de la gesti\u00f3n 2024, ante la Rectora Lilia Cedillo Ram\u00edrez y los integrantes de estos \u00f3rganos, los cuales son garantes del cumplimiento de actividades fundamentales para la instituci\u00f3n, as\u00ed como del cumplimiento de los ejes que dicta el Plan de Desarrollo Institucional.<\/p>\n\n\n\n<p>Instaurados como \u00f3rganos intermedios de autoridad acad\u00e9mica colegiada entre el Consejo Universitario y la Rectora, as\u00ed como autoridades acad\u00e9micas, su funci\u00f3n es llevar a cabo la planeaci\u00f3n y evaluaci\u00f3n de \u00e1reas sustantivas como la docencia, la investigaci\u00f3n y los planes de estudios de posgrado, as\u00ed como su actualizaci\u00f3n.<\/p>\n\n\n\n<p>Investigaci\u00f3n y Posgrado<\/p>\n\n\n\n<p>Tras escuchar el informe del Consejo de Investigaci\u00f3n y Estudios de Posgrado, por parte del vicerrector Ygnacio Mart\u00ednez Laguna, la Rectora Lilia Cedillo reconoci\u00f3 que el trabajo que desempe\u00f1an se refleja en las sesiones del Honorable Consejo Universitario, donde presentan y aprueban proyectos que confieren a esta casa de estudios un prestigio derivado de la calidad de sus posgrados.&nbsp;<\/p>\n\n\n\n<p>\u201cUstedes vigilan la calidad acad\u00e9mica que deben tener los programas de posgrado, porque \u00e9se es un distintivo de la BUAP. Agradezco el escrutinio y rigor con el que revisan estos proyectos para garantizar su \u00e9xito, pertinencia y factibilidad\u201d.<\/p>\n\n\n\n<p>Durante el informe, el vicerrector Ygnacio Mart\u00ednez Laguna dio cuenta de cuatro aspectos fundamentales: la gesti\u00f3n y el financiamiento que apoya la investigaci\u00f3n; la difusi\u00f3n y divulgaci\u00f3n cient\u00edfica; la generaci\u00f3n de recursos alternos por servicios acad\u00e9micos y de innovaci\u00f3n; y los posgrados, tanto de nueva creaci\u00f3n como el proyecto de actualizaci\u00f3n.<\/p>\n\n\n\n<p>Mart\u00ednez Laguna inform\u00f3 que la BUAP cuenta con 955 miembros del Sistema Nacional de Investigadores, lo que representa 16 por ciento m\u00e1s con relaci\u00f3n a la gesti\u00f3n anterior, de los cuales 15 son em\u00e9ritos. Asimismo, mil 37 son miembros activos del Padr\u00f3n Institucional de Investigadores. De igual forma, se brind\u00f3 apoyo a 288 proyectos de investigaci\u00f3n, cifra 8 por ciento superior a 2023.<\/p>\n\n\n\n<p>Otros logros mencionados fueron la alianza con el Instituto Polit\u00e9cnico Nacional con quien se pactaron cinco proyectos de investigaci\u00f3n. En materia de movilidad se increment\u00f3 el apoyo un 500 por ciento. Adem\u00e1s de inscribieron 25 solicitudes de patente y se obtuvieron 17 t\u00edtulos en el mismo sentido.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Destac\u00f3 la aprobaci\u00f3n de nuevos posgrados, as\u00ed como un proyecto de actualizaci\u00f3n para adaptarlos al entorno cambiante y adecuarlos a las nuevas realidades. Tambi\u00e9n se refiri\u00f3 al trabajo desarrollado en materia de divulgaci\u00f3n cient\u00edfica con programas como Ciencia a Bordo, entre otras acciones.&nbsp;<\/p>\n\n\n\n<p>Docencia&nbsp;<\/p>\n\n\n\n<p>Por otra parte, en sesi\u00f3n por separado del Consejo de Docencia, la Rectora Mar\u00eda Lilia Cedillo Ram\u00edrez reconoci\u00f3 el trabajo de los integrantes de este \u00f3rgano colegiado, quienes discuten y analizan los nuevos programas acad\u00e9micos, su factibilidad, y la adecuaci\u00f3n de la malla curricular acorde al proyecto de la Nueva Escuela Mexicana.<\/p>\n\n\n\n<p>\u00abSu trabajo colegiado permite adecuar las mallas curriculares de los planes de estudio, de acuerdo con las necesidades de la instituci\u00f3n. Por eso agradezco su labor, porque a trav\u00e9s de \u00e9sta avanzamos\u00bb. Tambi\u00e9n, la Rectora Cedillo dio a conocer las acciones institucionales para ofertar nuevas plazas acad\u00e9micas por medio de concurso y reconocer la dedicaci\u00f3n de los profesores hora-clase con el otorgamiento de un bono econ\u00f3mico.<\/p>\n\n\n\n<p>En la \u00faltima sesi\u00f3n ordinaria del a\u00f1o, el vicerrector de Docencia, Jos\u00e9 Jaime V\u00e1zquez L\u00f3pez, inform\u00f3 los acuerdos generados por este consejo para el fortalecimiento acad\u00e9mico, calidad educativa y mejora continua de la instituci\u00f3n en 2024.<\/p>\n\n\n\n<p>Entre los eventos destacados mencion\u00f3 el redise\u00f1o curricular del plan de estudio del Bachillerato 5 de Mayo, la creaci\u00f3n de nuevos planes de estudio del nivel superior y el redise\u00f1o curricular de 29 planes m\u00e1s.<\/p>\n\n\n\n<p>V\u00e1zquez L\u00f3pez anunci\u00f3 que para el pr\u00f3ximo a\u00f1o se trabajar\u00e1 en el fortalecimiento de Ciudad Universitaria 2 y se ofrecer\u00e1n nueve nuevos programas educativos en las \u00e1reas de Ingenier\u00eda y Ciencias Agropecuarias en los complejos regionales Centro y Nororiental, as\u00ed como en el nivel medio superior, espec\u00edficamente con la creaci\u00f3n de nuevos bachilleratos tecnol\u00f3gicos en la ciudad de Puebla y la posibilidad de un nuevo bachillerato general.<\/p>\n\n\n\n<p>Asimismo, en el Consejo de Docencia se presentaron las propuestas de mallas curriculares del Bachillerato General Universitario y del Bachillerato Tecnol\u00f3gico, con el fin de adecuarlo a los lineamientos de la Nueva Escuela Mexicana, modificaciones sustantivas en este nivel acad\u00e9mico en beneficio de los estudiantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En apego a lo que marca la legislaci\u00f3n universitaria, los consejos de Docencia e Investigaci\u00f3n y Estudios de Posgrado rindieron sus informes de actividades de la gesti\u00f3n 2024, ante la Rectora Lilia Cedillo Ram\u00edrez y los integrantes de estos \u00f3rganos, los cuales son garantes del cumplimiento de actividades fundamentales para la instituci\u00f3n, as\u00ed como del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":56893,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[186,223],"class_list":["post-56892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-buap","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/56892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=56892"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/56892\/revisions"}],"predecessor-version":[{"id":56894,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/56892\/revisions\/56894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/56893"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=56892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=56892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=56892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}