{"id":56208,"date":"2024-12-12T17:01:33","date_gmt":"2024-12-12T17:01:33","guid":{"rendered":"https:\/\/lahora.mx\/?p=56208"},"modified":"2024-12-12T17:01:34","modified_gmt":"2024-12-12T17:01:34","slug":"aprueban-presupuesto-de-egresos-2025-el-mas-alto-en-la-historia-de-mexico","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/12\/12\/aprueban-presupuesto-de-egresos-2025-el-mas-alto-en-la-historia-de-mexico\/","title":{"rendered":"Aprueban Presupuesto de Egresos 2025, el m\u00e1s alto en la historia de M\u00e9xico"},"content":{"rendered":"\n<p>Fueron 9 billones 302 mil 015 millones de pesos los que se aprobaron por mayor\u00eda en la C\u00e1mara de Diputados la madrugada de hoy como Presupuesto de Egresos de la Federaci\u00f3n 2025; el monto m\u00e1s alto en la historia del pa\u00eds.<\/p>\n\n\n\n<p>Con 353 votos a favor y 128 en contra, mayor\u00eda de Morena y aliados, se aprob\u00f3 el gasto federal para el pr\u00f3ximo a\u00f1o que tiene un incremento de 235 mil 970 millones respecto a presupuesto del a\u00f1o pasado.<\/p>\n\n\n\n<p>El Presupuesto de Egresos de la Federaci\u00f3n 2025 tuvo varios recortes contra organismos aut\u00f3nomos y \u00f3rganos de los Poderes de la Uni\u00f3n. Ese dinero, se\u00f1al\u00f3 la bancada oficialista, se destinar\u00e1 a programas sociales.<\/p>\n\n\n\n<p>Reducci\u00f3n de presupuesto a organismos aut\u00f3nomos va a bienestar social: Morena<br>Tras 13 horas de debate, los legisladores avalaron recortes por 30 mil 220 millones de pesos a organismos aut\u00f3nomos, incluyendo 14 mil 042 millones al Poder Judicial y 13 mil 476 millones al Instituto Nacional Electoral (INE), entre otros.<\/p>\n\n\n\n<p>Diputados oficialistas aseguraron que los recursos se reasignar\u00e1n a educaci\u00f3n, salud e infraestructura; \u201cEl presupuesto tiene rostro humano, combate la desigualdad y fortalece programas sociales\u201d, asegur\u00f3 la diputada Merilyn G\u00f3mez Pozos, de Morena.<\/p>\n\n\n\n<p>Miembros de la oposici\u00f3n criticaron los recortes al Presupuesto de Egresos de la Federaci\u00f3n 2025. Se\u00f1alaron que los megaproyectos del gobierno federal absorber\u00edan recursos que deber\u00edan dirigirse a sectores prioritarios.<\/p>\n\n\n\n<p>Entre los ajustes destacan ampliaciones al ramo educativo por 14 mil 984 millones de pesos y un incremento de 10 mil 720 millones a infraestructura, con \u00e9nfasis en caminos rurales y modernizaci\u00f3n.<\/p>\n\n\n\n<p>Tras la aprobaci\u00f3n, el presidente de la C\u00e1mara Baja, Sergio Guti\u00e9rrez Luna, inform\u00f3 que el decreto se enviar\u00e1 al Ejecutivo Federal para su promulgaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fueron 9 billones 302 mil 015 millones de pesos los que se aprobaron por mayor\u00eda en la C\u00e1mara de Diputados la madrugada de hoy como Presupuesto de Egresos de la Federaci\u00f3n 2025; el monto m\u00e1s alto en la historia del pa\u00eds. Con 353 votos a favor y 128 en contra, mayor\u00eda de Morena y aliados, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":56209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[176],"tags":[195],"class_list":["post-56208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-principal"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/56208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=56208"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/56208\/revisions"}],"predecessor-version":[{"id":56210,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/56208\/revisions\/56210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/56209"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=56208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=56208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=56208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}