{"id":56075,"date":"2024-12-09T03:05:15","date_gmt":"2024-12-09T03:05:15","guid":{"rendered":"http:\/\/lahora.mx\/?p=56075"},"modified":"2024-12-09T03:05:16","modified_gmt":"2024-12-09T03:05:16","slug":"el-presidente-electo-trump-confirma-deportaciones-recorte-a-ucrania-y-duda-sobre-otan","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/12\/09\/el-presidente-electo-trump-confirma-deportaciones-recorte-a-ucrania-y-duda-sobre-otan\/","title":{"rendered":"El presidente electo Trump confirma deportaciones, recorte a Ucrania y duda sobre OTAN"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente electo de Estados Unidos, Donald Trump, reiter\u00f3 este domingo sus promesas de campa\u00f1a de llevar a cabo deportaciones masivas de inmigrantes indocumentados e imponer aranceles, al tiempo que insinu\u00f3 que su pa\u00eds podr\u00eda retirarse de la OTAN.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su primera entrevista formal en televisi\u00f3n, seis semanas antes de su toma de posesi\u00f3n, el magnate republicano ratific\u00f3 que proceder\u00e1 a una deportaci\u00f3n masiva de inmigrantes indocumentados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Creo que hay que hacerlo. Es algo dif\u00edcil, es algo muy dif\u00edcil de hacer. Pero hay que tener normas, reglamentos, leyes. Entraron ilegalmente\u00bb, afirm\u00f3 en el programa \u00abMeet the Press with Kristen Welker\u00bb, de la cadena NBC.<br>Dijo tambi\u00e9n que pondr\u00eda fin al derecho constitucionalmente protegido a la ciudadan\u00eda estadounidense para cualquier persona nacida en el pa\u00eds, un derecho que calific\u00f3 de \u00abrid\u00edculo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si podemos, lo haremos a trav\u00e9s de la acci\u00f3n ejecutiva\u00bb, se\u00f1al\u00f3 para referirse a la manera en que llevar\u00eda a cabo esa medida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos a tener que cambiar\u00bb ese derecho, insisti\u00f3. \u00abQuiz\u00e1 tengamos que volver al pueblo. Pero tenemos que acabar con ello\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confirm\u00f3 por otra parte que el apoyo de su pa\u00eds a Ucrania, enfrentada militarmente a Rusia desde 2022, \u00abprobablemente\u00bb se reducir\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La entrevista fue grabada el viernes pero se emiti\u00f3 el domingo, tras las reuniones de Trump en Par\u00eds con los presidentes de Francia y Ucrania durante el fin de semana, su primer viaje al extranjero desde que gan\u00f3 las elecciones de noviembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trump volver\u00e1 a la Casa Blanca el pr\u00f3ximo 20 de enero.<br>OTAN en duda y aumento de aranceles<br>Trump reiter\u00f3 su conocida amenaza de abandonar la OTAN, la piedra angular de la seguridad en Europa desde la Segunda Guerra Mundial, diciendo que los aliados de Estados Unidos no pagan lo suficiente por su defensa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si est\u00e1n pagando sus cuentas, y si creo que nos est\u00e1n tratando de manera justa, la respuesta es absolutamente que me quedar\u00eda en la OTAN\u00bb, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero tambi\u00e9n existe \u00ababsolutamente\u00bb la posibilidad de que si esas dos condiciones no se cumplen, Washington se retire de la alianza atl\u00e1ntica, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manifest\u00f3 igualmente que cumplir\u00e1 con sus promesas electorales de imponer fuertes aranceles, incluso a los principales sociales comerciales del pa\u00eds, como Canad\u00e1, M\u00e9xico y China.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estamos subvencionando a M\u00e9xico, a Canad\u00e1 y a muchos pa\u00edses de todo el mundo\u00bb, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien utilizados\u00bb, los aranceles son \u00abuna herramienta muy poderosa\u00bb, coment\u00f3, y agreg\u00f3 que echar\u00e1 mano a ellos \u00abtambi\u00e9n para conseguir cosas fuera de la econom\u00eda\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a si el aumento de los aranceles repercutir\u00e1 o no en los precios al consumo en su pa\u00eds, dijo no poder \u00abgarantizar\u00bb nada. \u00abNo puedo garantizar lo que suceder\u00e1 ma\u00f1ana\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El magnate republicano sostuvo por otro lado que estudiar\u00e1 \u00abmuy r\u00e1pidamente\u00bb la posibilidad de indultar a sus partidarios encarcelados por asaltar el Capitolio tras su derrota en las elecciones de 2020 frente a Joe Biden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente electo de Estados Unidos, Donald Trump, reiter\u00f3 este domingo sus promesas de campa\u00f1a de llevar a cabo deportaciones masivas de inmigrantes indocumentados e imponer aranceles, al tiempo que insinu\u00f3 que su pa\u00eds podr\u00eda retirarse de la OTAN. En su primera entrevista formal en televisi\u00f3n, seis semanas antes de su toma de posesi\u00f3n, el [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":56077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[183],"tags":[],"class_list":["post-56075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/56075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=56075"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/56075\/revisions"}],"predecessor-version":[{"id":56078,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/56075\/revisions\/56078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/56077"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=56075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=56075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=56075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}