{"id":54461,"date":"2024-11-03T17:47:25","date_gmt":"2024-11-03T17:47:25","guid":{"rendered":"http:\/\/lahora.mx\/?p=54461"},"modified":"2024-11-03T17:47:25","modified_gmt":"2024-11-03T17:47:25","slug":"conagua-advierte-llegada-del-frente-frio-7","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/11\/03\/conagua-advierte-llegada-del-frente-frio-7\/","title":{"rendered":"Conagua advierte llegada del Frente Fr\u00edo 7"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Fuertes lluvias e intensas rachas de viento se han pronosticado para los estados en los que impactar\u00e1 el frente fr\u00edo n\u00famero 7. En algunos casos, tambi\u00e9n podr\u00eda haber altos oleajes, descensos en la temperatura, abundante nubosidad, heladas e incluso nevadas. Ante esta situaci\u00f3n, es necesario extremar precauciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este domingo 3 de noviembre, la Comisi\u00f3n Nacional del Agua (Conagua) lanz\u00f3 un comunicado en el que precis\u00f3 que igual llegar\u00e1n otros sistemas al pa\u00eds que podr\u00edan traer consecuencias similares, como la onda tropical n\u00famero 30, el ingreso de humedad desde el golfo de M\u00e9xico, un canal de baja presi\u00f3n, as\u00ed como otros factores similares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se exhort\u00f3 a la poblaci\u00f3n en general a estar al pendiente de las indicaciones de las autoridades, como las redes sociales de la Conagua o de Protecci\u00f3n Civil, en donde podr\u00edan dar m\u00e1s informaci\u00f3n sobre las condiciones clim\u00e1ticas, al igual que cualquier otro detalle que se considere pertinente. A continuaci\u00f3n te diremos c\u00f3mo ser\u00e1 el ambiente en Puebla.<br>El frente fr\u00edo 7 afectar\u00e1 a Puebla?<br>La Conagua precis\u00f3 que por el momento este sistema solo afectar\u00e1 a las entidades que se encuentran al noreste y norte de M\u00e9xico, como Sonora o Chihuahua, en donde podr\u00eda haber vientos que vayan de 80 a 100 kil\u00f3metros por hora (km\/h), al igual que lluvias puntuales muy fuertes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, en Puebla no se detendr\u00e1 la ca\u00edda de agua, pues es probable que haya intervalos de chubascos en distintos puntos de la entidad, lo que quiere decir que podr\u00eda haber lluvias de forma intermitente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es probable que estas precipitaciones aparezcan de ligera intensidad y que se presente en la Angel\u00f3polis, es decir, en la ciudad de Puebla y en puntos aleda\u00f1os, como en algunos municipios que se encuentran dentro de la zona conurbada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (PC) puntualiz\u00f3 que tambi\u00e9n podr\u00eda haber precipitaciones en las comunidades que se encuentra en Atlixco y Valles Centrales, as\u00ed como en las Sierras Norte, Nororiental y Negra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fuertes lluvias e intensas rachas de viento se han pronosticado para los estados en los que impactar\u00e1 el frente fr\u00edo n\u00famero 7. En algunos casos, tambi\u00e9n podr\u00eda haber altos oleajes, descensos en la temperatura, abundante nubosidad, heladas e incluso nevadas. Ante esta situaci\u00f3n, es necesario extremar precauciones. Este domingo 3 de noviembre, la Comisi\u00f3n Nacional [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":54462,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[223],"class_list":["post-54461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/54461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=54461"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/54461\/revisions"}],"predecessor-version":[{"id":54463,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/54461\/revisions\/54463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/54462"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=54461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=54461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=54461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}