{"id":54297,"date":"2024-10-30T00:01:21","date_gmt":"2024-10-30T00:01:21","guid":{"rendered":"http:\/\/lahora.mx\/?p=54297"},"modified":"2024-10-30T00:01:21","modified_gmt":"2024-10-30T00:01:21","slug":"buap-da-banderazo-de-salida-a-20-toneladas-de-viveres-para-damnificados-de-guerrero","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/10\/30\/buap-da-banderazo-de-salida-a-20-toneladas-de-viveres-para-damnificados-de-guerrero\/","title":{"rendered":"BUAP da banderazo de salida a 20 toneladas de v\u00edveres para damnificados de Guerrero"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Con 20 toneladas de alimento, as\u00ed como insumos y art\u00edculos de aseo personal, la comunidad universitaria y la sociedad poblana nuevamente se unieron para apoyar a los damnificados de Guerrero, por el paso de los huracanes Otis y John, en Acapulco. En coordinaci\u00f3n con la Universidad Aut\u00f3noma de Guerrero, los v\u00edveres partieron este martes de Ciudad Universitaria rumbo a Chilpancingo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al dar el banderazo de salida, en esta tercera entrega realizada por la BUAP, la Rectora Mar\u00eda Lilia Cedillo Ram\u00edrez agradeci\u00f3 la solidaridad de la comunidad universitaria y de la poblaci\u00f3n en general, pero en especial de los complejos regionales de la instituci\u00f3n, por sumarse a esta campa\u00f1a en beneficio de las personas afectadas por las inundaciones que dejaron estos ciclones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mencion\u00f3 que hace unos d\u00edas el rector de la Universidad Aut\u00f3noma de Guerrero le comparti\u00f3 im\u00e1genes sobre las labores que realizan con los ciudadanos que han sufrido m\u00e1s p\u00e9rdidas con estos fen\u00f3menos meteorol\u00f3gicos, a quienes se les han entregado alimentos preparados y despensas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAdem\u00e1s de los trabajos de limpieza en sus instalaciones, los estudiantes de esta universidad hermana ayudaron en escuelas primarias y secundarias para tenerlas listas para la reincorporaci\u00f3n a las clases. Tambi\u00e9n establecieron un albergue y un comedor, para las personas que perdieron sus hogares; y all\u00ed es donde precisamente los v\u00edveres recaudados llegar\u00e1n. Tengan la seguridad de que todo lo que se recolect\u00f3 se entregar\u00e1 a manos necesitadas. Somos uno solo y cuando un hermano cae en desgracia, ah\u00ed estamos los universitarios para apoyar\u201d, expres\u00f3 la Rectora de la BUAP.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este banderazo de salida estuvo presente el organizador de la colecta, el coordinador General de Atenci\u00f3n a los Universitarios, Jorge Avelino Sol\u00eds. Adem\u00e1s, funcionarios y directores de unidades acad\u00e9micas y dependencias administrativas, quienes tambi\u00e9n participaron en la donaci\u00f3n de alimentos no perecederos, art\u00edculos de limpieza, frazadas, pa\u00f1ales y agua, entre otros productos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">BUAP da banderazo de salida a 20 toneladas de v\u00edveres para damnificados de Guerrero<br>Jorge Avelino Sol\u00eds agradeci\u00f3 a quienes coordinaron la recepci\u00f3n de art\u00edculos, alimentos y productos en las sedes del Complejo Cultural Universitario, el Hospital Universitario de Puebla, el Centro de Convenciones de CU, el Ema 7 de CU2 y el Edificio Carolino. Reconoci\u00f3 tambi\u00e9n el entusiasmo de los complejos regionales, en especial del Nororiental que recab\u00f3 cinco toneladas de v\u00edveres que llegar\u00e1n a quienes m\u00e1s lo necesitan.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con 20 toneladas de alimento, as\u00ed como insumos y art\u00edculos de aseo personal, la comunidad universitaria y la sociedad poblana nuevamente se unieron para apoyar a los damnificados de Guerrero, por el paso de los huracanes Otis y John, en Acapulco. En coordinaci\u00f3n con la Universidad Aut\u00f3noma de Guerrero, los v\u00edveres partieron este martes de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":54298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[186,223],"class_list":["post-54297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-buap","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/54297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=54297"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/54297\/revisions"}],"predecessor-version":[{"id":54299,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/54297\/revisions\/54299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/54298"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=54297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=54297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=54297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}