{"id":52427,"date":"2024-09-24T18:24:44","date_gmt":"2024-09-24T18:24:44","guid":{"rendered":"http:\/\/lahora.mx\/?p=52427"},"modified":"2024-09-24T18:24:45","modified_gmt":"2024-09-24T18:24:45","slug":"por-mantenimiento-agua-de-puebla-desfasa-el-servicio-en-64-colonias-por-mantenimiento","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/09\/24\/por-mantenimiento-agua-de-puebla-desfasa-el-servicio-en-64-colonias-por-mantenimiento\/","title":{"rendered":"Por mantenimiento Agua de Puebla  desfasa el servicio en 64 colonias por mantenimiento"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Con el fin de mejorar el suministro de agua potable en tres de los sectores m\u00e1s importantes de la red, Agua de Puebla para Todos realizar\u00e1 trabajos de mantenimiento, modernizaci\u00f3n y conexi\u00f3n de las l\u00edneas de conducci\u00f3n renovadas hacia los tanques de almacenamiento La Constancia, Desarenador y Cerro del Marqu\u00e9s, as\u00ed como la instalaci\u00f3n de instrumentaci\u00f3n, renovaci\u00f3n de equipos de bombeo, de medici\u00f3n y v\u00e1lvulas de control para su automatizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agua de Puebla desfasa servicio en 64 colonias por mantenimiento<br>Dar\u00e1 mantenimiento mayor a las Plantas Potabilizadoras de Agua Sulfurosa Jint y San Felipe, para garantizar una producci\u00f3n mensual de 630 millones de litros de agua de calidad. Estas labores se realizar\u00e1n a partir de las 00:00 horas del mi\u00e9rcoles 25 de septiembre y concluir\u00e1n a las 08:00 horas del jueves 26 de septiembre del presente a\u00f1o, lo que implicar\u00e1 la suspensi\u00f3n temporal de la operaci\u00f3n de las 2 plantas potabilizadoras, 16 pozos, 5 tanques y rebombeos del Sistema Acuaf\u00e9rico, por lo que se ver\u00e1 desfasado el abasto de agua en 64 colonias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conjunto hab. La Guadalupana<br>Playas del Sur<br>Loma Linda<br>Lomas San Miguel<br>Lomas Flor del Bosque<br>Balcones del Sur<br>Ampliaci\u00f3n Reforma<br>Reforma Sur (La Libertad)<br>Tres Cruces<br>Galaxia la Calera (fraccionamiento)<br>Residencial Lomas del \u00c1ngel<br>Hacienda de Manzanilla (fraccionamiento)<br>Villa Encantada<br>Lagulena<br>Arboledas de Guadalupe<br>Ampliaci\u00f3n balcones del Sur<br>Conjunto Sat\u00e9lite, amp. Vista Hermosa \u00c1lamos<br>Jardines del Sur<br>Viveros del Valle<br>Los \u00c1ngeles Mayorazgo<br>San Baltazar Lindavista<br>Tliloxtoc<br>Fraternidad Antorchista<br>Universidades<br>Patrimonio<br>San Juan Bautista<br>Lomas de Loreto<br>Veracruz<br>H\u00e9roes 5 de Mayo Sur<br>Unidad hab. BUAP<br>El Encinar<br>Conjunto hab. Paseos de la Arboleda<br>Conjunto hab. Juan Pablo ii<br>Unidad hab. Hacienda San Jos\u00e9 y Hacienda San Jos\u00e9 3ra secc.<br>Loma Bonita Sur<br>San Jos\u00e9 Chapulco<br>Unidad hab. Chapulco<br>Universitaria<br>Bosques de Santa Anita<br>San Crist\u00f3bal Tulcingo (caleras)<br>Jardines de la Resurrecci\u00f3n<br>Ampliaci\u00f3n Fraternidad Antorchista<br>Loma Encantada<br>S. A. R. H. Xilotzingo (fraccionamiento)<br>Huixcolotera<br>El encinar 2da. Secci\u00f3n<br>Casa Blanca<br>8 de Diciembre<br>Conjunto hab. Villas Perisur<br>El Pinal, conjunto hab. Esmeralda<br>Molino de Enmedio<br>Caba\u00f1as del Lago<br>\u00c1lamos Vista Hermosa<br>Los Rosales 2da. Secci\u00f3n<br>Casa Blanca sector (Para\u00edso)<br>Las Playas<br>Conjunto hab. Villas Manzanilla<br>Conjunto hab. Villas el Ensue\u00f1o<br>Bosques de Atoyac<br>Malintzi<br>Las Chinampas<br>Bosques de los \u00c1ngeles<br>Valle de An\u00e1huac<br>Noche Buena<br>Agua de Puebla desfasa servicio en 64 colonias por mantenimiento<br>Una vez finalizados los trabajos, se reactivar\u00e1 la operaci\u00f3n de los pozos, plantas, rebombeos, tanques y el llenado de l\u00edneas para restablecer el abasto de agua conforme al calendario y su horario normal de servicio en cada colonia, por lo que solicitamos la comprensi\u00f3n de los usuarios durante las labores y recomendamos tomar medidas de prevenci\u00f3n durante ese lapso como el almacenamiento y un uso responsable del agua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el fin de mejorar el suministro de agua potable en tres de los sectores m\u00e1s importantes de la red, Agua de Puebla para Todos realizar\u00e1 trabajos de mantenimiento, modernizaci\u00f3n y conexi\u00f3n de las l\u00edneas de conducci\u00f3n renovadas hacia los tanques de almacenamiento La Constancia, Desarenador y Cerro del Marqu\u00e9s, as\u00ed como la instalaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":52428,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[239,195,223],"class_list":["post-52427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-gobierno","tag-principal","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/52427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=52427"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/52427\/revisions"}],"predecessor-version":[{"id":52429,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/52427\/revisions\/52429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/52428"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=52427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=52427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=52427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}