{"id":51909,"date":"2024-09-11T02:14:56","date_gmt":"2024-09-11T02:14:56","guid":{"rendered":"http:\/\/lahora.mx\/?p=51909"},"modified":"2024-09-11T02:14:57","modified_gmt":"2024-09-11T02:14:57","slug":"se-reanuda-la-discusion-sobre-la-reforma-al-poder-judicial-en-sede-alterna-del-senado","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/09\/11\/se-reanuda-la-discusion-sobre-la-reforma-al-poder-judicial-en-sede-alterna-del-senado\/","title":{"rendered":"Se reanuda la discusi\u00f3n sobre la reforma al Poder Judicial en sede alterna del Senado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Apenas el pasado 8 de septiembre, las comisiones de Puntos Constitucionales y Estudios Legislativos de la C\u00e1mara Alta analizaron y aprobaron con 25 votos a favor y 12 en contra la iniciativa de reforma al Poder Judicial. Por esa raz\u00f3n comenzar\u00e1 su an\u00e1lisis en el pleno y su posible votaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La semana pasada la iniciativa fue aprobada en lo general y en lo particular por la C\u00e1mara de Diputados en una sesi\u00f3n que dur\u00f3 m\u00e1s de 15 horas y tuvo que realizarse en una sede alterna debido a las protestas de trabajadores y estudiantes en San L\u00e1zaro, quienes buscaban impedir la discusi\u00f3n de esta iniciativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noro\u00f1a informa que Luis Donaldo Colosio fue agredido afuera del Senado<br>Durante la sesi\u00f3n, Fern\u00e1ndez Noro\u00f1a hizo del conocimiento del resto de los senadores que el legislador de Movimiento Ciudadano, Luis Donaldo Colosio Riojas fue agredido con gasolina en los ojos frente a la sede de Reforma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAnte estos hechos lamentables, esta presidencia condena este tipo de eventos y le pide a las autoridades competentes que resguarden el recinto y garanticen adecuadamente la seguridad de las y los senadores que asisten al mismo a efecto de que est\u00e9n en condiciones de desempe\u00f1ar adecuadamente el ejercicio de sus funciones\u201d, pidi\u00f3 Noro\u00f1a.<br>Miguel \u00c1ngel Yunes M\u00e1rquez se reincorpora a la discusi\u00f3n<br>Al reanudarse la sesi\u00f3n vespertina del Senado, Gerardo Fern\u00e1ndez Noro\u00f1a, presidente de la Mesa Directiva, anunci\u00f3 que el senador del PAN, Miguel \u00c1ngel Yunes M\u00e1rquez se reincorpora a sus funciones legislativas. Lo anterior, despu\u00e9s de que el legislador pidiera licencia por motivos de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El debate contin\u00faa en la antigua sede del Senado, ubicada en la casona de Xicot\u00e9ncatl, en el centro de la Ciudad de M\u00e9xico, luego de que manifestantes dieran \u2018portazo\u2019 en el recinto legislativo de Reforma. Debido a la irrupci\u00f3n, el presidente del Senado convoc\u00f3 a continuar la discusi\u00f3n en una sede alterna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Coparmex hace en\u00e9rgico llamado a los senadores a no desmantelar el Poder Judicial<br>La Coparmex hace en\u00e9rgico llamado a los senadores a no desmantelar el Poder Judicial<br>Levantan la sesi\u00f3n del Senado por ingreso de manifestantes contra la reforma judicial: \u2018Aqu\u00ed nos quedamos\u2019<br>Al grito de \u201caqu\u00ed nos quedamos\u201d, manifestantes en contra de la reforma judicial ingresaron a la sala de sesiones del Senado, donde se lleva a cabo la discusi\u00f3n este martes. La interrupci\u00f3n ocurri\u00f3 alrededor de las 16:30 horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al tomar el Pleno, manifestantes expresan: \u201cEl Poder Judicial no va a caer, no va a caer\u201d, \u201cEn d\u00f3nde est\u00e1n, en d\u00f3nde est\u00e1n, los senadores que nos iban a escuchar\u201d y \u201csomos abogados, no somos acarreados\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manifestantes interrumpieron la sesi\u00f3n del Senado donde era discutida la reforma judicial; se llam\u00f3 a un receso. (Senado)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante la toma del Senado, el presidente de la Mesa Directiva del Senado, Gerardo Fern\u00e1ndez Noro\u00f1a, inform\u00f3 que la discusi\u00f3n qued\u00f3 suspendida de manera indefinida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras los manifestantes gritan consignas, Noro\u00f1a intenta pedir a los senadores y senadoras que salgan del sal\u00f3n de sesiones, para resguardar su integridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los manifestantes tambi\u00e9n piden la presencia de Miguel \u00c1ngel Yunes M\u00e1rquez, senador que pidi\u00f3 licencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Senado El Senado ha sido tomado por manifestantes que est\u00e1n en contra de la reforma al Poder Judicial. (Senado)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la discusi\u00f3n de la reforma judicial en la C\u00e1mara de Diputados la semana pasada, trabajadores y estudiantes de Derecho \u2018tomaron\u2019 tambi\u00e9n las entradas del palacio legislativo de San L\u00e1zaro. Por ello, las y los diputados tuvieron que sesionar en una sede alterna, en la Magdalena Mixhuca, donde fue aprobado el dictamen y luego enviado al Senado. En el Deportivo elegido por los diputados, tambi\u00e9n hubo un portazo, pero se logr\u00f3 la aprobaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reforma judicial en el Senado: Miguel \u00c1ngel Yunes M\u00e1rquez pide licencia<br>Durante la sesi\u00f3n se dio a conocer que el senador Miguel \u00c1ngel Yunes M\u00e1rquez env\u00edo una solicitud al Senado para pedir licencia por tiempo indefinido argumentando problemas de salud, por lo que hizo un llamado a que se le tome protesta a su suplente. Con 83 votos a favor, 36 en contra y 0 abstenciones fue aprobada la solicitud de licencia por tiempo indefinido a partir de este martes 10 de septiembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, el presidente del Partido Acci\u00f3n Nacional (PAN), Marko Cort\u00e9s, reaccion\u00f3 a la decisi\u00f3n del veracruzano y acus\u00f3 que no le extra\u00f1aba debido a las intensas presiones a las cuales estuvo sometido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo lamento profundamente y soy el primero en llamarlo traidor porque est\u00e1 traicionado al pueblo de M\u00e9xico\u201d, agreg\u00f3 e hizo un llamado al suplente de Yunes M\u00e1rquez a votar en contra de la reforma al Poder Judicial: \u201cest\u00e1s a tiempo de ser un h\u00e9roe y no un traidor a la patria\u201d. Antes, el l\u00edder del PAN hab\u00eda amenazado con expulsar del partido a Miguel \u00c1ngel Yunes M\u00e1rquez; sin embargo, no mencion\u00f3 nada al respecto en su discurso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la aprobaci\u00f3n de la solicitud de licencia, Miguel \u00c1ngel Yunes Linares, padre y suplente del senador Yunes M\u00e1rquez, tom\u00f3 protesta en reemplazo del legislador entre protestas y gritos de los senadores. \u201cNi cobarde ni traidor, cobarde y traidor, eres t\u00fa (Marko Cort\u00e9s), no Miguel \u00c1ngel Yunes M\u00e1rquez, porque \u00e9l ha dado siempre la cara y a la familia Yunes nadie nos ha doblado\u201d, dijo como parte de su discurso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sigue la sesi\u00f3n del Senado Hoy martes 10 de septiembre EN VIVO<br>Tras leer la orden del d\u00eda, los senadores de Movimiento Ciudadano (MC) reportaron la supuesta detenci\u00f3n de Daniel Barreda y su padre en Campeche, por lo que hicieron un llamado para cancelar la sesi\u00f3n, pero Gerardo Fern\u00e1ndez Noro\u00f1a, presidente del Senado, neg\u00f3 la solicitud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El senador Ad\u00e1n Augusto asegur\u00f3 que habl\u00f3 con Daniel Barreda y descart\u00f3 que haya sido aprehendido. \u201cYo s\u00ed s\u00e9 d\u00f3nde est\u00e1 el senador Daniel Barreda porque acabo de hablar con \u00e9l (\u2026) Lo \u00fanico que me autoriz\u00f3 a que dijera es que est\u00e1 en la Ciudad de M\u00e9xico\u201d, agreg\u00f3. Ante estas declaraciones, el legislador de MC, Jos\u00e9 Clemente Casta\u00f1eda, hizo un llamado para mostrar evidencias de las afirmaciones hechas por el exsecretario de Gobernaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cUstedes saben que no cuentan con los votos para aprobar la reforma Constitucional y est\u00e1n presionando utilizando a las fiscal\u00edas de los estados para obtener a los votos que les faltan. Si tienen los votos, ganen a la buena, pero as\u00ed no. Hacemos un llamado a que se conduzcan con congruencia\u201d, dijo el senador del PAN, Ricardo Anaya, durante su participaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, el dirigente del PRI, Alejandro Moreno, denunci\u00f3 presiones del Instituto Nacional Electoral (INE) que rechaz\u00f3 los estatutos con los que se renov\u00f3 su dirigencia y asegur\u00f3 que esto es para que voten a favor de la reforma. \u201cVamos a votar en contra, no nos van a amedrentar\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de las 14:30 horas inici\u00f3 la discusi\u00f3n de la iniciativa de Reforma al Poder Judicial en el Pleno del Senado, con la exposici\u00f3n de la senadora Ernestina Godoy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta es la reforma m\u00e1s trascendente desde que se promulg\u00f3 la Constituci\u00f3n de 1917. Lo que va a quedar plasmado en la Constituci\u00f3n es la consecuencia de una iniciativa que busca que Morena tome por asalto al Poder Judicial\u201d, dijo Ricardo Anaya en su participaci\u00f3n para votar en contra de la reforma Judicial y enumer\u00f3 las \u2018trampas\u2019 que contiene la iniciativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 dice la reforma al Poder Judicial?<br>La reforma al Poder Judicial fue propuesta por el presidente Andr\u00e9s Manuel L\u00f3pez Obrador el pasado 5 de febrero y ha desatado protestas de trabajadores y estudiantes. Entre los motivos est\u00e1n que la iniciativa sugiere la votaci\u00f3n popular de jueces, magistrados y ministros de la Suprema Corte de Justicia de la Naci\u00f3n (SCJN) entre otras modificaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se menciona a los llamados \u2018jueces sin rostro\u2019 para ocultar la identidad de los juzgadores cuando los casos est\u00e9n relacionados con el narcotr\u00e1fico o crimen organizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, est\u00e1 la creaci\u00f3n de un \u00f3rgano independiente a la SCJN para formar el Tribunal de Disciplina Judicial para evaluar a los jueces, compuesto por 5 magistraturas elegidas tambi\u00e9n por voto popular. Por esa raz\u00f3n se eliminar\u00eda al Consejo de la Judicatura Federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta reforma tiene como fin que la sociedad tenga acceso a la justicia de manera pronta y expedita\u201d, explic\u00f3 la senadora Ernestina Godoy al exponer la iniciativa de reforma Judicial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 que el dictamen es el resultado de un \u2018ampl\u00edsimo\u2019 proceso de discusi\u00f3n y an\u00e1lisis en el que se hicieron m\u00e1s de 50 foros regionales en Congresos locales, plazas p\u00fablicas, donde participaron todos los grupos parlamentarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa fue enriquecida con m\u00e1s de 100 modificaciones realizadas a la propuesta original, seg\u00fan explic\u00f3 Godoy. Otro de los puntos establece que ning\u00fan juez, ministro o magistrado recibir\u00e1 un sueldo superior al del Presidente de la Rep\u00fablica; adem\u00e1s de respetar los derechos de los trabajadores del Poder Judicial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCon cu\u00e1ntos votos se aprueba la reforma al Poder Judicial?<br>El tema de los votos necesarios para la aprobaci\u00f3n o rechazo de la reforma al Poder Judicial tambi\u00e9n ha desatado una pol\u00e9mica debido a que Morena afirma tener la mayor\u00eda calificada, mientras que la oposici\u00f3n apuesta por mantenerse unida para lograr 43 votos en contra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gerardo Fern\u00e1ndez Noro\u00f1a, presidente del Senado, afirm\u00f3 que Morena necesitar\u00eda 85 votos y no 86, como se hab\u00eda mencionado en un principio, lo cual representar\u00eda las dos terceras partes de los senadores a favor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los legisladores de los partidos Revolucionario Institucional (PRI), Acci\u00f3n Nacional (PAN) y Movimiento Ciudadano (MC) denunciaron intimidaciones y presiones de Morena contra los senadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto los panistas como trabajadores del Poder Judicial, as\u00ed como la Asociaci\u00f3n Nacional de Magistrados de Circuito y Jueces de Distrito del Poder Judicial de la Federaci\u00f3n (Jufed) hicieron un llamado al senador Miguel \u00c1ngel Yunes M\u00e1rquez para que no cambie el sentido de su voto.<br>\u201cNo va a pasar, no va a pasar, la reforma judicial\u201d, fue el grito de cientos de manifestantes que protestaron en contra de la iniciativa presidencial por democratizar el Poder Judicial, mientras el nerviosismo e incertidumbre crece entre m\u00e1s se acerca el inicio de sesi\u00f3n ordinaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apenas el pasado 8 de septiembre, las comisiones de Puntos Constitucionales y Estudios Legislativos de la C\u00e1mara Alta analizaron y aprobaron con 25 votos a favor y 12 en contra la iniciativa de reforma al Poder Judicial. Por esa raz\u00f3n comenzar\u00e1 su an\u00e1lisis en el pleno y su posible votaci\u00f3n. La semana pasada la iniciativa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":51910,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[176],"tags":[],"class_list":["post-51909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/51909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=51909"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/51909\/revisions"}],"predecessor-version":[{"id":51911,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/51909\/revisions\/51911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/51910"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=51909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=51909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=51909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}