{"id":51614,"date":"2024-09-03T17:37:06","date_gmt":"2024-09-03T17:37:06","guid":{"rendered":"http:\/\/lahora.mx\/?p=51614"},"modified":"2024-09-03T17:37:07","modified_gmt":"2024-09-03T17:37:07","slug":"choque-de-ambulancia-en-calzada-zaragoza-cobra-su-segunda-victima","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/09\/03\/choque-de-ambulancia-en-calzada-zaragoza-cobra-su-segunda-victima\/","title":{"rendered":"Choque de ambulancia en Calzada Zaragoza cobra su segunda v\u00edctima"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La occisa fue identificada como Leslie N, de 28 a\u00f1os de edad, quien muri\u00f3 el lunes por la tarde en el Hospital Universitario, donde se encontraba internada desde el d\u00eda del accidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue el viernes pasado a las 23 horas cuando se registr\u00f3 el choque de la ambulancia contra la guarnici\u00f3n de concreto que protege un poste de la Comisi\u00f3n Federal de Electricidad, frente a las v\u00edas a la altura del Walmart.<br>En el veh\u00edculo viajaban tres personas: Leslie, quien conduc\u00eda; Rodrigo, de aproximadamente 30 a\u00f1os, quien iba como copiloto; y un tercer param\u00e9dico que viajaba en la parte de atr\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el impacto, los tres fueron llevados de emergencia al Hospital de Traumatolog\u00eda y Ortopedia del Sector Salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rodrigo, el copiloto, sufri\u00f3 las lesiones m\u00e1s graves debido a la posici\u00f3n que ocupaba en el momento del impacto. Lamentablemente, falleci\u00f3 el s\u00e1bado por la noche, 24 horas despu\u00e9s del accidente, a consecuencia de las heridas sufridas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tercer param\u00e9dico que viajaba en la parte trasera de la ambulancia sigue hospitalizado y en estado delicado, mientras que Leslie fue trasladada al Hospital Universitario debido a su v\u00ednculo laboral con este nosocomio, siendo trabajadora social all\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de los esfuerzos m\u00e9dicos, el estado de salud de Leslie empeor\u00f3 y falleci\u00f3 el lunes por la tarde, sum\u00e1ndose a la lista de fallecidos del tr\u00e1gico accidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El choque de la ambulancia sigue bajo investigaci\u00f3n de las autoridades con el fin de establecer la causa precisa del accidente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La occisa fue identificada como Leslie N, de 28 a\u00f1os de edad, quien muri\u00f3 el lunes por la tarde en el Hospital Universitario, donde se encontraba internada desde el d\u00eda del accidente. Fue el viernes pasado a las 23 horas cuando se registr\u00f3 el choque de la ambulancia contra la guarnici\u00f3n de concreto que protege [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":51615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-51614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/51614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=51614"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/51614\/revisions"}],"predecessor-version":[{"id":51616,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/51614\/revisions\/51616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/51615"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=51614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=51614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=51614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}