{"id":50623,"date":"2024-08-15T21:13:35","date_gmt":"2024-08-15T21:13:35","guid":{"rendered":"http:\/\/lahora.mx\/?p=50623"},"modified":"2024-08-15T21:13:35","modified_gmt":"2024-08-15T21:13:35","slug":"fiscalia-anticorrupcion-de-chihuahua-declara-profugo-de-la-justicia-a-javier-corral","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/08\/15\/fiscalia-anticorrupcion-de-chihuahua-declara-profugo-de-la-justicia-a-javier-corral\/","title":{"rendered":"Fiscal\u00eda Anticorrupci\u00f3n de Chihuahua declara &#8216;pr\u00f3fugo de la justicia&#8217; a Javier Corral"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El titular de la Fiscal\u00eda Anticorrupci\u00f3n de Chihuahua, Luis Abelardo Valenzuela Holgu\u00edn, sostuvo que el personal de la Fiscal\u00eda de la Ciudad de M\u00e9xico les impidi\u00f3 \u201cejecutar una orden de aprehensi\u00f3n\u201d en contra del exgobernador chihuahuense Javier corral, lo que constituye \u201cuna obstrucci\u00f3n clara de la justicia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a Valenzuela Holgu\u00edn, el proceder de la instituci\u00f3n capitalina, y en especial el del encargado de despacho, Ulises Lara, dijo, \u201cconstituye varias irregularidades, entre ellas la probable comisi\u00f3n de un delito\u201d.<br>En entrevista con Pascal Beltr\u00e1n del R\u00edo, para Imagen Radio, Abelardo Valenzuela narr\u00f3 que, semanas atr\u00e1s, detuvieron a otro empresario involucrado en el mismo caso que el exgobernador Corral, esto fue en la colonia Condesa en la Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esa ocasi\u00f3n, refiri\u00f3 el fiscal hubo total \u201ccolaboraci\u00f3n con la fiscal\u00eda de la Ciudad de M\u00e9xico, hicimos el mismo procedimiento, el mismo protocolo\u201d, por lo que consider\u00f3 \u201cinaudito\u201d el que Lara L\u00f3pez increpara al personal ministerial de Chihuahua, alegando que la dependencia que dirige hab\u00eda decidido no colaborar en esta ocasi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El servidor p\u00fablico de Chihuahua indic\u00f3 que \u201cante la negativa que nos est\u00e1 planteando el hoy el titular de la fiscal\u00eda capitalina\u201d, reintentar\u00e1n el convenio de colaboraci\u00f3n entre ambos \u00f3rganos para \u201ccumplir con todos los requisitos que \u00e9l dice que no se cumplieron, y que nosotros estamos plenamente convencidos y conscientes que se cumplieron a cabalidad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque rechaz\u00f3 a pronunciarse respecto a la denuncia que Javier Corral dijo que interpondr\u00e1 contra \u00e9l y contra la actual gobernadora del estado Maru Campos. No obstante, respecto a las declaraciones del presidente L\u00f3pez Obrador, quien indic\u00f3 en su ma\u00f1anera que el intento de aprehensi\u00f3n del exgobernador es parte de un conflicto pol\u00edtico, Abelardo Valenzuela insisti\u00f3 en que la Fiscal\u00eda Anticorrupci\u00f3n es aut\u00f3noma del poder ejecutivo estatal, y s\u00f3lo intentaban dar cumplimiento a una orden de aprehensi\u00f3n contra Corral, quien, insisti\u00f3, \u201choy est\u00e1 pr\u00f3fugo de la justicia\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El titular de la Fiscal\u00eda Anticorrupci\u00f3n de Chihuahua, Luis Abelardo Valenzuela Holgu\u00edn, sostuvo que el personal de la Fiscal\u00eda de la Ciudad de M\u00e9xico les impidi\u00f3 \u201cejecutar una orden de aprehensi\u00f3n\u201d en contra del exgobernador chihuahuense Javier corral, lo que constituye \u201cuna obstrucci\u00f3n clara de la justicia\u201d. De acuerdo a Valenzuela Holgu\u00edn, el proceder de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":50624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[176,226],"tags":[],"class_list":["post-50623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","category-policia"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/50623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=50623"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/50623\/revisions"}],"predecessor-version":[{"id":50625,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/50623\/revisions\/50625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/50624"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=50623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=50623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=50623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}