{"id":49626,"date":"2024-07-26T18:48:32","date_gmt":"2024-07-26T18:48:32","guid":{"rendered":"http:\/\/lahora.mx\/?p=49626"},"modified":"2024-07-26T18:48:33","modified_gmt":"2024-07-26T18:48:33","slug":"castigan-a-verstappen-con-10-lugares-en-el-gp-de-belgica","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/07\/26\/castigan-a-verstappen-con-10-lugares-en-el-gp-de-belgica\/","title":{"rendered":"Castigan a Verstappen con 10 lugares en el GP de B\u00e9lgica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El neerland\u00e9s Max Verstappen, l\u00edder del Mundial de F\u00f3rmula 1, ser\u00e1 penalizado con 10 posiciones en la parrilla de salida del domingo del Gran Premio de B\u00e9lgica 2024 debido a un cambio del motor de su monoplaza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Red Bull instal\u00f3 en el coche del vigente campe\u00f3n del mundo, un quinto motor de combusti\u00f3n interna, uno m\u00e1s de los que est\u00e1n permitidos por temporada. Este cambio supone una penalizaci\u00f3n en la parrilla de salida del Gran Premio, seg\u00fan las normas vigentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Max Verstappen<br>Esta sanci\u00f3n no es ninguna sorpresa para Verstappen quien asegur\u00f3 a la prensa el jueves que iba a ser \u201cmuy probablemente\u201d penalizado por este cambio de motor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el legendario circuito de Spa-Francorchamps, el neerland\u00e9s, nacido en Flandes, a unos cien kil\u00f3metros del trazado belga, ha ganado las tres \u00faltimas ediciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Verstappen, sin embargo, prefiere ser realista: \u201cSi miramos nuestras \u00faltimas carreras, donde no hemos sido particularmente r\u00e1pidos, yo no dir\u00eda que con una penalizaci\u00f3n de diez puestos podamos tener posibilidades de ganar el domingo. Pero una carrera puede desordenarse en cualquier momento\u201d, reconoci\u00f3 este jueves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">arsenal<br>Fabio Vieira marc\u00f3 un golazo en el empate contra el Bournemouth.<br>arsenal logo Arsenal FC<br>Nunca desde 2021 hab\u00eda dejado escapar tantas victorias consecutivas en el Mundial, seis en 13 carrera disputadas, cuando el a\u00f1o pasado s\u00f3lo perdi\u00f3 dos en el mismo periodo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El neerland\u00e9s Max Verstappen, l\u00edder del Mundial de F\u00f3rmula 1, ser\u00e1 penalizado con 10 posiciones en la parrilla de salida del domingo del Gran Premio de B\u00e9lgica 2024 debido a un cambio del motor de su monoplaza. Red Bull instal\u00f3 en el coche del vigente campe\u00f3n del mundo, un quinto motor de combusti\u00f3n interna, uno [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":49627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[3,6],"tags":[223,142],"class_list":["post-49626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","category-sports","tag-puebla","tag-sports"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/49626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=49626"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/49626\/revisions"}],"predecessor-version":[{"id":49628,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/49626\/revisions\/49628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/49627"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=49626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=49626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=49626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}