{"id":46766,"date":"2024-05-30T00:19:44","date_gmt":"2024-05-30T00:19:44","guid":{"rendered":"http:\/\/lahora.mx\/?p=46766"},"modified":"2024-05-30T00:19:45","modified_gmt":"2024-05-30T00:19:45","slug":"iee-solicita-seguridad-en-sitios-donde-ediles-que-se-reeligen-no-dejaron-el-cargo","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/05\/30\/iee-solicita-seguridad-en-sitios-donde-ediles-que-se-reeligen-no-dejaron-el-cargo\/","title":{"rendered":"IEE solicita seguridad en sitios donde ediles que se reeligen no dejaron el cargo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Instituto Electoral del Estado (IEE) solicit\u00f3 al Gobierno de Puebla garantizar la seguridad en los municipios donde sus ediles no presentaron renuncia \u2014como Tehuac\u00e1n o Eloxochitl\u00e1n\u2014 y que pretenden reelegirse en las votaciones de este domingo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En comunicado de este 29 de mayo el IEE exhort\u00f3 a los tres niveles de gobierno, federal, estatal y municipal, se mantenga la vigilancia durante la jornada electoral del 2 de junio, con el fin de \u201cque se cumplan y garanticen elecciones neutrales, imparciales y equitativas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe exhorta y solicita la coadyuvancia del Gobierno del Estado con \u00e9ste Instituto para que intervenga en el \u00e1mbito de su competencia en materia de Seguridad P\u00fablica principalmente en los municipios ya referidos\u201d, se lee en el texto que comparti\u00f3 el organismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el documento tambi\u00e9n se\u00f1alaron que es facultad de la presidencia del IEE presentar esta solicitud para que no haya alg\u00fan tipo de altercado el d\u00eda de la elecci\u00f3n, ya sea por de situaci\u00f3n de parcialidad o por alguna otra.<br>Hace dos semanas, el titular de la Secretar\u00eda de Gobernaci\u00f3n, Javier Aquino Lim\u00f3n, detall\u00f3 que s\u00f3lo 40 de 106 presidentes municipales que optaron por reelegirse pidieron licencia a su cargo, lo que motiv\u00f3 quejas de parte de la ciudadan\u00eda, pues llegaron denuncias que se\u00f1alaron la parcialidad de algunas polic\u00edas municipales en favor del candidato y edil de diferentes ciudades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Electoral del Estado (IEE) solicit\u00f3 al Gobierno de Puebla garantizar la seguridad en los municipios donde sus ediles no presentaron renuncia \u2014como Tehuac\u00e1n o Eloxochitl\u00e1n\u2014 y que pretenden reelegirse en las votaciones de este domingo. En comunicado de este 29 de mayo el IEE exhort\u00f3 a los tres niveles de gobierno, federal, estatal [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":46767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[195,223],"class_list":["post-46766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-principal","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/46766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=46766"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/46766\/revisions"}],"predecessor-version":[{"id":46768,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/46766\/revisions\/46768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/46767"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=46766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=46766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=46766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}