{"id":45110,"date":"2024-04-29T00:03:14","date_gmt":"2024-04-29T00:03:14","guid":{"rendered":"http:\/\/lahora.mx\/?p=45110"},"modified":"2024-04-29T00:03:14","modified_gmt":"2024-04-29T00:03:14","slug":"luz-de-la-paz-otra-victima-de-feminicidio-en-teziutlan-la-mataron-a-golpes-en-su-propia-casa","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/04\/29\/luz-de-la-paz-otra-victima-de-feminicidio-en-teziutlan-la-mataron-a-golpes-en-su-propia-casa\/","title":{"rendered":"Luz de la Paz, otra v\u00edctima de feminicidio en Teziutl\u00e1n: la mataron a golpes en su propia casa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Luz de la Paz Pinz\u00f3n, de 74 a\u00f1os, fue asesinada a golpes en su propio domicilio el pasado 8 de abril en Teziutl\u00e1n, pero no se supo de su feminicidio hasta este s\u00e1bado, durante la marcha para exigir justicia por Vianey Jim\u00e9nez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin signos vitales, con una pierna visiblemente fracturada, y tendida boca abajo en el suelo, fue como su hijo encontr\u00f3 a Luz de la Paz, cuya sangre qued\u00f3 esparcida en varias partes de su casa y muebles tirados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El asesinato de Luz de la Paz tuvo lugar en Barrio de Francia y se convirti\u00f3 en el segundo feminicidio registrado en el Pueblo M\u00e1gico de Teziutl\u00e1n, tan s\u00f3lo en lo que va de abril.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMi madre era una persona de la tercera edad, indefensa, que no le hac\u00eda da\u00f1o a nadie y que fue v\u00edctima de unos sujetos que no han sido encontrados, que son una amenaza para m\u00e1s mujeres\u201d, escribi\u00f3 en redes sociales Jos\u00e9 Hugo Santiago Pinz\u00f3n, hijo de la ahora occisa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue a las 9 de la noche del 8 de abril cuando el cuerpo de Luz de la Paz fue hallado al interior de su casa, a donde acudieron polic\u00edas para iniciar con las averiguaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMi madre se encontraba sola en el domicilio que compart\u00edamos, mientras yo me encontraba en el trabajo ella se quedaba sola\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hugo revel\u00f3 que el dictamen m\u00e9dico confirm\u00f3 que fue un homicidio cometido por m\u00e1s de dos personas, sin embargo, a la fecha a\u00fan no localizan a los probables feminicidios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLevante la denuncia ante el MP, pero no han encontrado a los culpables. Por ello les pido su apoyo para compartir y exigir justicia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es necesario se\u00f1alar que fue durante la marcha pac\u00edfica de este s\u00e1bado 27 de abril en la Casa de Justicia de Teziutl\u00e1n que el caso de Luz de la Paz fue conocido a la opini\u00f3n p\u00fablica, pues este feminicidio a\u00fan no estaba documentado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luz de la Paz Pinz\u00f3n, de 74 a\u00f1os, fue asesinada a golpes en su propio domicilio el pasado 8 de abril en Teziutl\u00e1n, pero no se supo de su feminicidio hasta este s\u00e1bado, durante la marcha para exigir justicia por Vianey Jim\u00e9nez. Sin signos vitales, con una pierna visiblemente fracturada, y tendida boca abajo en [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":45111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-45110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/45110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=45110"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/45110\/revisions"}],"predecessor-version":[{"id":45112,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/45110\/revisions\/45112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/45111"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=45110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=45110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=45110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}