{"id":43984,"date":"2024-04-02T18:54:17","date_gmt":"2024-04-02T18:54:17","guid":{"rendered":"http:\/\/lahora.mx\/?p=43984"},"modified":"2024-04-02T18:54:18","modified_gmt":"2024-04-02T18:54:18","slug":"municipios-de-texmelucan-tiran-su-basura-en-barrancas-por-cierre-de-relleno-sanitario","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/04\/02\/municipios-de-texmelucan-tiran-su-basura-en-barrancas-por-cierre-de-relleno-sanitario\/","title":{"rendered":"Municipios de Texmelucan tiran su basura en barrancas por cierre de relleno sanitario"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las autoridades de San Salvador El Verde fueron denunciadas de tirar basura en una de las barrancas ubicadas en este municipio, luego del cierre del relleno sanitario de San Andr\u00e9s Calpan por integrantes de Pueblos Originarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hecho se di\u00f3 a conocer, el pasado lunes, a trav\u00e9s de un video denuncia en el que se observa a camiones recolectores de basura de El Verde, depositando basura en la barranca ubicada en el camino a la capilla de San Miguel Contla de este municipio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto ha generado preocupaci\u00f3n en la ciudadan\u00eda por las acciones que est\u00e1n tomando las autoridades sin importar la contaminaci\u00f3n y el foco de infecci\u00f3n que se pueda generar por los residuos, en la colonia Guadalupe La Encinera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En videos que llegaron a la redacci\u00f3n se aprecia c\u00f3mo llega el cami\u00f3n recolector a tirar los desechos a la barranca sin importar el grado de contaminaci\u00f3n que esto pueda generar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed como el foco de infecci\u00f3n por los desechos ah\u00ed vertidos, por lo que ha generado inconformidad en la ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cierre del relleno sanitario intermunicipal<br>El pasado 22 de marzo pobladores de diferentes municipios cercanos al relleno sanitario ubicado en los l\u00edmites de San Andr\u00e9s Calpan y Cholula tomaron las instalaciones bloqueando el acceso a todos los camiones recolectores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto, luego de que los manifestantes indicaran que el nivel de contaminaci\u00f3n que se est\u00e1 generando podr\u00eda afectar los mantos acu\u00edferos de la zona, debido a que varios municipios tiran sus desechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a ello, ya se generaron problemas en el municipio de San Salvador El Verde, los cuales no cuentan con lugar para que depositen los desechos recolectados los cuales los arrojan en barrancas del municipio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caso como se denuci\u00f3 en la barranca ubicada en el camino a la capilla de San Miguel Contla, en la colonia Guadalupe La Encinera de este municipio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los ciudadanos se\u00f1alan que no es posible que las autoridades est\u00e9n contaminando las barrancas, sumado a la contaminaci\u00f3n que hay en los r\u00edos por las empresas textiles que ninguna autoridad ha hecho nada para solucionarlo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las autoridades de San Salvador El Verde fueron denunciadas de tirar basura en una de las barrancas ubicadas en este municipio, luego del cierre del relleno sanitario de San Andr\u00e9s Calpan por integrantes de Pueblos Originarios. El hecho se di\u00f3 a conocer, el pasado lunes, a trav\u00e9s de un video denuncia en el que se [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":43985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[223],"class_list":["post-43984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/43984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=43984"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/43984\/revisions"}],"predecessor-version":[{"id":43986,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/43984\/revisions\/43986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/43985"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=43984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=43984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=43984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}