{"id":43548,"date":"2024-03-26T01:49:19","date_gmt":"2024-03-26T01:49:19","guid":{"rendered":"http:\/\/lahora.mx\/?p=43548"},"modified":"2024-03-26T01:49:19","modified_gmt":"2024-03-26T01:49:19","slug":"este-martes-inician-las-actividades-de-semana-santa-en-puebla","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/03\/26\/este-martes-inician-las-actividades-de-semana-santa-en-puebla\/","title":{"rendered":"Este martes inician las actividades de Semana Santa en Puebla"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las actividades de Semana Santa en la ciudad de Puebla dar\u00e1n comienzo este martes 26 de marzo. El secretario de Econom\u00eda y Turismo del Ayuntamiento, V\u00edctor Mata Temoltzin, destac\u00f3 el recorrido del Antiguo Viacrucis de Puebla, la Visita de las Siete Casas y la Procesi\u00f3n del Viernes Santo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mata Temoltzin indic\u00f3 que el martes 26 y mi\u00e9rcoles 27 de marzo, a partir de las 11:00 horas, se realizar\u00e1n los recorridos del Antiguo Viacrucis de Puebla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El punto de encuentro ser\u00e1 en el atrio de la iglesia de San Francisco y el recorrido terminar\u00e1 en las Capillas del Calvario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El funcionario mencion\u00f3 que desde 2011 este recorrido se ha convertido en una tradici\u00f3n en esta temporada de Semana Santa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCu\u00e1l es la ruta del Antiguo Viacrucis en Puebla?<br>El recorrido del Antiguo Viacrucis visita diferentes estaciones en la zona del barrio del Alto.<br>Primera estaci\u00f3n \u2013 Templo de San Francisco (Jes\u00fas es condenado a muerte)<br>Segunda estaci\u00f3n \u2013 Atrio del Templo de San Francisco (Jes\u00fas carga con la cruz)<br>Tercera estaci\u00f3n \u2013 Atrio del templo de San Francisco (Jes\u00fas cae por primera vez)<br>Cuarta estaci\u00f3n \u2013 Capilla de la Macarena, que se ubica sobre la 14 oriente (Jes\u00fas encuentra a Mar\u00eda, su Sant\u00edsima Madre)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quinta estaci\u00f3n \u2013 Capilla del Cireneo, que venera a la Virgen de la Medalla Milagrosa (Sim\u00f3n de Cirene ayuda a llevar la Cruz de Jes\u00fas)<br>Sexta estaci\u00f3n \u2013 Capilla de la Ver\u00f3nica, sobre la 16 Oriente, a un costado de Casa Aguayo (La Ver\u00f3nica limpia el rostro de Jes\u00fas)<br>S\u00e9ptima estaci\u00f3n \u2013 Capilla de los Plateros, en la 20 Oriente (Jes\u00fas cae por segunda vez)<br>Octava estaci\u00f3n \u2013 Capilla de Piadosas o Pla\u00f1ideras (Jes\u00fas consuela a las mujeres de Jerusal\u00e9n)<br>Novena estaci\u00f3n \u2013 Capilla de la tercera ca\u00edda (Jes\u00fas cae por tercera vez)<br>D\u00e9cima estaci\u00f3n \u2013 Capilla del Expolio (Jes\u00fas es despojado de sus vestiduras)<br>Onceava estaci\u00f3n \u2013 Capilla de la Crucifixi\u00f3n (Jes\u00fas es clavado en la Cruz)<br>Doceava estaci\u00f3n \u2013 Capilla de la Expiraci\u00f3n (Jes\u00fas muere en la Cruz)<br>Treceava estaci\u00f3n \u2013 Capilla del Santo Sepulcro (Jes\u00fas es bajado de la cruz y puesto en brazos de su Madre)<br>Actividades de Semana Santa en Puebla inician este martes con Antiguo Viacrucis<br>Procesi\u00f3n del Viernes Santo en Puebla<br>De igual manera, la edici\u00f3n 32 de la procesi\u00f3n del Viernes Santo, que ser\u00e1 el 29 de marzo, dar\u00e1 inicio a las 12 horas y el funcionario mencion\u00f3 que se espera a cerca de 160 mil personas; el arzobispo V\u00edctor S\u00e1nchez Espinosa ser\u00e1 quien encabece este recorrido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la directora de Tr\u00e1nsito municipal, Mar\u00eda del Rayo Ram\u00edrez Polo, indic\u00f3 que habr\u00e1 180 elementos para el acompa\u00f1amiento del recorrido del Viernes Santo e inform\u00f3 el cierre de vialidades del primer cuadro de la ciudad de 9:00 a 17:00 horas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por esta raz\u00f3n habr\u00e1 cierres desde la 11 Norte-Sur, a la altura de avenida Reforma, bulevar 5 de Mayo y 17 Oriente a 18 Oriente, desde la iglesia de San Jos\u00e9 hasta El Carmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La titular de Tr\u00e1nsito municipal indic\u00f3 que se realizar\u00e1n operativos Alcohol\u00edmetro para garantizar la seguridad de los peatones y automovilistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otorgan permisos para mil 500 ambulantes en El Calvario y la Romero Vargas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, Jorge Cruz Lepe, titular de la Secretar\u00eda de Gobernaci\u00f3n municipal, indic\u00f3 que se otorgar\u00e1n mil 500 permisos para la instalaci\u00f3n de vendedores ambulantes en El Calvario y la junta auxiliar Ignacio Romero Vargas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joel Figueroa Tentori, director de Gesti\u00f3n de Riesgos en Materia de Protecci\u00f3n Civil, indic\u00f3 que estar\u00e1n pendientes de las actividades en Semana Santa para garantizar la seguridad de la ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, recomend\u00f3 mantenerse hidratado durante los recorridos, usar protector solar y ropa c\u00f3moda y gorra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las actividades de Semana Santa en la ciudad de Puebla dar\u00e1n comienzo este martes 26 de marzo. El secretario de Econom\u00eda y Turismo del Ayuntamiento, V\u00edctor Mata Temoltzin, destac\u00f3 el recorrido del Antiguo Viacrucis de Puebla, la Visita de las Siete Casas y la Procesi\u00f3n del Viernes Santo. Mata Temoltzin indic\u00f3 que el martes 26 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":43549,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[223],"class_list":["post-43548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/43548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=43548"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/43548\/revisions"}],"predecessor-version":[{"id":43550,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/43548\/revisions\/43550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/43549"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=43548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=43548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=43548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}