{"id":43032,"date":"2024-03-14T02:21:29","date_gmt":"2024-03-14T02:21:29","guid":{"rendered":"http:\/\/lahora.mx\/?p=43032"},"modified":"2024-03-14T02:21:30","modified_gmt":"2024-03-14T02:21:30","slug":"volkswagen-se-va-a-paro-tecnico-por-dos-meses","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/03\/14\/volkswagen-se-va-a-paro-tecnico-por-dos-meses\/","title":{"rendered":"Volkswagen se va a paro t\u00e9cnico por dos meses"},"content":{"rendered":"\n<p>La armadora Volkswagen se ir\u00e1 a paro t\u00e9cnico dos meses en el segmento Tiguan, as\u00ed lo aseguraron fuentes internas de la compa\u00f1\u00eda a e-consulta, a pesar de que la empresa no ha dado a conocer la informaci\u00f3n de manera oficial y se desconoce la postura del sindicato.<\/p>\n\n\n\n<p>De acuerdo con los reportes, este paro inici\u00f3 a partir del lunes 11 de marzo y se extender\u00e1 hasta la semana 20 del a\u00f1o, es decir, hasta por lo menos el 12 de mayo, pues al momento se cursa la semana 11, que va del 10 al 16 de marzo; mientras que la semana 20 ir\u00e1 del 12 al 18 de mayo.<\/p>\n\n\n\n<p>Lo anterior significan dos meses sin producci\u00f3n del modelo Tiguan, que empatan con una industria automotriz en el estado de Puebla que acaba de pasar por una huelga en la planta Audi de 25 d\u00edas y un par de esc\u00e1ndalos en el nuevo sindicato de Volkswagen.<\/p>\n\n\n\n<p>Asimismo, Enrique Tepox Casta\u00f1eda, un extrabajador de la armadora despedido a principios de este a\u00f1o, dio a conocer que ir\u00e1 a juicio laboral contra la empresa, pues demanda haber sido separado de su cargo de manera injustificada, por ello busca su restituci\u00f3n.<\/p>\n\n\n\n<p>El obrero dio a conocer su caso junto con por los menos otros 11 compa\u00f1eros, quienes acusaron persecuci\u00f3n pol\u00edtica tras el cambio de patronato sindical, pues la mayor\u00eda de los despedidos contendieron en su contra con otra planilla sindical.<\/p>\n\n\n\n<p>El 29 de febrero se celebr\u00f3 un juicio contra la armadora en el cual \u00e9sta ofreci\u00f3 un cheque con una cantidad correspondiente a su liquidaci\u00f3n, misma que no acept\u00f3, pues dijo que busca que su puesto laboral sea devuelto, toda vez que no hizo nada para perderlo.<\/p>\n\n\n\n<p>Los despidos habr\u00edan comenzado a partir de que Hugo Tlalpan Luna se hiciera con el cargo de secretario general del Sindicato Independiente de Trabajadores de Volkswagen (Sitiavw), tras ganar las elecciones para el periodo 2024-2028.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La armadora Volkswagen se ir\u00e1 a paro t\u00e9cnico dos meses en el segmento Tiguan, as\u00ed lo aseguraron fuentes internas de la compa\u00f1\u00eda a e-consulta, a pesar de que la empresa no ha dado a conocer la informaci\u00f3n de manera oficial y se desconoce la postura del sindicato. De acuerdo con los reportes, este paro inici\u00f3 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":43033,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175,2],"tags":[195,223],"class_list":["post-43032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","category-negocios","tag-principal","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/43032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=43032"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/43032\/revisions"}],"predecessor-version":[{"id":43034,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/43032\/revisions\/43034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/43033"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=43032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=43032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=43032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}