{"id":42776,"date":"2024-03-08T00:57:55","date_gmt":"2024-03-08T00:57:55","guid":{"rendered":"http:\/\/lahora.mx\/?p=42776"},"modified":"2024-03-08T00:57:56","modified_gmt":"2024-03-08T00:57:56","slug":"replicar-las-experiencias-exitosas-piden-a-rivera","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/03\/08\/replicar-las-experiencias-exitosas-piden-a-rivera\/","title":{"rendered":"Replicar las experiencias exitosas piden a Rivera"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Previo al gran festejo a &#8216;Don Goyo&#8217; -12 de marzo-, Lalo Rivera visit\u00f3 los municipios de Calpan, San Nicol\u00e1s de los Ranchos y Nealtican, donde militantes y simpatizantes de PAN, PRI, PRD y PSI le pidieron replicar las experiencias exitosas que tuvo en el municipio de Puebla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras atestiguar las tomas de protesta de las estructuras seccionales de los institutos que lo respaldan, Rivera P\u00e9rez escuch\u00f3 las problem\u00e1ticas de la poblaci\u00f3n de la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde Calpan reconoci\u00f3 la civilidad de l\u00edderes y militancias de cada uno de los Partidos, pues convivieron en un solo evento, por lo que apunt\u00f3 que esta unidad se debe a \u00abun prop\u00f3sito superior: el municipio, Puebla y M\u00e9xico\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siendo las principales problem\u00e1ticas de dicha demarcaci\u00f3n la reubicaci\u00f3n del relleno sanitario intermunicipal -que se convirti\u00f3 en un foco de contaminaci\u00f3n-, falta de agua potable; da\u00f1os en campos de cultivo por aguas residuales; robo a casa habitaci\u00f3n y comercios; carencia de transporte p\u00fablico; adem\u00e1s que las y los campesinos de la regi\u00f3n requieren apoyos para no tener que abandonar su labor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, Lalo Rivera se dirigi\u00f3 a la junta auxiliar Santiago Xalitzintla en San Nicol\u00e1s de los Ranchos, donde Ana Mar\u00eda Sandre, l\u00edder en el municipio, le solicit\u00f3 conservar la sencillez y la atenci\u00f3n a la ciudadan\u00eda que le caracterizan, pues en la actualidad los &#8216;martes ciudadanos&#8217; sirven para poner una queja de la cual nunca se recibe respuesta, por lo que los buenos y cercanos gobiernos son necesarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed Lalo Rivera tambi\u00e9n escuch\u00f3 a Vicky Mart\u00ednez, representante de las artesanas que trabajan con ocoxal, creando piezas \u00fanicas como llaveros, aretes, medallas, bolsas, entre otros art\u00edculos, a quien le interes\u00f3 el impulso a este sector como se hizo en Puebla capital, al igual que el contar con cr\u00e9ditos que les permita hacer crecer su emprendimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s tarde se dirigi\u00f3 a Nealtican para otra toma de protesta de las militancias, donde las y los asistentes comentaron que no hay patrullas ni polic\u00edas, mantenimiento a las calles y carreteras, no hay agua potable, personal m\u00e9dico y medicamentos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finamente, Lalo Rivera cerr\u00f3 su mensaje reafirmando que de los aspirantes que hay a la gubernatura \u00abno hay ninguno otro que tenga la experiencia de haber gobernado una ciudad tan grande como Puebla capital\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En estos actos internos de las fuerzas pol\u00edticas que integran la alianza Mejor Rumbo para Puebla, tambi\u00e9n estuvieron en Calpan: Obdulia Zepeda panista distinguida; Roc\u00edo Terreros, priista distinguida; Miguel Hern\u00e1ndez, perredista distinguido; Adelina Marcos, militante de PSI; en San Nicol\u00e1s de los Ranchos Braulio Caro, Presidente de Estructura PAN; L\u00e1zaro Soto, panista de la regi\u00f3n; y en Nealtican: los panistas Domingo Jim\u00e9nez, Paty Hidalgo y Pedro Luna, Presidente del Comit\u00e9 Directivo Municipal albiazul.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previo al gran festejo a &#8216;Don Goyo&#8217; -12 de marzo-, Lalo Rivera visit\u00f3 los municipios de Calpan, San Nicol\u00e1s de los Ranchos y Nealtican, donde militantes y simpatizantes de PAN, PRI, PRD y PSI le pidieron replicar las experiencias exitosas que tuvo en el municipio de Puebla. Tras atestiguar las tomas de protesta de las [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":42778,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[223],"class_list":["post-42776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/42776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=42776"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/42776\/revisions"}],"predecessor-version":[{"id":42779,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/42776\/revisions\/42779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/42778"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=42776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=42776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=42776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}