{"id":4192,"date":"2022-03-13T23:37:35","date_gmt":"2022-03-13T23:37:35","guid":{"rendered":"http:\/\/lahora.mx\/?p=4192"},"modified":"2022-03-13T23:37:36","modified_gmt":"2022-03-13T23:37:36","slug":"busca-puebla-capital-servicio-integral-de-alumbrado-y-semaforos","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/03\/13\/busca-puebla-capital-servicio-integral-de-alumbrado-y-semaforos\/","title":{"rendered":"Busca Puebla capital servicio integral de alumbrado y sem\u00e1foros"},"content":{"rendered":"\n<p>El Ayuntamiento de Puebla recibi\u00f3 la ciudad con la peor&nbsp;<strong>infraestructura de alumbrado<\/strong>&nbsp;de los \u00faltimos 20 a\u00f1os, asegur\u00f3 en un comunicado de prensa.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que hay falta de mantenimiento en 118 puntos de luz, 80 mil concluir\u00e1n su vida \u00fatil en menos de 2 a\u00f1os y se detectaron&nbsp;<strong>niveles deficientes de luz<\/strong>&nbsp;en 70% de la infraestructura.<\/p>\n\n\n\n<p>Adem\u00e1s hay deficiencias heredadas en la sincronizaci\u00f3n de sem\u00e1foros y su mal funcionamiento provoca&nbsp;<strong>accidentes y atropellamientos.<\/strong><\/p>\n\n\n\n<p>Por esas razones, el Ayuntamiento de Puebla ha trabajado en&nbsp;<strong>un \u00fanico proyecto de alumbrado y semaforizaci\u00f3n<\/strong>&nbsp;con el fin de que exista un&nbsp;<strong>servicio integral y eficiente para los ciudadanos<\/strong>. Busca mejorar en 40% los tiempos de ejecuci\u00f3n de obra de alumbrado y en 25% los plazos de respuesta a la ciudadan\u00eda.<\/p>\n\n\n\n<p>Agreg\u00f3 que en el proceso de licitaci\u00f3n abierta, totalmente transparente, se establecer\u00e1n par\u00e1metros de evaluaci\u00f3n y seguimiento de los servicios contratados.<\/p>\n\n\n\n<p>La empresa que gane la licitaci\u00f3n deber\u00e1 garantizar como m\u00ednimo la renovaci\u00f3n de 16 mil l\u00e1mparas a tecnolog\u00eda led, el cambio de otras 30 mil para que funcione de manera adecuada el 95% de luminarias, brindar mantenimiento mec\u00e1nico y el\u00e9ctrico a los puntos restantes as\u00ed como la ampliaci\u00f3n de la infraestructura con m\u00e1s de 5 mil luminarias nuevas, iluminaci\u00f3n art\u00edstica en edificios y la correspondiente a fiestas patrias y temporada navide\u00f1a.<\/p>\n\n\n\n<p>En cuanto a la semaforizaci\u00f3n, tendr\u00e1 que&nbsp;<strong>renovar la luz led en 80 cruceros, instalar sem\u00e1foros peatonales, dotar de tecnolog\u00eda adecuada a otros 160 cruceros<\/strong>&nbsp;para incorporarlos al Sistema Centralizado de Sem\u00e1foros y brindar mantenimiento mec\u00e1nico y el\u00e9ctrico suficiente, entre otras cosas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Puebla recibi\u00f3 la ciudad con la peor&nbsp;infraestructura de alumbrado&nbsp;de los \u00faltimos 20 a\u00f1os, asegur\u00f3 en un comunicado de prensa. Se\u00f1al\u00f3 que hay falta de mantenimiento en 118 puntos de luz, 80 mil concluir\u00e1n su vida \u00fatil en menos de 2 a\u00f1os y se detectaron&nbsp;niveles deficientes de luz&nbsp;en 70% de la infraestructura. Adem\u00e1s [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4193,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[223],"class_list":["post-4192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/4192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4192"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/4192\/revisions"}],"predecessor-version":[{"id":4194,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/4192\/revisions\/4194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/4193"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=4192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=4192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}