{"id":4182,"date":"2022-03-13T14:28:41","date_gmt":"2022-03-13T14:28:41","guid":{"rendered":"http:\/\/lahora.mx\/?p=4182"},"modified":"2022-03-13T14:28:41","modified_gmt":"2022-03-13T14:28:41","slug":"atienden-a-diario-a-5-victimas-de-violencia-en-puebla","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/03\/13\/atienden-a-diario-a-5-victimas-de-violencia-en-puebla\/","title":{"rendered":"Atienden a diario a 5 v\u00edctimas de violencia en Puebla"},"content":{"rendered":"\n<p>A diario se atiende en Puebla en promedio a&nbsp;<strong>cinco v\u00edctimas de violencia<\/strong>, como mujeres y menores de edad, de acuerdo con datos de la Secretar\u00eda de Igualdad Sustantiva del estado.<\/p>\n\n\n\n<p>En un reporte se detalla que en 2021 hubo en total&nbsp;<strong>1 mil 440 atenciones&nbsp;<\/strong>enfocadas a mujeres, pero septiembre, octubre y noviembre son los meses en los que hubo m\u00e1s casos, al sumar&nbsp;<strong>140 en cada uno.<\/strong><\/p>\n\n\n\n<p>Por el contrario, enero fue el de menos incidencia, al sumar&nbsp;<strong>50 atenciones<\/strong>&nbsp;nada m\u00e1s, seg\u00fan la informaci\u00f3n publicada en la Plataforma Nacional de Transparencia (PNT).<\/p>\n\n\n\n<p>Las acciones para mujeres consisten en&nbsp;<strong>atenci\u00f3n jur\u00eddica y psicol\u00f3gica&nbsp;<\/strong>especializada de primera vez y seguimiento, a la poblaci\u00f3n que recibe protecci\u00f3n a trav\u00e9s del&nbsp;<strong>refugio para mujeres v\u00edctimas de violencia extrema.<\/strong><\/p>\n\n\n\n<p>En el caso de menores de edad, las atenciones se dan en el Centro de Empoderamiento para Ni\u00f1as, Ni\u00f1os y Adolescentes, V\u00edctimas Indirectas de la Violencia de G\u00e9nero y el a\u00f1o pasado&nbsp;<strong>hubo 400 atenciones.<\/strong><\/p>\n\n\n\n<p>En el caso de menores, en enero de 2021&nbsp;<strong>no hubo ning\u00fan caso,<\/strong>&nbsp;pero en los subsecuentes se registraron&nbsp;<strong>hasta 40 cada mes,<\/strong>&nbsp;con excepci\u00f3n de febrero y diciembre, s\u00f3lo sumaron 20 cada uno.<\/p>\n\n\n\n<p>Las atenciones no s\u00f3lo se dan en los refugios, tambi\u00e9n a trav\u00e9s del&nbsp;<strong>Telmujer<\/strong>&nbsp;<strong>911,&nbsp;<\/strong>donde el a\u00f1o pasado hubo&nbsp;<strong>9 mil 600<\/strong>&nbsp;llamadas para asesor\u00edas psicol\u00f3gicas y jur\u00eddicas.<\/p>\n\n\n\n<p><strong>Puebla<\/strong>&nbsp;es una de las entidades con Alerta de Violencia de G\u00e9nero contra las Mujeres (AVGM) activa, debido al alta incidencia de agresiones&nbsp;<strong>desde abril de 2019.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A diario se atiende en Puebla en promedio a&nbsp;cinco v\u00edctimas de violencia, como mujeres y menores de edad, de acuerdo con datos de la Secretar\u00eda de Igualdad Sustantiva del estado. En un reporte se detalla que en 2021 hubo en total&nbsp;1 mil 440 atenciones&nbsp;enfocadas a mujeres, pero septiembre, octubre y noviembre son los meses en [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4183,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[223],"class_list":["post-4182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/4182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4182"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/4182\/revisions"}],"predecessor-version":[{"id":4184,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/4182\/revisions\/4184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/4183"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=4182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=4182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}