{"id":41177,"date":"2024-02-06T17:42:44","date_gmt":"2024-02-06T17:42:44","guid":{"rendered":"http:\/\/lahora.mx\/?p=41177"},"modified":"2024-02-06T17:42:44","modified_gmt":"2024-02-06T17:42:44","slug":"elemento-de-la-policia-municipal-evita-que-joven-salte-del-puente-de-periferico-ecologico","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/02\/06\/elemento-de-la-policia-municipal-evita-que-joven-salte-del-puente-de-periferico-ecologico\/","title":{"rendered":"Elemento de la polic\u00eda municipal evita que joven salte del puente de Perif\u00e9rico Ecol\u00f3gico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un elemento de la polic\u00eda municipal de Puebla logr\u00f3 evitar que un poblano se terminara quitando la vida, pues el joven llamado \u00c1ngel ten\u00eda intenciones de lanzarse del puente del Perif\u00e9rico y la 16 de septiembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El reporte lo recibieron las autoridades, por lo que arribaron hasta el citado punto donde encontraron al poblano de 20 a\u00f1os de edad sentado a la orilla del puente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante ello, un polic\u00eda descendi\u00f3 de la patrulla y comenz\u00f3 a dialogar con \u00e9l. Despu\u00e9s de varios minutos, el oficial logr\u00f3 convencerlo de que no atentara contra su vida, y fue as\u00ed como el joven hizo caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un elemento de la polic\u00eda municipal de Puebla logr\u00f3 evitar que un poblano se terminara quitando la vida, pues el joven llamado \u00c1ngel ten\u00eda intenciones de lanzarse del puente del Perif\u00e9rico y la 16 de septiembre. El reporte lo recibieron las autoridades, por lo que arribaron hasta el citado punto donde encontraron al poblano de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":41178,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175,226],"tags":[223],"class_list":["post-41177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","category-policia","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/41177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=41177"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/41177\/revisions"}],"predecessor-version":[{"id":41179,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/41177\/revisions\/41179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/41178"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=41177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=41177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=41177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}