{"id":40196,"date":"2024-01-18T16:38:59","date_gmt":"2024-01-18T16:38:59","guid":{"rendered":"http:\/\/lahora.mx\/?p=40196"},"modified":"2024-01-18T16:38:59","modified_gmt":"2024-01-18T16:38:59","slug":"asesinan-a-fiscal-en-ecuador-tras-toma-de-televisora","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/01\/18\/asesinan-a-fiscal-en-ecuador-tras-toma-de-televisora\/","title":{"rendered":"Asesinan a fiscal en Ecuador tras toma de televisora"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Luego de que ayer mi\u00e9rcoles 17 de enero fuera asesinado el fiscal ecuatoriano que era responsable de llevar el caso del asalto a un canal de televisi\u00f3n el pasado 9 de enero, las autoridades de Ecuador confirmaron la captura de dos personas involucradas en el ataque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n fue dada a conocer por el Comandante General de la Polic\u00eda Nacional del Ecuador, C\u00e9sar Augusto Zapata Correa, a trav\u00e9s de redes sociales, en donde inform\u00f3 que hab\u00edan detenido a dos de los implicados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zapata Correa comparti\u00f3 en su cuenta de X, antes Twitter, que \u201chemos aprehendido a dos presuntos implicados en el asesinato del fiscal C\u00e9sar Su\u00e1rez, tras diligencias investigativas que permitieron identificar la presunta participaci\u00f3n en el hecho criminal\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, tambi\u00e9n agreg\u00f3 que, al momento de ser detenidos, se les encontr\u00f3 un fusil, dos pistolas, alimentadoras y dos veh\u00edculos, lo que fueron suficientes indicios para vincularlos con el ataque directo al fiscal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Medios locales aseguraron que el fiscal fue perseguido por las calles de Guayaquil al salir de las oficinas de la Fiscal\u00eda ecuatoriana, quienes luego de darle alcance, dispararon contra su autom\u00f3vil en m\u00faltiples ocasiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los desconocidos se dieron a la fuga luego de acribillar al fiscal, sin embargo, las autoridades confirmaron la ma\u00f1ana de este jueves 18 de enero la captura de dos de los presuntos involucrados en su asesinato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con reportes, el fiscal C\u00e9sar Su\u00e1rez, quien no s\u00f3lo llevaba el caso del asalto a la televisora, sino que tambi\u00e9n estaba a cargo de casos relacionados con el narcotr\u00e1fico, terrorismo y delincuencia organizada, hab\u00eda solicitado resguardo policial un d\u00eda antes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto luego de haberles tomado la declaraci\u00f3n a las 13 personas que estuvieron involucradas con la toma de la televisora, 11 adultos y dos menores de edad, quienes luego de declarar fueron enviados a prisi\u00f3n preventiva y a un centro de internamiento, respectivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Diana Salazar, fiscal general del Estado, rechaz\u00f3 el asesinato de C\u00e9sar Su\u00e1rez y asegur\u00f3 que no se detendr\u00e1n en la lucha interna contra el crimen organizado y el narcotr\u00e1fico, pues tienen un compromiso con la sociedad ecuatoriana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEste hecho atroz trae consigo un mensaje para el trabajo que estamos cumpliendo desde la justicia en el Ecuador\u201d, se\u00f1al\u00f3 la fiscal general, por lo que realiz\u00f3 un llamado a \u201cgarantizar la seguridad de quienes nos encontramos en cumplimiento de nuestras funciones.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, tambi\u00e9n asegur\u00f3 que \u201clos grupos de delincuencia organizada, los criminales, los terroristas no detendr\u00e1n nuestro compromiso con la sociedad ecuatoriana\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de que ayer mi\u00e9rcoles 17 de enero fuera asesinado el fiscal ecuatoriano que era responsable de llevar el caso del asalto a un canal de televisi\u00f3n el pasado 9 de enero, las autoridades de Ecuador confirmaron la captura de dos personas involucradas en el ataque. La informaci\u00f3n fue dada a conocer por el Comandante [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":40197,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[183,226],"tags":[],"class_list":["post-40196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","category-policia"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/40196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=40196"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/40196\/revisions"}],"predecessor-version":[{"id":40198,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/40196\/revisions\/40198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/40197"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=40196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=40196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=40196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}