{"id":39927,"date":"2024-01-12T17:06:13","date_gmt":"2024-01-12T17:06:13","guid":{"rendered":"http:\/\/lahora.mx\/?p=39927"},"modified":"2024-01-12T17:06:14","modified_gmt":"2024-01-12T17:06:14","slug":"tlatehui-destapa-a-su-esposa-lupita-cuautle-para-san-andres-cholula-si-es-para-genero-femenino","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2024\/01\/12\/tlatehui-destapa-a-su-esposa-lupita-cuautle-para-san-andres-cholula-si-es-para-genero-femenino\/","title":{"rendered":"Tlatehui destapa a su esposa Lupita Cuautle para San Andr\u00e9s Cholula, si es para g\u00e9nero femenino"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El alcalde de San Andr\u00e9s Cholula, Edmundo Tlatehui destap\u00f3 a su esposa \u2018Lupita\u2019 Cuautle para buscar la alcald\u00eda de dicho municipio en las elecciones de junio de este a\u00f1o en caso de que las dirigencias nacional y estatal del PAN decidan que en dicho municipio se lleve a una mujer como abanderada por la presidencia municipal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una reuni\u00f3n con due\u00f1os y directores de medios de comunicaci\u00f3n, Mundo Tlatehui dej\u00f3 en claro que s\u00ed piensa en la reelecci\u00f3n como alcalde de San Andr\u00e9s, pues as\u00ed se lo permite la ley, \u201cy si no es as\u00ed, si es genero femenino Lupita contar\u00e1 con todo mi apoyo para estar ah\u00ed. Lupita y yo somos un gran equipo y estamos trabajando arduamente\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El alcalde sanandrese\u00f1o despej\u00f3 de esta manera las dudas que hab\u00eda sobre su continuidad en el cargo, pues dej\u00f3 en claro que s\u00ed quiere repetir en la presidencia municipal si es que las dirigencias de su partido se lo permiten, pues destac\u00f3 que la ley electoral s\u00ed se lo permite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tlatehui ponder\u00f3 el trabajo realizado en estos dos a\u00f1os de su trienio por su esposa Lupita Cuautle al frente del Sistema Municipal DIF y le agradeci\u00f3 el empe\u00f1o que pone en cada una de las acciones siempre buscando lo mejor para San Andr\u00e9s Cholula y sus ciudadanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a los plazos establecidos por la dirigencia estatal de Acci\u00f3n Nacional en Puebla ser\u00e1 en este mes de enero o principios de febrero cuando lance las respectivas convocatorias para definir a sus abanderados, despu\u00e9s de acordar con las dirigencias del PRI, PRD y PSI el reparto de los municipios, por lo que ser\u00e1 en las siguientes semanas cuando se defina qui\u00e9n de los dos sanandrese\u00f1os abanderara al blanquiazul.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El alcalde de San Andr\u00e9s Cholula, Edmundo Tlatehui destap\u00f3 a su esposa \u2018Lupita\u2019 Cuautle para buscar la alcald\u00eda de dicho municipio en las elecciones de junio de este a\u00f1o en caso de que las dirigencias nacional y estatal del PAN decidan que en dicho municipio se lleve a una mujer como abanderada por la presidencia [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":39928,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[223],"class_list":["post-39927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/39927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=39927"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/39927\/revisions"}],"predecessor-version":[{"id":39929,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/39927\/revisions\/39929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/39928"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=39927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=39927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=39927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}